{"id":32858,"date":"2022-07-16T06:35:29","date_gmt":"2022-07-16T06:35:29","guid":{"rendered":"https:\/\/fpschampion.com\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/"},"modified":"2023-06-04T06:09:32","modified_gmt":"2023-06-04T06:09:32","slug":"como-jogar-e-construir-mul-t-em-risk-of-rain-2","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/","title":{"rendered":"Como jogar e construir Mul T em Risk of Rain 2"},"content":{"rendered":"\n<p>Mul-T \u00e9 um rob\u00f4 multiuso com grande versatilidade utilizando suas v\u00e1rias armas intercambi\u00e1veis. Ele \u00e9 projetado para se adaptar a v\u00e1rios estilos de jogo. Al\u00e9m disso, seus diferentes tipos de armas permitem que eles joguem em diferentes dist\u00e2ncias e com diferentes caminhos de constru\u00e7\u00e3o Mul T em Risk of Rain 2. Mul T funciona de maneira diferente de outros sobreviventes, pois voc\u00ea pode escolher duas prim\u00e1rias para eles ao iniciar o jogo. <\/p>\n\n<p>Mul-T \u00e9 uma escolha forte para quem quer fazer malabarismos com diferentes estilos de jogo. Tamb\u00e9m \u00e9 perfeito para qualquer pessoa interessada em fingir ser o h\u00edbrido entre Railgunner e uma torre do Engineer. Voc\u00ea deve completar o desafio Verificado para desbloquear Mul T em Risk of Rian 2. Enfrentar esse desafio requer terminar o primeiro evento de teletransporte cinco vezes. Voc\u00ea pode fazer isso facilmente se demorar durante v\u00e1rias execu\u00e7\u00f5es.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-unlock-mul-t-in-risk-of-rain-2\">Como desbloquear Mul-T em Risk of Rain 2<\/h2>\n\n<p><strong>Mul-T &#8211; Verificado<\/strong><\/p>\n\n<p>Para desbloquear Mul-T em Risk of Rain 2, voc\u00ea deve sobreviver ao segundo est\u00e1gio 5 vezes. O desafio Verificado exige que voc\u00ea conclua o primeiro evento de teletransporte cinco vezes no total e \u00e9 um desafio muito f\u00e1cil de executar, jogando no Drizzle e redefinindo ap\u00f3s cada evento de teletransporte conclu\u00eddo.<\/p>\n\n<p>Voc\u00ea tamb\u00e9m pode desbloquear Mul-T facilmente apenas fazendo corridas como <a href=\"https:\/\/fpschampion.com\/pt-br\/all-risk-of-rain-2-personagens-classificados-do-pior-ao-melhor\/\" target=\"_blank\" rel=\"noreferrer noopener\">outros personagens em RoR2<\/a> . O Mul-T ser\u00e1 desbloqueado se voc\u00ea n\u00e3o estiver preso no primeiro est\u00e1gio.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-do-mul-t-s-abilities-work\">Como funcionam as habilidades de Mul-T?<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-primary-weapons-on-mul-t\">Armas prim\u00e1rias em Mul T<\/h3>\n\n<h4 class=\"wp-block-heading\" id=\"h-auto-nailgun\">Pistola de pregos autom\u00e1tica<\/h4>\n\n<p>A primeira de muitas armas prim\u00e1rias de Mul-T \u00e9 a Auto-Nailgun, que dispara 12 pregos por segundo, causando 840% de dano por segundo. Ap\u00f3s liberar o bot\u00e3o de disparo, a arma finaliza com um disparo de 12 pregos antes de entrar em um curto tempo de espera. A Auto-Nailgun tem um coeficiente de proc de 0,6. No entanto, sofre com a queda padr\u00e3o do proj\u00e9til, enfraquecendo os pregos a longas dist\u00e2ncias.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-rebar-puncher\">perfurador de vergalh\u00f5es<\/h4>\n\n<p>A pr\u00f3xima arma prim\u00e1ria padr\u00e3o de Mul-T \u00e9 o Rebar Puncher, que funciona de forma semelhante a uma railgun. O Rebar Puncher dispara uma linha de vergalh\u00e3o que causa 600% de dano base com um coeficiente de proc de 1,0. Ao contr\u00e1rio do Auto-Nailgun, \u00e9 necess\u00e1rio recarregar antes de disparar cada tiro, mas o Rebar Puncher n\u00e3o sofre queda de dano.<\/p>\n\n<p><strong>Artigo Relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/completo-risk-of-rain-2-bandit-build-e-guia-do-jogador\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como Jogar e Construir Bandit em RoR2<\/a><\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-scrap-launcher\">Lan\u00e7ador de sucata<\/h4>\n\n<p>O Scrap Launcher de Mul-T \u00e9 sua primeira arma prim\u00e1ria desbloque\u00e1vel que funciona como um lan\u00e7ador de foguetes. O Scrap Launcher da Mul T comporta at\u00e9 quatro foguetes de sucata. Cada um causa 600% de dano base, tem um coeficiente de proc de 1,0 e tem queda de dano de ponto ideal.<\/p>\n\n<p>O Scrap Launcher tem um pequeno atraso entre os disparos e inicia uma recarga curta ap\u00f3s o lan\u00e7amento de um foguete. N\u00e3o importa se voc\u00ea dispara um ou todos os m\u00edsseis, a recarga ir\u00e1 recarregar todos os quatro tiros da arma.<\/p>\n\n<p>Para desbloquear o Scrap Launcher para sua compila\u00e7\u00e3o Mul T em Risk of Rain 2, voc\u00ea deve concluir o Pest Control Challenge. Para terminar este desafio, voc\u00ea deve derrotar dois Beetle Queens sem sair da zona de teletransporte. As Rainhas dos Besouros s\u00e3o chefes padr\u00e3o para os est\u00e1gios um e dois, mas ativar o Santu\u00e1rio da Montanha aumenta suas chances de gerar v\u00e1rias rainhas.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-power-saw\">serra el\u00e9trica<\/h4>\n\n<p>Power-Saw \u00e9 a \u00faltima arma prim\u00e1ria de Mul-T que se destaca em combate corpo a corpo. Isso faz com que Mul-T implante uma serra enorme que causa 1000% de dano base por segundo aos inimigos pr\u00f3ximos com um coeficiente de proc de 1,0. Cada marca de dano causa 100% de dano e um ataque marca dez vezes por segundo com velocidade de ataque base.<\/p>\n\n<p>Para desbloquear o Power-Saw de Mul-T, voc\u00ea deve completar o Gotcha! Desafio. Para este desafio, voc\u00ea deve acertar o golpe mortal em um Imp Overlord com o Preon Accumulator. O Preon Accumulator \u00e9 um equipamento de alto dano que atira uma bola lenta que causa 8000% de dano em um raio de explos\u00e3o de 20 metros.<\/p>\n\n<p>Voc\u00ea pode adquirir o Preon Accumulator no ba\u00fa exclusivo em Rallypoint Delta. O ba\u00fa de seguran\u00e7a cronometrado \u00e9 um ba\u00fa com o qual s\u00f3 \u00e9 poss\u00edvel interagir se voc\u00ea abri-lo antes que o cron\u00f4metro do jogo chegue a 10 minutos.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-secondaries\">Secund\u00e1rios<\/h3>\n\n<h4 class=\"wp-block-heading\" id=\"h-blast-canister\">Recipiente de Explos\u00e3o<\/h4>\n\n<p>Blast Canister \u00e9 o \u00fanico secund\u00e1rio para voc\u00ea construir Mul T em Risk of Rain 2. Ele lan\u00e7a v\u00e1rias pequenas bombas de uma vasilha que atordoa os inimigos em contato. A vasilha causa 200% de dano enquanto as bombas pequenas causam 5&#215;44% de dano e atordoam. Segurar a tecla secund\u00e1ria exibe o arco do proj\u00e9til e o raio da explos\u00e3o. Use isso para garantir que voc\u00ea obtenha o m\u00e1ximo de seu controle de multid\u00e3o.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-the-only-utility-ability-mul-t-has-in-risk-of-rain-2\">A \u00fanica habilidade utilit\u00e1ria que Mul T tem em Risk of Rain 2<\/h3>\n\n<p>Mul-T tem um Utilit\u00e1rio para adicionar \u00e0 sua compila\u00e7\u00e3o em Risk of Rain 2, e \u00e9 chamado de Modo de Transporte. Embora n\u00e3o seja t\u00e3o vers\u00e1til quanto outros Utilit\u00e1rios, o Modo de Transporte \u00e9 uma \u00f3tima maneira de fugir de uma situa\u00e7\u00e3o ruim ou enfrentar um grupo de inimigos. Atingir um inimigo com o modo de transporte causar\u00e1 2,5x seu dano base, mas se o inimigo for grande, voc\u00ea o atordoar\u00e1 e causar\u00e1 10x seu dano base, encerrando o modo de transporte.<\/p>\n\n<p>Voc\u00ea ganha 200 de armadura quando esta habilidade est\u00e1 ativa, reduzindo o dano recebido em aproximadamente 66%. O poder tamb\u00e9m oferece uma explos\u00e3o tempor\u00e1ria de aproximadamente 45% da velocidade de movimento.<\/p>\n\n<p><strong>Guia relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/transcendencia-e-bom-em-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">voc\u00ea deve usar transcend\u00eancia em Risk of Rain 2?<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-specials\">Especiais <\/h3>\n\n<p>Os especiais do Mul-T mudam drasticamente a forma como voc\u00ea os joga, fornecendo um modo de jogo diferente para cada um. O principal especial de Mul-T \u00e9 Retool. Ele permite que Mul T troque entre os dois conjuntos de prim\u00e1rias escolhidos no in\u00edcio do jogo. O Retool pode alternar entre dois m\u00e9todos de jogo sem ter que se comprometer totalmente com um. Isso permite que Mul-T equipe dois conjuntos de itens de equipamento com seus cooldowns exclusivos. Acreditamos que a alternativa \u00e9 mais forte por maior que seja essa capacidade.<\/p>\n\n<p>A habilidade do modo de energia do Mul-T \u00e9 uma altern\u00e2ncia incrivelmente forte que permite ao rob\u00f4 disparar as duas prim\u00e1rias escolhidas no in\u00edcio do jogo em detrimento da velocidade. Embora a dica de ferramenta sugira que Mul-T seja reduzido para 40% da velocidade, eles mant\u00eam aproximadamente 66% de sua velocidade de movimento.<\/p>\n\n<p>Essa habilidade concede Armadura Mul T 100 em Risco de Chuva 2, o que reduziria o dano recebido em aproximadamente 50%, visto que voc\u00ea n\u00e3o possui armadura natural. A outra restri\u00e7\u00e3o \u00e9 que Mul-T \u00e9 impedido de usar seu secund\u00e1rio padr\u00e3o nesta forma, mas \u00e9 indiscutivelmente sua habilidade mais fraca, ent\u00e3o voc\u00ea n\u00e3o est\u00e1 perdendo muito.<\/p>\n\n<p>Para desbloquear o Power Mode, voc\u00ea deve atingir o est\u00e1gio 7 ou posterior e ir para o Void Fields. Caso voc\u00ea n\u00e3o tenha certeza, os Campos Vazios podem ser encontrados apenas indo ao Bazaar Between Time e depois \u00e0 enseada bem abaixo do spawn. \u00c9 altamente recomend\u00e1vel fazer isso apenas se voc\u00ea estiver jogando no Drizzle e j\u00e1 tiver uma constru\u00e7\u00e3o que abater\u00e1 os inimigos poderosos ao seu redor.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-should-you-build-on-mul-t-in-risk-of-rain-2\">O que voc\u00ea deve construir em Mul T em Risk of Rain 2?<\/h2>\n\n<p>A escolha de itens de Mul-T gira em torno de suas in\u00fameras habilidades prim\u00e1rias, dependendo mais do estilo de jogo que voc\u00ea deseja seguir. Voc\u00ea pode optar por velocidade de ataque, crit, armadura, velocidade de movimento, ao acertar, ao matar, etc. Acreditamos que usar o Power Mode junto com duas Auto-Nailguns \u00e9 a melhor op\u00e7\u00e3o para Mul-T. Isso transformar\u00e1 o Mul-T em um tanque de ataque e permitir\u00e1 que voc\u00ea destrua os inimigos se voc\u00ea curar os inimigos devido aos v\u00e1rios proj\u00e9teis da Auto-Nailgun.<\/p>\n\n<p>A \u00fanica coisa que n\u00e3o encorajamos, pelo menos do ponto de vista s\u00e9rio, \u00e9 usar a Serra El\u00e9trica. A menos que voc\u00ea esteja fazendo isso por divers\u00e3o, o Power Saw n\u00e3o \u00e9 ideal na maioria das situa\u00e7\u00f5es, especialmente se voc\u00ea n\u00e3o tiver uma op\u00e7\u00e3o prim\u00e1ria alternativa.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-tips-tricks-on-how-to-play-mul-t-in-risk-of-rain-2\">Dicas e truques para jogar Mul-T em Risk of Rain 2<\/h2>\n\n<ul class=\"wp-block-list\"><li>O Power-Saw de Mul T pode ser usado durante a corrida e no modo de transporte, desde que o bot\u00e3o de disparo seja pressionado.<\/li><li>Ao sair do Power Mode, todas as pilhas de Blast Canisters s\u00e3o recarregadas imediatamente.<\/li><li>Ao iniciar uma execu\u00e7\u00e3o de Risk of Rain 2 como Mul-T, voc\u00ea pode selecionar a mesma arma principal duas vezes. Isso permite que voc\u00ea empunhe duas vezes a mesma arma.<\/li><li>A Ess\u00eancia da Heresia substitui Retool ou Power Mode, o que torna o prim\u00e1rio secund\u00e1rio de Mul-T inativo at\u00e9 que o tempo seja removido. Evite agarrar Essence of Heresy em Mul-T.<\/li><li>O Power Mode basicamente dobra a produ\u00e7\u00e3o de dano do Mul-T com pequenas desvantagens, permitindo que voc\u00ea dobre o dano e a taxa de disparo de qualquer prim\u00e1rio, como pistolas Auto-Nail de empunhadura dupla ou Power-Saws.<\/li><li>A velocidade de ataque empilh\u00e1vel permite que o recuo da Auto-Nailgun empurre Mul-T para tr\u00e1s o suficiente para mant\u00ea-los indefinidamente no ar.<\/li><\/ul>\n\n<p><strong>Guia Relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-a-cacadora-em-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como Construir Huntress em RoR2<\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wrap-up\">Embrulhar<\/h2>\n\n<p>Esse \u00e9 o nosso guia para tudo o que voc\u00ea precisa saber sobre como jogar Mul T em Risk of Rain 2. No geral, esse sobrevivente \u00e9 conhecido por sua utilidade e tem muito potencial para mais builds que outros sobreviventes carecem em compara\u00e7\u00e3o. <\/p>\n\n<p>Mul-T \u00e9 uma pot\u00eancia lenta com op\u00e7\u00f5es de armas prim\u00e1rias suficientes para se adequar a uma variedade de estilos de jogo de Risk of Rain 2. Eles tamb\u00e9m t\u00eam uma capacidade de tanque surpreendente para enfrentar hordas de monstros que outros n\u00e3o conseguem.<\/p>\n\n<p>O que voc\u00ea achou das nossas dicas de como jogar e construir Mul T em Risk of Rain 2? Se voc\u00ea \u00e9 um grande f\u00e3 do Mul-T, tem alguma outra sugest\u00e3o para seus colegas leitores? N\u00f3s adorar\u00edamos ouvir de voc\u00ea.<\/p>\n\n<p>Para mais dicas de constru\u00e7\u00e3o, confira nosso guia sobre <a href=\"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-commando-em-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">como jogar e construir Commando em Risk of Rain 2<\/a> .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mul-T \u00e9 um rob\u00f4 multiuso com grande versatilidade utilizando suas v\u00e1rias armas intercambi\u00e1veis. Ele \u00e9 projetado para se adaptar a v\u00e1rios estilos de jogo. Al\u00e9m disso, seus diferentes tipos de armas permitem que eles joguem em diferentes dist\u00e2ncias e com diferentes caminhos de constru\u00e7\u00e3o Mul T em Risk of Rain 2. Mul T funciona de<\/p>\n","protected":false},"author":6,"featured_media":15655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[628],"tags":[1473],"platform":[669,670,631,671],"class_list":{"0":"post-32858","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guias-pt-br","8":"tag-risco-de-chuva-2","9":"platform-playstation-4-pt-br","10":"platform-trocar","11":"platform-windowsos-pt-br","12":"platform-xbox-one-pt-br"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Como jogar e construir Mul T em Risk of Rain 2 | FPS Champion<\/title>\n<meta name=\"description\" content=\"Mul T \u00e9 uma pot\u00eancia de um rob\u00f4. Este guia mostrar\u00e1 como construir Mul-T e jog\u00e1-lo em Risk of Rain 2.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como jogar e construir Mul T em Risk of Rain 2\" \/>\n<meta property=\"og:description\" content=\"Mul T \u00e9 uma pot\u00eancia de um rob\u00f4. Este guia mostrar\u00e1 como construir Mul-T e jog\u00e1-lo em Risk of Rain 2.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-16T06:35:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T06:09:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/mul-t-risk-of-rain-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Como jogar e construir Mul T em Risk of Rain 2\",\"datePublished\":\"2022-07-16T06:35:29+00:00\",\"dateModified\":\"2023-06-04T06:09:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/\"},\"wordCount\":1728,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/mul-t-risk-of-rain-2.jpg\",\"keywords\":[\"Risco de Chuva 2\"],\"articleSection\":[\"Guias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/\",\"name\":\"Como jogar e construir Mul T em Risk of Rain 2 | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/mul-t-risk-of-rain-2.jpg\",\"datePublished\":\"2022-07-16T06:35:29+00:00\",\"dateModified\":\"2023-06-04T06:09:32+00:00\",\"description\":\"Mul T \u00e9 uma pot\u00eancia de um rob\u00f4. Este guia mostrar\u00e1 como construir Mul-T e jog\u00e1-lo em Risk of Rain 2.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/mul-t-risk-of-rain-2.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/mul-t-risk-of-rain-2.jpg\",\"width\":1600,\"height\":812,\"caption\":\"Mul T from Risk of Rain 2 | Source: In-Game Screenshot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como jogar e construir Mul T em Risk of Rain 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como jogar e construir Mul T em Risk of Rain 2 | FPS Champion","description":"Mul T \u00e9 uma pot\u00eancia de um rob\u00f4. Este guia mostrar\u00e1 como construir Mul-T e jog\u00e1-lo em Risk of Rain 2.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Como jogar e construir Mul T em Risk of Rain 2","og_description":"Mul T \u00e9 uma pot\u00eancia de um rob\u00f4. Este guia mostrar\u00e1 como construir Mul-T e jog\u00e1-lo em Risk of Rain 2.","og_url":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/","og_site_name":"FPS Champion","article_published_time":"2022-07-16T06:35:29+00:00","article_modified_time":"2023-06-04T06:09:32+00:00","og_image":[{"width":1600,"height":812,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/mul-t-risk-of-rain-2.jpg","type":"image\/jpeg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Como jogar e construir Mul T em Risk of Rain 2","datePublished":"2022-07-16T06:35:29+00:00","dateModified":"2023-06-04T06:09:32+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/"},"wordCount":1728,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/mul-t-risk-of-rain-2.jpg","keywords":["Risco de Chuva 2"],"articleSection":["Guias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/","url":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/","name":"Como jogar e construir Mul T em Risk of Rain 2 | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/mul-t-risk-of-rain-2.jpg","datePublished":"2022-07-16T06:35:29+00:00","dateModified":"2023-06-04T06:09:32+00:00","description":"Mul T \u00e9 uma pot\u00eancia de um rob\u00f4. Este guia mostrar\u00e1 como construir Mul-T e jog\u00e1-lo em Risk of Rain 2.","breadcrumb":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/mul-t-risk-of-rain-2.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/mul-t-risk-of-rain-2.jpg","width":1600,"height":812,"caption":"Mul T from Risk of Rain 2 | Source: In-Game Screenshot"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/pt-br\/como-jogar-e-construir-mul-t-em-risk-of-rain-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Como jogar e construir Mul T em Risk of Rain 2"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/pt-br\/#website","url":"https:\/\/fpschampion.com\/pt-br\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/pt-br\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/pt-br\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/comments?post=32858"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32858\/revisions"}],"predecessor-version":[{"id":32865,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32858\/revisions\/32865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media\/15655"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media?parent=32858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/categories?post=32858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/tags?post=32858"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/platform?post=32858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}