{"id":32765,"date":"2022-06-29T04:57:31","date_gmt":"2022-06-29T04:57:31","guid":{"rendered":"https:\/\/fpschampion.com\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/"},"modified":"2023-06-04T06:08:55","modified_gmt":"2023-06-04T06:08:55","slug":"como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/","title":{"rendered":"Como usar o rifle de assalto em Halo Infinite (MA40 AR)"},"content":{"rendered":"\n<p>O rifle de assalto sempre foi um item b\u00e1sico na s\u00e9rie Halo. \u00c9 a principal arma usada pelos espartanos e fuzileiros navais da UNSC. Al\u00e9m da pistola, ela costuma ser uma das primeiras armas que voc\u00ea vai come\u00e7ar a usar. Ao longo dos anos, esta arma passou por muitas mudan\u00e7as de design. Mas a jogabilidade do fuzil de assalto permanece a mesma em Halo Infinite.<\/p>\n\n<p>Tecnicamente, a s\u00e9rie Halo apresentou diferentes varia\u00e7\u00f5es desta arma, com o MA40 AR sendo um modelo mais antigo em termos de tradi\u00e7\u00e3o, todos eles t\u00eam o mesmo desempenho. No entanto, o MA40 AR tem uma das maiores capacidades de carregador e a taxa de disparo mais r\u00e1pida em compara\u00e7\u00e3o com os fuzis de assalto anteriores em Halo. Provando que, embora possa ser mais antigo, ainda pode competir com muitas armas no universo Halo.<\/p>\n\n<p>O rifle de assalto raramente mudou de jogo para jogo, mas parece estar em um lugar muito melhor aqui. Vamos mergulhar mais fundo e descobrir o porqu\u00ea.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-ma40-ar-assault-rifle-general-information\">MA40 AR (Rifle de Assalto) Informa\u00e7\u00f5es Gerais<\/h2>\n\n<ul class=\"wp-block-list\"><li><strong>Tipo de Arma:<\/strong> Rifle de Assalto<\/li><li><strong>Fabricante:<\/strong> Misriah Armory<\/li><li><strong>Tipo de Muni\u00e7\u00e3o:<\/strong> Cin\u00e9tica<\/li><li><strong>Tamanho da revista:<\/strong> 36<\/li><li><strong>Cad\u00eancia de tiro:<\/strong> totalmente autom\u00e1tica<\/li><li><strong>Perfect Time To Kill (Multiplayer):<\/strong> 15 tiros (12 tiros no corpo e 3 tiros na cabe\u00e7a).<\/li><\/ul>\n\n<p>O MA40 AR \u00e9 um rifle de assalto totalmente autom\u00e1tico em Halo Infinite fabricado pelo Misriah Armory. \u00c9 usado principalmente pelo UNSC. Funciona maravilhosamente ao lidar com oponentes de alcance pr\u00f3ximo a m\u00e9dio.<\/p>\n\n<p>Ao contr\u00e1rio da maioria das armas cin\u00e9ticas, esta arma n\u00e3o mata oponentes desprotegidos com um tiro na cabe\u00e7a. Esta arma ser\u00e1 sua principal arma inicial no Quick Play. No entanto, esta arma \u00e9 trocada pelo Rifle de Batalha nas <a href=\"https:\/\/fpschampion.com\/pt-br\/classificacoes-em-halo-infinite-tudo-o-que-voce-precisa-saber-sobre-a-arena-ranqueada\/\" target=\"_blank\" rel=\"noreferrer noopener\">partidas da Arena Ranqueada<\/a> .<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-best-maps-to-use-the-assault-rifle-in-halo-infinite\">Melhores mapas para usar o rifle de assalto em Halo Infinite<\/h2>\n\n<p>O melhor do MA40 \u00e9 que ele \u00e9 adequado para todos os mapas do Halo Infinite. Com toda a honestidade, deve ser bom para todos os mapas, considerando que \u00e9 sua arma inicial. A menos que voc\u00ea esteja jogando Ranqueado, sua arma inicial ser\u00e1 <a href=\"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-batalha-br75-no-halo-infinite-multiplayer\/\" target=\"_blank\" rel=\"noreferrer noopener\">o Rifle de Batalha<\/a> . No entanto, n\u00e3o importa se voc\u00ea est\u00e1 jogando Quickplay ou Big Team Battle, voc\u00ea sempre come\u00e7ar\u00e1 com o MA40 AR na m\u00e3o.<\/p>\n\n<p>Os mapas de arena s\u00e3o mais adequados para esta arma devido ao seu tamanho em compara\u00e7\u00e3o com mapas maiores. O fuzil de assalto \u00e9 fant\u00e1stico no multijogador Halo Infinite de curto e m\u00e9dio alcance. As \u00fanicas outras armas sem poder que podem competir com ele s\u00e3o o Bulldog e o <a href=\"https:\/\/fpschampion.com\/pt-br\/como-usar-o-sentinel-beam-no-halo-infinite-multiplayer\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sentinel Beam em Halo Infinite<\/a> . Talvez o Battle Rifle, mas apenas se voc\u00ea estiver mais distante do jogador.<\/p>\n\n<p>Esta arma pode funcionar em mapas de Big Team Battle, mas considerando quantos distribuidores de armas est\u00e3o perto da base, \u00e9 melhor voc\u00ea pegar uma arma de precis\u00e3o. Se n\u00e3o houver armas dispon\u00edveis, sinta-se \u00e0 vontade para usar o MA40 AR. No entanto, armas de precis\u00e3o e armas poderosas reinam neste modo de jogo. A melhor situa\u00e7\u00e3o para usar esta arma \u00e9 durante <a href=\"https:\/\/fpschampion.com\/pt-br\/cobertura-completa-dos-novos-modos-de-jogo-de-halo-infinite-na-segunda-temporada\/\">os modos de jogo baseados em captura<\/a> .<\/p>\n\n<p>Por exemplo, o modo de jogo Total Control exige que voc\u00ea seja ofensivo ou defensivo. Se voc\u00ea est\u00e1 defendendo um de seus pontos capturados, o rifle de assalto \u00e9 uma \u00f3tima arma para derrubar inimigos. O mesmo pode ser dito para ir para a ofensiva. Algumas <a href=\"https:\/\/fpschampion.com\/pt-br\/como-usar-todas-as-granadas-infinitas-do-halo-de-maneira-eficaz-no-modo-multijogador\/\">granadas bem posicionadas no Halo Infinite<\/a> podem derrubar um pouco os escudos inimigos. Ent\u00e3o sinta-se \u00e0 vontade para tentar limp\u00e1-los com o MA40 AR com uma saraivada de balas.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-halo-infinite-assault-rifle-tips-and-tricks\">Halo Infinite Assault Rifle Dicas e Truques<\/h2>\n\n<p>O Rifle de Assalto MA40 \u00e9 uma das armas mais diretas em Halo Infinite. Basta pulverizar e rezar. Honestamente, \u00e9 bastante preciso e mata algu\u00e9m em segundos se voc\u00ea acertar todos os tiros. No entanto, ainda requer us\u00e1-lo estrategicamente. Ent\u00e3o, aqui est\u00e3o algumas dicas r\u00e1pidas que devem ajudar.<\/p>\n\n<h3 class=\"wp-block-heading\">Go Full Auto (perto e alcance m\u00e9dio)<\/h3>\n\n<p>Esta arma tem tudo a ver com segurar o gatilho e descarregar um pente inteiro em algu\u00e9m. Se o seu oponente estiver pr\u00f3ximo ou a menos de 15 metros de voc\u00ea, ent\u00e3o atire o m\u00e1ximo de balas poss\u00edvel. Os exerc\u00edcios com armas ajudar\u00e3o a determinar a que dist\u00e2ncia um oponente est\u00e1 se voc\u00ea n\u00e3o souber.<\/p>\n\n<p><strong>Artigo relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/como-denunciar-um-jogador-no-halo-infinite\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como denunciar um jogador no Halo Infinite<\/a><\/p>\n\n<h3 class=\"wp-block-heading\">Explos\u00f5es mais curtas com o rifle de assalto funcionam melhor a longo alcance em Halo Infinite<\/h3>\n\n<p>Embora seja melhor disparar continuamente a arma, para uma melhor precis\u00e3o a longas dist\u00e2ncias, tente usar rajadas curtas. S\u00f3 recorra a esta op\u00e7\u00e3o se n\u00e3o tiver arma de precis\u00e3o como secund\u00e1ria. Rajadas curtas ajudar\u00e3o a manter a precis\u00e3o da arma. Infelizmente, esta arma n\u00e3o vai matar ningu\u00e9m a longas dist\u00e2ncias, \u00e9 principalmente para impedir que o escudo se regenere e fornecer suporte aos companheiros de equipe.<\/p>\n\n<h3 class=\"wp-block-heading\">Combine o Rifle de Assalto com uma Arma de Precis\u00e3o em Halo Infinite<\/h3>\n\n<p>O Rifle de Assalto \u00e9 uma das \u00fanicas armas cin\u00e9ticas que n\u00e3o mata um oponente com 1 bala na cabe\u00e7a enquanto n\u00e3o est\u00e1 blindado. Leva 3 tiros na cabe\u00e7a. Por esse motivo, \u00e9 melhor ter uma arma de precis\u00e3o como secund\u00e1ria para a qual voc\u00ea possa trocar para uma morte f\u00e1cil. As <a href=\"https:\/\/fpschampion.com\/pt-br\/como-usar-a-pistola-sidekick-do-halo-infinite-no-modo-multijogador\/\" target=\"_blank\" rel=\"noreferrer noopener\">pistolas VK78 Commando, BR75 e MK50 Sidekick<\/a> s\u00e3o boas escolhas para se ter como reserva e podem matar com um tiro na cabe\u00e7a de um oponente desprotegido.<\/p>\n\n<h3 class=\"wp-block-heading\">A propaga\u00e7\u00e3o da arma aumenta durante o disparo<\/h3>\n\n<p>O MA40 AR \u00e9 bastante preciso em dist\u00e2ncias mais pr\u00f3ximas e tamb\u00e9m tem baixo recuo. Mas quanto mais voc\u00ea constantemente disparar a arma, maior ser\u00e1 a propaga\u00e7\u00e3o da bala da arma. Depois de disparar de 15 a 20 balas, suas balas v\u00e3o sair do ret\u00edculo. Embora esteja muito perto de um oponente, isso n\u00e3o importa muito. No entanto, mesmo em m\u00e9dio alcance, isso come\u00e7ar\u00e1 a se tornar um problema.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclus\u00e3o<\/h2>\n\n<p>O MA40 AR \u00e9 uma \u00f3tima arma inicial e o Assualt Rifle nunca foi melhor. A maioria dos jogadores obter\u00e1 a maior parte de suas mortes com esta arma, a menos que eles peguem uma arma poderosa. Baixo recuo, dano razo\u00e1vel e boa precis\u00e3o tornam esta arma dif\u00edcil de lidar.<\/p>\n\n<p>\u00c9 dif\u00edcil escapar do Rifle de Assalto em Halo Infinite. Uma barragem constante de balas com uma velocidade de recarga bastante r\u00e1pida ajuda a tornar este rifle uma das <a href=\"https:\/\/fpschampion.com\/pt-br\/todas-as-armas-do-halo-infinite-classificadas-do-melhor-ao-pior-lista-de-niveis-de-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">melhores armas do Halo Infinite<\/a> . Quais s\u00e3o seus pensamentos sobre o MA40 AR? \u00c9 uma \u00f3tima arma inicial? Sinta-se livre para soar na se\u00e7\u00e3o de coment\u00e1rios abaixo.<\/p>\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como usar o arsenal do Halo Infinite, confira nosso <a href=\"https:\/\/fpschampion.com\/pt-br\/como-usar-o-ravager-em-halo-infinite-multiplayer\/\" target=\"_blank\" rel=\"noreferrer noopener\">guia para usar o Ravager no modo multijogador<\/a> .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O rifle de assalto sempre foi um item b\u00e1sico na s\u00e9rie Halo. \u00c9 a principal arma usada pelos espartanos e fuzileiros navais da UNSC. Al\u00e9m da pistola, ela costuma ser uma das primeiras armas que voc\u00ea vai come\u00e7ar a usar. Ao longo dos anos, esta arma passou por muitas mudan\u00e7as de design. Mas a jogabilidade<\/p>\n","protected":false},"author":1,"featured_media":15191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[628],"tags":[1549],"platform":[631,671,672],"class_list":{"0":"post-32765","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guias-pt-br","8":"tag-halo-infinito","9":"platform-windowsos-pt-br","10":"platform-xbox-one-pt-br","11":"platform-xbox-series-x-s-pt-br"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Como usar o rifle de assalto em Halo Infinite (MA40 AR) | FPS Champion<\/title>\n<meta name=\"description\" content=\"O Rifle de Assalto \u00e9 OP em Halo Infinite? Pode ser, mas nossas dicas e truques mostrar\u00e3o como ser verdadeiramente impar\u00e1vel com isso!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como usar o rifle de assalto em Halo Infinite (MA40 AR)\" \/>\n<meta property=\"og:description\" content=\"O Rifle de Assalto \u00e9 OP em Halo Infinite? Pode ser, mas nossas dicas e truques mostrar\u00e3o como ser verdadeiramente impar\u00e1vel com isso!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T04:57:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T06:08:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Halo-Infinite-Assault-Rifle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2448\" \/>\n\t<meta property=\"og:image:height\" content=\"1207\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"John\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/\"},\"author\":{\"name\":\"John\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/46c4155ed84016df7368a97955a3a8ed\"},\"headline\":\"Como usar o rifle de assalto em Halo Infinite (MA40 AR)\",\"datePublished\":\"2022-06-29T04:57:31+00:00\",\"dateModified\":\"2023-06-04T06:08:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/\"},\"wordCount\":1164,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Halo-Infinite-Assault-Rifle.jpg\",\"keywords\":[\"halo infinito\"],\"articleSection\":[\"Guias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/\",\"name\":\"Como usar o rifle de assalto em Halo Infinite (MA40 AR) | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Halo-Infinite-Assault-Rifle.jpg\",\"datePublished\":\"2022-06-29T04:57:31+00:00\",\"dateModified\":\"2023-06-04T06:08:55+00:00\",\"description\":\"O Rifle de Assalto \u00e9 OP em Halo Infinite? Pode ser, mas nossas dicas e truques mostrar\u00e3o como ser verdadeiramente impar\u00e1vel com isso!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Halo-Infinite-Assault-Rifle.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Halo-Infinite-Assault-Rifle.jpg\",\"width\":2448,\"height\":1207,\"caption\":\"Assault Rifle (MA40 AR) | Source: Halo Infinite Screenshot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como usar o rifle de assalto em Halo Infinite (MA40 AR)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/46c4155ed84016df7368a97955a3a8ed\",\"name\":\"John\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"caption\":\"John\"},\"description\":\"John has been playing video games for almost 30 years. From the days of Sim Ant until now, he's been a fan of just about all genres of video games, including FPS games. He has taken on reporting on new and old games as a passion project and really just enjoys being able to inform and guide other like-minded players.\",\"sameAs\":[\"https:\\\/\\\/fpschampion.com\"],\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/author\\\/fpschamp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como usar o rifle de assalto em Halo Infinite (MA40 AR) | FPS Champion","description":"O Rifle de Assalto \u00e9 OP em Halo Infinite? Pode ser, mas nossas dicas e truques mostrar\u00e3o como ser verdadeiramente impar\u00e1vel com isso!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/","og_locale":"pt_BR","og_type":"article","og_title":"Como usar o rifle de assalto em Halo Infinite (MA40 AR)","og_description":"O Rifle de Assalto \u00e9 OP em Halo Infinite? Pode ser, mas nossas dicas e truques mostrar\u00e3o como ser verdadeiramente impar\u00e1vel com isso!","og_url":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/","og_site_name":"FPS Champion","article_published_time":"2022-06-29T04:57:31+00:00","article_modified_time":"2023-06-04T06:08:55+00:00","og_image":[{"width":2448,"height":1207,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Halo-Infinite-Assault-Rifle.jpg","type":"image\/jpeg"}],"author":"John","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"John","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/"},"author":{"name":"John","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/46c4155ed84016df7368a97955a3a8ed"},"headline":"Como usar o rifle de assalto em Halo Infinite (MA40 AR)","datePublished":"2022-06-29T04:57:31+00:00","dateModified":"2023-06-04T06:08:55+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/"},"wordCount":1164,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Halo-Infinite-Assault-Rifle.jpg","keywords":["halo infinito"],"articleSection":["Guias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/","url":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/","name":"Como usar o rifle de assalto em Halo Infinite (MA40 AR) | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Halo-Infinite-Assault-Rifle.jpg","datePublished":"2022-06-29T04:57:31+00:00","dateModified":"2023-06-04T06:08:55+00:00","description":"O Rifle de Assalto \u00e9 OP em Halo Infinite? Pode ser, mas nossas dicas e truques mostrar\u00e3o como ser verdadeiramente impar\u00e1vel com isso!","breadcrumb":{"@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Halo-Infinite-Assault-Rifle.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Halo-Infinite-Assault-Rifle.jpg","width":2448,"height":1207,"caption":"Assault Rifle (MA40 AR) | Source: Halo Infinite Screenshot"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/pt-br\/como-usar-o-rifle-de-assalto-em-halo-infinite-ma40-ar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Como usar o rifle de assalto em Halo Infinite (MA40 AR)"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/pt-br\/#website","url":"https:\/\/fpschampion.com\/pt-br\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/pt-br\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/46c4155ed84016df7368a97955a3a8ed","name":"John","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","caption":"John"},"description":"John has been playing video games for almost 30 years. From the days of Sim Ant until now, he's been a fan of just about all genres of video games, including FPS games. He has taken on reporting on new and old games as a passion project and really just enjoys being able to inform and guide other like-minded players.","sameAs":["https:\/\/fpschampion.com"],"url":"https:\/\/fpschampion.com\/pt-br\/author\/fpschamp\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/comments?post=32765"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32765\/revisions"}],"predecessor-version":[{"id":32775,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32765\/revisions\/32775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media\/15191"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media?parent=32765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/categories?post=32765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/tags?post=32765"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/platform?post=32765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}