{"id":32028,"date":"2022-04-08T05:16:04","date_gmt":"2022-04-08T05:16:04","guid":{"rendered":"https:\/\/fpschampion.com\/eles-nerf-aim-assist-em-halo-infinite\/"},"modified":"2023-06-04T06:03:44","modified_gmt":"2023-06-04T06:03:44","slug":"eles-nerf-aim-assist-em-halo-infinite","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/","title":{"rendered":"Eles Nerf Aim Assist em Halo Infinite?"},"content":{"rendered":"\n<p>Desde o lan\u00e7amento do jogo, o Aim Assist em Halo Infinite tem sido um t\u00f3pico de discuss\u00e3o. Ao longo da vida de Halo, a franquia sempre se concentrou em programar os jogos especificamente para controladores. Isso permitiu que todos os jogadores estivessem em p\u00e9 de igualdade.<\/p>\n\n<p>Desde o lan\u00e7amento da Master Chief Collection no PC, todos os t\u00edtulos Halo anteriores foram introduzidos no mouse e teclado pela primeira vez. Desde ent\u00e3o, o Halo Infinite, projetado para ambas as plataformas ap\u00f3s o lan\u00e7amento, fica aqu\u00e9m do Aim Assist para usu\u00e1rios do controlador. Isso levou muitos a se perguntarem se o controlador ainda \u00e9 a op\u00e7\u00e3o superior ou se o teclado e o mouse s\u00e3o competitivamente iguais.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-looking-back-at-previous-halo-games\">Olhando para tr\u00e1s nos jogos Halo anteriores<\/h2>\n\n<p>Halo 3 \u00e9 amplamente reconhecido como um dos melhores jogos Halo lan\u00e7ados. Ele introduziu uma carga de mudan\u00e7as bem-vindas para a comunidade. Assim como as duas primeiras itera\u00e7\u00f5es da franquia, o Halo 3 foi feito com controladores na estrutura do movimento do jogo.<\/p>\n\n<p>Esta obra-prima tinha rastreamento suave para usu\u00e1rios de controladores. Como resultado, a mira se moveria para o alvo que o jogador estava mirando. Como discutiremos, o Halo Infinite n\u00e3o herdou esse esquema de controle para o Aim Assist. O rastreamento era muito consistente no Halo 3 e seguia ativamente os alvos, mesmo parados.<\/p>\n\n<p>Isso seria visto como uma adapta\u00e7\u00e3o muito ruim do Aim Assist na era moderna. Hoje em dia, as pessoas frequentemente escolhem jogar com outras pessoas que preferem estilos de controle diferentes. O Aim Assist for Halo Infinite foi criado com isso em mente. Ent\u00e3o, muito do que o tornou bom foi destru\u00eddo para tentar equilibrar ainda mais o jogo.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-different-examples-of-aim-assist-in-modern-media\">Diferentes exemplos de assist\u00eancia de mira na m\u00eddia moderna<\/h2>\n\n<p>Muitos jogos FPS incluem Aim Assist, como Call of Duty e Apex Legends. Se um jogo for projetado para um console, voc\u00ea raramente encontrar\u00e1 uma situa\u00e7\u00e3o em que n\u00e3o haja algum n\u00edvel de Aim Assist. A principal diferen\u00e7a entre o mouse e o teclado s\u00e3o os movimentos r\u00e1pidos e movimentos precisos. Estes s\u00e3o facilmente alcan\u00e7\u00e1veis quando algu\u00e9m est\u00e1 deslizando o mouse sobre a mesa.<\/p>\n\n<p>Alguns jogos exageraram ao tentar dar aos jogadores controladores um meio de replicar essa vantagem reflexa. Um bom exemplo disso s\u00e3o os jogos modernos de Call of Duty. Tornar o Aim Assist ajust\u00e1vel ao jogador pode eliminar v\u00e1rios graus de habilidade, uma vez que as pessoas descobrem quais configura\u00e7\u00f5es exigem menos esfor\u00e7o.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-aim-assist-in-halo-infinite\">Assist\u00eancia de Mira no Halo Infinite<\/h2>\n\n<p>Halo Infinite \u00e9 um jogo de tiro baseado em arena, assim como os t\u00edtulos Halo anteriores. O controle do mapa, os objetivos e o uso da caixa de areia a seu favor comp\u00f5em a jogabilidade central do Halo. Maximizar seu KDA no Halo \u00e9 em grande parte o objetivo. Uma grande parte do seu tempo ser\u00e1 gasta em lutas corpo a corpo. Neles, os jogadores est\u00e3o constantemente metralhando, pulando, deslizando. Eles geralmente fazem o poss\u00edvel para superar o oponente enquanto acertam o m\u00e1ximo de tiros poss\u00edvel.<\/p>\n\n<p>Este estilo de luta \u00e9 fundamental para todos os jogos FPS. No entanto, \u00e9 separado para Halo com a frequ\u00eancia com que isso acontece. H\u00e1 pouco ou nenhum tempo de inatividade como nos jogos Battle Royal. Al\u00e9m disso, raramente h\u00e1 uma configura\u00e7\u00e3o como nos atiradores de equipe mais tradicionais.<\/p>\n\n<p>Ao rastrear um alvo usando um controlador no Halo Infinite, sua c\u00e2mera ir\u00e1 encaixar e ajustar para manter seu alvo. Isso torna as lutas metralhadoras muito mais f\u00e1ceis do que o teclado. Este Aim Assist sempre esteve nos jogos Halo. No entanto, todos os jogos Halo anteriores foram criados para uso do controlador apenas em mente.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-aim-assist-in-halo-infinite-for-controller-users-vs-mouse-and-keyboard-users\">Aim Assist no Halo Infinite para usu\u00e1rios de controle versus usu\u00e1rios de mouse e teclado<\/h3>\n\n<p>Se n\u00e3o houvesse a op\u00e7\u00e3o de uso do teclado, esse t\u00f3pico provavelmente nunca teria dividido a comunidade. No entanto, agora h\u00e1 uma escolha de como jogar Halo, e isso gerou muitas discuss\u00f5es acaloradas. No ano passado, houve v\u00e1rios relat\u00f3rios, filmagens e experi\u00eancias mostrando que o controlador tem uma vantagem significativa sobre o PC e inst\u00e2ncias em que o Aim Assist est\u00e1 quebrado.<\/p>\n\n<p>Os jogadores descobriram que o rastreamento de armas em ambas as formas de jogo era inconsistente. Bullet Magnetism e Bloom s\u00e3o exemplos prim\u00e1rios de como o Halo Infinite ainda luta para equilibrar seus esquemas de controle duplo. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-bullet-magnetism\">Magnetismo de bala<\/h2>\n\n<p>Um tipo de assist\u00eancia que tanto o controlador quanto o mouse e o teclado compartilham \u00e9 o Bullet Magnetism. Sempre que o ret\u00edculo estiver ligeiramente desviado de atingir um inimigo, voc\u00ea poder\u00e1 ver algumas balas perdidas aparentemente sendo sugadas aleatoriamente para a caixa de acerto do inimigo. Isso geralmente \u00e9 chamado de Bullet Magnetism e \u00e9 uma ferramenta amplamente suportada em jogos FPS modernos.<\/p>\n\n<p>O magnetismo de bala geralmente entra em jogo quando os hitboxes podem ser inconsistentes ou se estender para fora do modelo do jogador. O magnetismo da bala pode se tornar altamente aparente se houver lacunas nas hitboxes, como entre as pernas. Na maioria dos casos, o Bullet Magnetism \u00e9 equilibrado com base na dist\u00e2ncia do ret\u00edculo \u00e0s caixas de acerto do jogador real, calculando um pouco de uma \u00e1rea de perd\u00e3o.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-reticle-bloom\">Flor de ret\u00edculo<\/h2>\n\n<p>Se voc\u00ea n\u00e3o sabe o que \u00e9 bloom por acaso, bloom \u00e9 a descri\u00e7\u00e3o para quando o ret\u00edculo cresce um pouco maior com tiros r\u00e1pidos cont\u00ednuos. As armas com flor ter\u00e3o dificuldade em acertar tiros cont\u00ednuos de alcance, a menos que sejam disparadas em rajadas atrasadas.<\/p>\n\n<p>Embora as armas compartilhem o magnetismo como uma mec\u00e2nica de jogo central, algumas poucas em Halo Infinite floresceram. O Battle Rifle, por exemplo, n\u00e3o tem nenhum. Enquanto o SideKick, Commando e Assault Rifle lutam para disparar continuamente sem florescer, tornando-se uma grande desvantagem. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-the-problem-with-halo-infinite-s-sniper-rifle\">O problema com o rifle de precis\u00e3o de Halo Infinite<\/h2>\n\n<p>O Sniper Rifle, uma arma amada em todos os jogos de halo, pela primeira vez, saiu de cena por causa da assist\u00eancia de mira em Halo Infinite. Ao usar um mouse e teclado, \u00e9 mais dif\u00edcil mirar com o Sniper Rifle.<\/p>\n\n<p>Presumivelmente, um bug atualmente na primeira temporada; n\u00e3o mirar com o rifle de precis\u00e3o no mouse e no teclado enquanto um inimigo est\u00e1 metralhando for\u00e7ar\u00e1 a ret\u00edcula a se afastar levemente do inimigo. Nesta discuss\u00e3o, os jogadores geralmente acham que o <a href=\"https:\/\/fpschampion.com\/pt-br\/como-encontrar-e-usar-o-halo-infinite-stalker-rifle\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stalker Rifle<\/a> \u00e9 o melhor rifle de precis\u00e3o. Isso ocorre devido a essa desvantagem inconsistente.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-jumping-and-how-it-affects-aim-assist-in-halo-infinite\">Pular e como isso afeta a assist\u00eancia \u00e0 mira no Halo Infinite<\/h2>\n\n<p>Alguns jogadores relatam que o rastreamento nos controladores piora com qualquer arma durante o salto. Isso causou um novo surto de jogadores pulando agachados em vez de pular durante as lutas. Mesmo em um controlador onde o Aim Assist \u00e9 melhor, o ret\u00edculo pode parar de grudar em um alvo com muito movimento.<\/p>\n\n<p>Ficar parado parece ser ainda menos \u00fatil. O Aim Assist \u00e0s vezes nem funciona a menos que voc\u00ea esteja se movendo, sendo isso um problema em ambas as formas de controle. Embora o rastreamento esteja quebrado, o controlador ainda tem claramente a vantagem. Parece quase como se eles tivessem nerfado a mira com for\u00e7a.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-our-advice-use-a-controller-for-now\">Nosso conselho: use um controlador por enquanto<\/h2>\n\n<p>Essa discuss\u00e3o pode nunca ter ocorrido se a \u00fanica op\u00e7\u00e3o fosse um controlador. Jogadores de eSport, streamers e qualquer pessoa com experi\u00eancia podem concordar que o controle \u00e9 mais forte, apesar do objetivo geral ser inconsistente e quebrar \u00e0s vezes. O teclado e o mouse devem ser ajustados de acordo com o controlador, para que n\u00e3o caiam no esquecimento. Seria melhor buffar os jogadores de teclado do que nerf aim assist para jogadores de controle.<\/p>\n\n<p>A implementa\u00e7\u00e3o de um ac\u00famulo lento para ter o ret\u00edculo no alvo como o Halo 3 ajudaria a trazer o poder necess\u00e1rio de que os jogadores de PC precisam. Em vez de atenuar a experi\u00eancia dos jogadores controladores para equilibrar o Aim Assist, os usu\u00e1rios do teclado devem ter alguma margem de manobra e serem tratados com o mesmo valor.<\/p>\n\n<p>Os profissionais de mouse e teclado devem ter sua interface aprimorada e a ader\u00eancia ao alvo deve ser mais consistente e n\u00e3o quebrar. Como um lan\u00e7amento relativamente novo, o Halo Infinite ainda tem muitos problemas. No entanto, se for dado algum tempo, este jogo pode se tornar um dos melhores, assim como a trilogia Halo original. Este jogo \u00e9 um diamante bruto. Precisa de mais polimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde o lan\u00e7amento do jogo, o Aim Assist em Halo Infinite tem sido um t\u00f3pico de discuss\u00e3o. Ao longo da vida de Halo, a franquia sempre se concentrou em programar os jogos especificamente para controladores. Isso permitiu que todos os jogadores estivessem em p\u00e9 de igualdade. Desde o lan\u00e7amento da Master Chief Collection no PC,<\/p>\n","protected":false},"author":6,"featured_media":13083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[588],"tags":[1549],"platform":[631,671,672],"class_list":{"0":"post-32028","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-artigo-em-destaque","8":"tag-halo-infinito","9":"platform-windowsos-pt-br","10":"platform-xbox-one-pt-br","11":"platform-xbox-series-x-s-pt-br"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eles Nerf Aim Assist em Halo Infinite? | FPS Champion<\/title>\n<meta name=\"description\" content=\"Halo sempre foi o primeiro jogo do controlador. Com um novo foco no teclado e mouse, eles nerf aim assist em Halo Infinite?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eles Nerf Aim Assist em Halo Infinite?\" \/>\n<meta property=\"og:description\" content=\"Halo sempre foi o primeiro jogo do controlador. Com um novo foco no teclado e mouse, eles nerf aim assist em Halo Infinite?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T05:16:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T06:03:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Halo-Aiming-Rifle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Eles Nerf Aim Assist em Halo Infinite?\",\"datePublished\":\"2022-04-08T05:16:04+00:00\",\"dateModified\":\"2023-06-04T06:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/\"},\"wordCount\":1463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Halo-Aiming-Rifle.jpg\",\"keywords\":[\"halo infinito\"],\"articleSection\":[\"Artigo em Destaque\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/\",\"name\":\"Eles Nerf Aim Assist em Halo Infinite? | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Halo-Aiming-Rifle.jpg\",\"datePublished\":\"2022-04-08T05:16:04+00:00\",\"dateModified\":\"2023-06-04T06:03:44+00:00\",\"description\":\"Halo sempre foi o primeiro jogo do controlador. Com um novo foco no teclado e mouse, eles nerf aim assist em Halo Infinite?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Halo-Aiming-Rifle.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Halo-Aiming-Rifle.jpg\",\"width\":1600,\"height\":900,\"caption\":\"Source: halowaypoint.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/eles-nerf-aim-assist-em-halo-infinite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eles Nerf Aim Assist em Halo Infinite?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eles Nerf Aim Assist em Halo Infinite? | FPS Champion","description":"Halo sempre foi o primeiro jogo do controlador. Com um novo foco no teclado e mouse, eles nerf aim assist em Halo Infinite?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/","og_locale":"pt_BR","og_type":"article","og_title":"Eles Nerf Aim Assist em Halo Infinite?","og_description":"Halo sempre foi o primeiro jogo do controlador. Com um novo foco no teclado e mouse, eles nerf aim assist em Halo Infinite?","og_url":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/","og_site_name":"FPS Champion","article_published_time":"2022-04-08T05:16:04+00:00","article_modified_time":"2023-06-04T06:03:44+00:00","og_image":[{"width":1600,"height":900,"type":"image\/jpeg","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Halo-Aiming-Rifle.jpg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Eles Nerf Aim Assist em Halo Infinite?","datePublished":"2022-04-08T05:16:04+00:00","dateModified":"2023-06-04T06:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/"},"wordCount":1463,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Halo-Aiming-Rifle.jpg","keywords":["halo infinito"],"articleSection":["Artigo em Destaque"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/","url":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/","name":"Eles Nerf Aim Assist em Halo Infinite? | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Halo-Aiming-Rifle.jpg","datePublished":"2022-04-08T05:16:04+00:00","dateModified":"2023-06-04T06:03:44+00:00","description":"Halo sempre foi o primeiro jogo do controlador. Com um novo foco no teclado e mouse, eles nerf aim assist em Halo Infinite?","breadcrumb":{"@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Halo-Aiming-Rifle.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Halo-Aiming-Rifle.jpg","width":1600,"height":900,"caption":"Source: halowaypoint.com"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Eles Nerf Aim Assist em Halo Infinite?"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/pt-br\/#website","url":"https:\/\/fpschampion.com\/pt-br\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/pt-br\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/pt-br\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/comments?post=32028"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32028\/revisions"}],"predecessor-version":[{"id":32033,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/32028\/revisions\/32033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media\/13083"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media?parent=32028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/categories?post=32028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/tags?post=32028"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/platform?post=32028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}