{"id":31965,"date":"2022-04-14T04:43:15","date_gmt":"2022-04-14T04:43:15","guid":{"rendered":"https:\/\/fpschampion.com\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/"},"modified":"2023-06-04T06:03:15","modified_gmt":"2023-06-04T06:03:15","slug":"tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/","title":{"rendered":"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection"},"content":{"rendered":"\n<p>Para o choque e admira\u00e7\u00e3o da comunidade Halo, 343 deu a Halo MCC uma grande atualiza\u00e7\u00e3o com a Atualiza\u00e7\u00e3o Floodfight. Muitos n\u00e3o esperavam esta atualiza\u00e7\u00e3o, especialmente porque o Halo Infinite est\u00e1 programado para sua segunda temporada no in\u00edcio de maio. Embora esta atualiza\u00e7\u00e3o tenha sido sugerida para adicionar mais conte\u00fado novo para tiroteio ODST, este patch tamb\u00e9m trouxe muitas mudan\u00e7as adicionais.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-the-flood-returns\">A enchente retorna<\/h2>\n\n<p>O foco principal desta atualiza\u00e7\u00e3o \u00e9 derivado do modo de jogo Firefight baseado em onda do Halo ODST. Todas as diferentes formas do Flood chegaram ao Firefight, junto com algumas novas condi\u00e7\u00f5es e mec\u00e2nicas nunca inclu\u00eddas no lan\u00e7amento original do jogo. O civil infectado, ODST e Elite Major foram recentemente introduzidos neste modo. O Elite Major foi trazido de volta enquanto ostentava sua ic\u00f4nica armadura vermelha e escudos de energia.<\/p>\n\n<p>Junto com esses inimigos adicionais, jogadores ODST mortos podem ser infectados e ressuscitados pelo Flood pela primeira vez na hist\u00f3ria do Halo. Todos os jogadores infectados retornam do t\u00famulo com suas armas anteriores, tornando-os uma amea\u00e7a extra poderosa se voc\u00ea tivesse algo parecido com um Rocket Launcher quando morrer. Essas novas ondas de inunda\u00e7\u00e3o tamb\u00e9m afetam o pr\u00f3prio mapa sempre que voc\u00ea entra em uma.<\/p>\n\n<p>The Flood aparece com uma densa n\u00e9voa verde que torna os momentos mais assustadores e atmosf\u00e9ricos como as miss\u00f5es de campanha anteriores. Nesta atualiza\u00e7\u00e3o &#8220;Floodfight&#8221; para Halo, o Flood ainda traz perigos \u00fanicos, como Flood Stalkers e caindo do c\u00e9u com Flood Dispersal Pods. Pela primeira vez desde Halo 2, o Flood pode controlar os ve\u00edculos novamente, al\u00e9m de ser capaz de manejar torres junto com v\u00e1rias anima\u00e7\u00f5es rec\u00e9m-adicionadas.<\/p>\n\n<h2 class=\"wp-block-heading\">Atualiza\u00e7\u00f5es do jogador chegando nesta atualiza\u00e7\u00e3o da cole\u00e7\u00e3o Halo Master Chief<\/h2>\n\n<p>O Flood n\u00e3o \u00e9 o \u00fanico a receber novos recursos; houve algumas mudan\u00e7as adicionadas para os jogadores. Pela primeira vez, os jogadores poder\u00e3o usar a Energy Sword e o Sentinel Beam no ODST. Os jogadores agora podem usar o mapa VISR para ver os locais inimigos, mesmo enquanto esperam para reaparecer. Os Flood n\u00e3o s\u00e3o os \u00fanicos adicionados ao Firefight; Elites Inimigos podem ser encontrados nas novas ondas variantes.<\/p>\n\n<p>Os jogadores podem obter &#8220;Boons&#8221; em diferentes mapas, como racks de armas contendo rifles de batalha e rifles de assalto que n\u00e3o foram inclu\u00eddos no lan\u00e7amento original de Halo 3: ODST. Alguns mapas incluem lan\u00e7a-chamas, fuzileiros navais e oficiais do NMPD para ajudar a combater o Flood. Em miss\u00f5es noturnas, os Elites aliados aparecem por meio de pods de inser\u00e7\u00e3o para ajud\u00e1-lo contra o Flood.<\/p>\n\n<p>Um punhado de corre\u00e7\u00f5es e melhorias tamb\u00e9m foram importadas de volta para o Halo: Reach. Uma mudan\u00e7a not\u00e1vel \u00e9 que fuzileiros navais amig\u00e1veis \u200b\u200bna Instala\u00e7\u00e3o 04 agora podem ser expulsos de ve\u00edculos e voc\u00ea pode trocar armas com eles, assim como na campanha.<\/p>\n\n<h2 class=\"wp-block-heading\">Personaliza\u00e7\u00e3o da campanha Halo 4 na atualiza\u00e7\u00e3o Floodfight para Halo TMCC<\/h2>\n\n<p>Uma mudan\u00e7a pequena, mas bem-vinda, \u00e9 a personaliza\u00e7\u00e3o de skin adicional sendo adicionada \u00e0 campanha de Halo 4. As skins que voc\u00ea ganhou por meio dos passes de temporada gratuitos do Halo MCC agora podem ser ativadas em miss\u00f5es de campanha. No entanto, os jogadores ainda aparecer\u00e3o como Master Chief e n\u00e3o usar\u00e3o armaduras personalizadas, visores ou efeitos de armadura como a campanha de Halo: Reach.<\/p>\n\n<h2 class=\"wp-block-heading\">Novos Skulls para Halo 2: Anniversary, Halo 3 e Halo 3: ODST chegando na atualiza\u00e7\u00e3o Floodfight<\/h2>\n\n<p>O Cr\u00e2nio de Acrofobia que foi adicionado anteriormente ao Halo 3 agora est\u00e1 dispon\u00edvel no Halo 2: Anniversary, fazendo com que os jogadores n\u00e3o precisem mais de ferramentas de modifica\u00e7\u00e3o para ativar esse efeito. Halo 3 e ODST receberam caveiras exclusivas apenas de Halo: Combat Evolved Anniversary e Halo 2 Anniversary. A lista de caveiras \u00e9:<\/p>\n\n<ul class=\"wp-block-list\"><li>Raiva \u2013 Inimigos disparam suas armas mais r\u00e1pido e com mais frequ\u00eancia<\/li><li>Bandana \u2013 Muni\u00e7\u00e3o infinita<\/li><li>Bonded Pair \u2013 Co-op skull: Quando um jogador morre, o outro jogador recebe um grande aumento de dano que dura um tempo<\/li><li>Boom \u2013 Aumenta o raio da explos\u00e3o x2<\/li><li>Tapa-olho \u2013 Recursos de mira autom\u00e1tica desativados para todas as armas<\/li><li>Estrangeiro &#8211; Os jogadores n\u00e3o podem pegar ou usar armas de fac\u00e7\u00f5es opostas<\/li><li>Fantasma \u2013 IA n\u00e3o se esquiva mais de ataques<\/li><li>Jacked \u2013 Os jogadores s\u00f3 podem entrar em ve\u00edculos terrestres embarcando<\/li><li>Mau funcionamento \u2013 Toda vez que voc\u00ea reaparece, um elemento aleat\u00f3rio do seu HUD \u00e9 desativado<\/li><li>Master Blaster \u2013 Co-op skull: Os escudos de um jogador recarregam at\u00e9 o n\u00edvel de overshield e s\u00f3 podem usar corpo a corpo enquanto o segundo jogador n\u00e3o tem escudos e tem muni\u00e7\u00e3o infinita. Os pap\u00e9is mudam ap\u00f3s uma s\u00e9rie de mortes inimigas<\/li><li>Pinata \u2013 Socar inimigos faz com que joguem uma granada<\/li><li>Recess\u00e3o \u2013 Cada tiro vale o dobro da muni\u00e7\u00e3o<\/li><li>Ent\u00e3o&#8230; Irritado&#8230; &#8211; Brutos enfurecidos explodem como granadas de fragmenta\u00e7\u00e3o se n\u00e3o forem despachados em segundos. Os valores de pontua\u00e7\u00e3o base do Brute s\u00e3o aumentados<\/li><li>Swarm \u2013 Ca\u00e7adores s\u00e3o muito mais fortes. Os valores de pontua\u00e7\u00e3o base do Ca\u00e7ador s\u00e3o aumentados.<\/li><li>Isso \u00e9 apenas&#8230; Errado \u2013 Aumentar a percep\u00e7\u00e3o do inimigo sobre o jogador<\/li><li>They Come Back \u2013 Flood Combat Forms gerados por <a href=\"https:\/\/fpschampion.com\/pt-br\/veremos-um-modo-de-jogo-multijogador-halo-infinite-infection\/\" target=\"_blank\" rel=\"noreferrer noopener\">Infection<\/a> Forms que reanimam um cad\u00e1ver s\u00e3o muito mais perigosos<\/li><\/ul>\n\n<p>Halo 3: ODST recebe todos os cr\u00e2nios mencionados acima Incluindo Acrofobia e excluindo &#8216;Eles Voltam&#8217;.<\/p>\n\n<h2 class=\"wp-block-heading\">51 novas medalhas de Halo 3<\/h2>\n\n<p>Halo 3 tamb\u00e9m ganhou 51 novas medalhas exclusivas para multiplayer. Essas medalhas j\u00e1 ser\u00e3o familiares aos f\u00e3s de Halo, pois s\u00e3o inspiradas em t\u00edtulos posteriores de Halo. Se voc\u00ea deseja continuar vendo apenas as medalhas tradicionais do Halo 3, essas medalhas extras podem ser desativadas no menu de configura\u00e7\u00f5es. A lista de novas medalhas multiplayer chegando na atualiza\u00e7\u00e3o Floodfight para Halo Master Chief Collection \u00e9:<\/p>\n\n<ol class=\"wp-block-list\"><li>Headshot: Mate um oponente atirando na cabe\u00e7a dele.<\/li><li>Assist: Ajude um jogador a conseguir uma morte.<\/li><li>Vingan\u00e7a: Mate o oponente respons\u00e1vel por sua \u00faltima morte.<\/li><li>Matar: Matar um oponente (aplica-se apenas quando nenhuma outra medalha de morte \u00e9 concedida).<\/li><li>Vingador: Mate um oponente que recentemente matou seu companheiro de equipe.<\/li><li>Comeback Kill: Consiga uma morte depois de morrer 3 vezes seguidas.<\/li><li>Reload This: Mate um oponente que est\u00e1 recarregando.<\/li><li>Grenade Kill: Mate um oponente usando uma Frag Grenade ou Pulse Grenade<\/li><li>Protetor: Salve um companheiro de equipe matando seu atacante.<\/li><li>Close Call: Mate um oponente enquanto sua sa\u00fade est\u00e1 baixa e sobreviva.<\/li><li>Rocket Kill: Mate um oponente usando um Rocket Launcher.<\/li><li>Plasma Kill: Mate um oponente usando uma Plasma Grenade.<\/li><li>Vehicle Kill: Mate um oponente com um ve\u00edculo. Isso inclui a Torre Sombria e a Torre Elefante. Isso \u00e9 para mortes com armas de ve\u00edculos, n\u00e3o respingos.<\/li><li>Ve\u00edculo Destru\u00eddo: Destrua um ve\u00edculo inimigo.<\/li><li>Sword Kill: Mate um oponente usando uma Espada de Energia<\/li><li>First Strike: Ganhe a primeira morte da partida.<\/li><li>Vehicle Destroy Assist: Ajude a destruir um ve\u00edculo.<\/li><li>Supercombine: Mate um oponente usando um Needler.<\/li><li>Instant\u00e2neo: Mate um oponente com um rifle de precis\u00e3o sem aumentar o zoom.<\/li><li>Last Strike: Ganhe a morte final.<\/li><li>Flag Taken: Pegue a bandeira de um inimigo de sua base.<\/li><li>Hill Offense: Mate um oponente segurando uma colina.<\/li><li>Hill Defense: Mate um oponente enquanto segura uma colina.<\/li><li>Ball Carrier Kill: Mate um oponente segurando o Oddball.<\/li><li>Flag Returned: Devolva a bandeira do seu time.<\/li><li>First Touch: Seja o primeiro jogador a pegar o Oddball.<\/li><li>Fuel Rod Cannon Kill: Mate um oponente usando um Fuel Rod Cannon.<\/li><li>Primeiro Ponto: Seja o primeiro jogador a ganhar um ponto em uma colina.<\/li><li>Hammer Kill: Mate um oponente usando um Gravity Hammer.<\/li><li>Inconceb\u00edvel: Mate 35 oponentes seguidos sem morrer.<\/li><li>Unfrigginbelievable: Mate 40 oponentes seguidos sem morrer.<\/li><li>Titular da bola: Segure o Oddball por 10 segundos.<\/li><li>Guarda-bola: Segure o Oddball por 20 segundos.<\/li><li>Ball Master: Segure o Oddball por 30 segundos.<\/li><li>Ball Hog: Segure o Oddball por 45 segundos.<\/li><li>Magic Hands: Segure o Oddball por 1 minuto.<\/li><li>Flag Runner: Capture 2 bandeiras em um jogo.<\/li><li>Flag Champion: Capture 3 bandeiras em um jogo.<\/li><li>Movimentos suaves: Consiga um Triple Kill com o exc\u00eantrico.<\/li><li>Dom\u00ednio da Colina: Segure e sobreviva na colina por toda a dura\u00e7\u00e3o.<\/li><li>Brute Shot Kill: Mate um oponente com um Brute Shot.<\/li><li>Sentinel Beam Kill: Mate um oponente com um Sentinel Beam.<\/li><li>Turret Kill: Mate um oponente com uma torre.<\/li><li>Territ\u00f3rio Capturado: Capturou um Territ\u00f3rio.<\/li><li>Territorial: Mate um oponente enquanto estiver em uma Zona de Territ\u00f3rio.<\/li><li>Triunvirato: capture 3 territ\u00f3rios diferentes durante uma partida.<\/li><li>Bomb Defense: Proteja a bomba inimiga matando um oponente pr\u00f3ximo a ela.<\/li><li>Bomba desativada: desarme a bomba.<\/li><li>Desarmado: Mate um oponente enquanto ele est\u00e1 armando a bomba.<\/li><li>Sabotador: Plante com sucesso 2 bombas que explodem durante uma partida.<\/li><li>Ambientalista: Mate um oponente com qualquer elemento din\u00e2mico no n\u00edvel.<\/li><\/ol>\n\n<h2 class=\"wp-block-heading\">Outras adi\u00e7\u00f5es chegando na atualiza\u00e7\u00e3o Floodfight Halo<\/h2>\n\n<p>O navegador de jogo personalizado para Halo MCC foi finalmente atualizado com um recurso de correspond\u00eancia r\u00e1pida. Al\u00e9m disso, todos os t\u00edtulos do Halo foram adicionados ao navegador, o que significa que todos os lobbies do Halo est\u00e3o finalmente acess\u00edveis a todos.<\/p>\n\n<p><strong>Artigo relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/eles-nerf-aim-assist-em-halo-infinite\/\" target=\"_blank\" rel=\"noreferrer noopener\">O Halo Infinite Asim Assist foi nerfado?<\/a><\/p>\n\n<p>As campanhas Halo 3 e Halo 3: ODST agora t\u00eam cross-play ativado. Ambos os jogadores no PC e no Xbox podem jogar ambas as campanhas online cooperativamente entre si.<\/p>\n\n<p>Halo 3: ODST Mod Tools foi lan\u00e7ado junto com esta atualiza\u00e7\u00e3o. As ferramentas mod podem ser baixadas no Steam. A 343 Industries planeja lan\u00e7ar ferramentas de mod para os t\u00edtulos restantes no MCC; em breve, todos os jogos Halo no MCC ter\u00e3o mods suportados.<\/p>\n\n<p>Por fim, muitos conte\u00fados cortados e in\u00e9ditos n\u00e3o chegaram \u00e0s temporadas anteriores do Halo MCC que o 343 ainda n\u00e3o lan\u00e7ou. Podemos esperar que atualiza\u00e7\u00f5es futuras tragam ainda mais personaliza\u00e7\u00f5es inesperadas para o jogo finalmente.<\/p>\n\n<p>Juntamente com todas essas mudan\u00e7as, v\u00e1rias atualiza\u00e7\u00f5es de interface do usu\u00e1rio e corre\u00e7\u00f5es de bugs foram adicionadas ao Halo MCC nesta atualiza\u00e7\u00e3o do Floodfight. A atualiza\u00e7\u00e3o mais recente do MCC \u00e9 uma conquista fant\u00e1stica para a 343 Industries, e a comunidade mal pode esperar por mais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para o choque e admira\u00e7\u00e3o da comunidade Halo, 343 deu a Halo MCC uma grande atualiza\u00e7\u00e3o com a Atualiza\u00e7\u00e3o Floodfight. Muitos n\u00e3o esperavam esta atualiza\u00e7\u00e3o, especialmente porque o Halo Infinite est\u00e1 programado para sua segunda temporada no in\u00edcio de maio. Embora esta atualiza\u00e7\u00e3o tenha sido sugerida para adicionar mais conte\u00fado novo para tiroteio ODST, este<\/p>\n","protected":false},"author":6,"featured_media":13131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1441],"tags":[1600],"platform":[631,671,672],"class_list":{"0":"post-31965","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"tag-areola","9":"platform-windowsos-pt-br","10":"platform-xbox-one-pt-br","11":"platform-xbox-series-x-s-pt-br"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: TMCC<\/title>\n<meta name=\"description\" content=\"A atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection trar\u00e1 um grande n\u00famero de melhorias e novos recursos para um jogo que j\u00e1 \u00e9 \u00f3timo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection\" \/>\n<meta property=\"og:description\" content=\"A atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection trar\u00e1 um grande n\u00famero de melhorias e novos recursos para um jogo que j\u00e1 \u00e9 \u00f3timo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-14T04:43:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T06:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection\",\"datePublished\":\"2022-04-14T04:43:15+00:00\",\"dateModified\":\"2023-06-04T06:03:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/\"},\"wordCount\":1742,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"keywords\":[\"ar\u00e9ola\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/\",\"name\":\"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: TMCC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"datePublished\":\"2022-04-14T04:43:15+00:00\",\"dateModified\":\"2023-06-04T06:03:15+00:00\",\"description\":\"A atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection trar\u00e1 um grande n\u00famero de melhorias e novos recursos para um jogo que j\u00e1 \u00e9 \u00f3timo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"width\":1600,\"height\":900,\"caption\":\"Source: halowaypoint.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: TMCC","description":"A atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection trar\u00e1 um grande n\u00famero de melhorias e novos recursos para um jogo que j\u00e1 \u00e9 \u00f3timo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/","og_locale":"pt_BR","og_type":"article","og_title":"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection","og_description":"A atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection trar\u00e1 um grande n\u00famero de melhorias e novos recursos para um jogo que j\u00e1 \u00e9 \u00f3timo!","og_url":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/","og_site_name":"FPS Champion","article_published_time":"2022-04-14T04:43:15+00:00","article_modified_time":"2023-06-04T06:03:15+00:00","og_image":[{"width":1600,"height":900,"type":"image\/jpeg","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection","datePublished":"2022-04-14T04:43:15+00:00","dateModified":"2023-06-04T06:03:15+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/"},"wordCount":1742,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","keywords":["ar\u00e9ola"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/","url":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/","name":"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: TMCC","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","datePublished":"2022-04-14T04:43:15+00:00","dateModified":"2023-06-04T06:03:15+00:00","description":"A atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection trar\u00e1 um grande n\u00famero de melhorias e novos recursos para um jogo que j\u00e1 \u00e9 \u00f3timo!","breadcrumb":{"@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","width":1600,"height":900,"caption":"Source: halowaypoint.com"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/pt-br\/tudo-o-que-voce-precisa-saber-sobre-a-atualizacao-floodfight-para-halo-the-master-chief-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Tudo o que voc\u00ea precisa saber sobre a atualiza\u00e7\u00e3o Floodfight para Halo: The Master Chief Collection"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/pt-br\/#website","url":"https:\/\/fpschampion.com\/pt-br\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/pt-br\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/pt-br\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/31965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/comments?post=31965"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/31965\/revisions"}],"predecessor-version":[{"id":31975,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/31965\/revisions\/31975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media\/13131"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media?parent=31965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/categories?post=31965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/tags?post=31965"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/platform?post=31965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}