{"id":30903,"date":"2022-08-27T17:46:21","date_gmt":"2022-08-27T17:46:21","guid":{"rendered":"https:\/\/fpschampion.com\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/"},"modified":"2023-06-04T05:53:21","modified_gmt":"2023-06-04T05:53:21","slug":"melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/","title":{"rendered":"Melhores armas e outras armas do Payday 2 (atualizado em 2023)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Payday 2 \u00e9 um jogo com toneladas e toneladas de conte\u00fado que sempre d\u00e1 aos jogadores coisas para fazer, conte\u00fado para desbloquear e muita divers\u00e3o sozinho ou com amigos. Payday 2 oferece aos jogadores um enorme arsenal com armas para todos os estilos de jogo, desde rifles de assalto, espingardas, franco-atiradores, armas de fogo akimbo, lan\u00e7adores, etc. Este artigo mostrar\u00e1 as melhores armas e outras armas do Payday 2 para ajud\u00e1-lo a ter sucesso em todos os seus assaltos.<\/p>\n\n<p class=\"wp-block-paragraph\">Em Payday 2, n\u00e3o existe meta arma ou loadout, mas algumas armas s\u00e3o consideradas as melhores pela comunidade porque s\u00e3o divertidas de usar ou extremamente \u00fateis com uma constru\u00e7\u00e3o espec\u00edfica. Aqui ser\u00e3o abordadas algumas das armas de fogo consideradas as melhores do jogo. Aconselhamos vivamente os jogadores a irem ao arsenal e experimentarem cada arma por si pr\u00f3prios e decidirem qual \u00e9 a sua favorita.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-overview-of-the-best-guns-in-payday-2-in-2023\">Vis\u00e3o geral das melhores armas em Payday 2 em 2023<\/h2>\n\n<p class=\"wp-block-paragraph\">A prefer\u00eancia por uma arma em particular neste jogo pode ser subjetiva, j\u00e1 que todas funcionam muito bem em sua \u00e1rea, um China Puff pode n\u00e3o ser a melhor arma para uma constru\u00e7\u00e3o Stealth, mas pode ser adequada para uma Stoic. Lembre-se de que algumas das melhores armas e outras armas do Payday 2 est\u00e3o por tr\u00e1s do DLC, que os jogadores precisam pagar para ter acesso a elas. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-top-10-guns-in-payday-2\">Top 10 armas em Payday 2<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-1-car-4-rifle\">1. Rifle CAR-4<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/car-4-rifle-1024x565.png\" alt=\"A arma CAR-4 em Payday 2 &#xE9; uma das melhores armas para escolher\" class=\"wp-image-6006\"\/><figcaption class=\"wp-element-caption\">A arma CAR-4 vem com o jogo base Payday 2.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">O CAR-4 \u00e9 o pau para toda obra no Payday 2, pois \u00e9 altamente personaliz\u00e1vel e, basicamente, os jogadores podem us\u00e1-lo em diferentes cen\u00e1rios se modificados corretamente. Esta arma tende a ser usada para carregamentos furtivos que requerem bons n\u00edveis de oculta\u00e7\u00e3o. Lembre-se que alguns dos mods para esta arma podem trazer muitas desvantagens para eles.<\/p>\n\n<p class=\"wp-block-paragraph\">Confira nosso artigo sobre a <a href=\"https:\/\/fpschampion.com\/pt-br\/melhor-construcao-furtiva-do-payday-2-em-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">melhor constru\u00e7\u00e3o furtiva do Payday 2<\/a> que cobriu os melhores mods para um rifle CAR-4 bem escondido.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 30<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 150<\/li>\n\n\n\n<li>Cad\u00eancia de Tiro: 600<\/li>\n\n\n\n<li>Dano: 62<\/li>\n\n\n\n<li>Precis\u00e3o: 52<\/li>\n\n\n\n<li>Estabilidade: 60<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 20<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-2-buzzsaw-42-light-machine-gun\">2. Metralhadora Leve Buzzsaw 42<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/buzzsaw-weapon-Payday-2-1024x566.png\" alt=\"metralhadora leve no dia de pagamento 2\" class=\"wp-image-6008\"\/><figcaption class=\"wp-element-caption\">O Buzzsaw 42 faz parte do DLC Gage Historical Pack.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">A Buzzsaw 42 \u00e9 uma das melhores armas deste jogo devido \u00e0 sua rid\u00edcula cad\u00eancia de tiro de 1200. Esta cad\u00eancia de tiro torna esta metralhadora leve a arma mais r\u00e1pida com o dano mais severo do jogo, e derreter\u00e1 inimigos pesados que ousarem cruzar seu caminho. Lembre-se de que esta arma foi projetada para combates corpo a corpo em Payday 2. Pode ser dif\u00edcil de usar em dist\u00e2ncias maiores devido \u00e0 queda de dano e alto recuo. <\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-1\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 150<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 450<\/li>\n\n\n\n<li>Cad\u00eancia de Tiro: 1200<\/li>\n\n\n\n<li>Dano: 80<\/li>\n\n\n\n<li>Precis\u00e3o: 56<\/li>\n\n\n\n<li>Estabilidade: 28<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 1<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-3-ksp-light-machine-gun-in-payday-2\">3. KSP Light Machine Gun em Payday 2<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"566\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-1024x566.png\" alt=\"KSP LMG\" class=\"wp-image-6009\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-1024x566.png 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-300x166.png 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-768x424.png 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-1536x849.png 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-150x83.png 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-450x249.png 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2-1200x663.png 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/KSP-Payday-2.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">O KSP faz parte do Gage Weapon Pack #02 DLC<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Como o Buzzsaw 42, esta metralhadora leve oferece uma alta cad\u00eancia de tiro de 909 e danos significativos. Se o KSP for modificado corretamente, a precis\u00e3o e o recuo podem ser significativamente melhorados e ter uma arma mortal de curto a m\u00e9dio alcance.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-2\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 200<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 400<\/li>\n\n\n\n<li>Cad\u00eancia de tiro: 909<\/li>\n\n\n\n<li>Dano: 80<\/li>\n\n\n\n<li>Precis\u00e3o: 56<\/li>\n\n\n\n<li>Estabilidade: 28<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 1<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Artigo relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/melhor-construcao-estoica-do-payday-2-em-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">A melhor compila\u00e7\u00e3o est\u00f3ica do Payday 2<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-4-akimbo-goliath-12g-shotguns\">4. Espingardas Akimbo Goliath 12G<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/goliath-12G-1024x566.png\" alt=\"Espingardas duplas Goliath\" class=\"wp-image-6011\"\/><figcaption class=\"wp-element-caption\">As armas Akimbo Goliath v\u00eam com Payday 2 e n\u00e3o requerem nenhum DLC para serem usadas.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">O Akimbo Goliath \u00e9 uma \u00f3tima arma no Payday 2 para derrubar inimigos de perto com alta precis\u00e3o e dano significativo. A comunidade do Payday 2 usa muito essas espingardas e elas n\u00e3o v\u00e3o decepcionar voc\u00ea em suas lutas corpo a corpo.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-3\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 12<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 72<\/li>\n\n\n\n<li>Cad\u00eancia de tiro: 333<\/li>\n\n\n\n<li>Dano:42<\/li>\n\n\n\n<li>Precis\u00e3o: 64<\/li>\n\n\n\n<li>Estabilidade: 8<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 13<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-5-brothers-grimm-12g-shotgun\">5. Espingarda Irm\u00e3os Grimm 12G<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"566\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-1024x566.png\" alt=\"espingardas duplas dos irm&#xE3;os grimm no dia de pagamento 2\" class=\"wp-image-6012\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-1024x566.png 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-300x166.png 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-768x424.png 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-1536x849.png 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-150x83.png 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-450x249.png 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm-1200x663.png 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/brothers-grimm.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">The Brothers Grimm vem com o jogo base.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">O Brothers Grimm tem estat\u00edsticas mais baixas que o Golias, mas compensa devido ao seu impulso que pode ser modificado para aumentar o dano. Al\u00e9m disso, este par de espingardas carrega mais muni\u00e7\u00e3o e oferece melhor estabilidade, alta propaga\u00e7\u00e3o e oculta\u00e7\u00e3o.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-4\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 16<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 96<\/li>\n\n\n\n<li>Cad\u00eancia de tiro: 333<\/li>\n\n\n\n<li>Dano: 18<\/li>\n\n\n\n<li>Precis\u00e3o: 20<\/li>\n\n\n\n<li>Estabilidade: 12<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 21<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-6-china-puff-40mm-grenade-launcher\">6. Lan\u00e7a-Granadas China Puff de 40mm<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/grenade-launcher-weapon-in-Payday-2-1024x568.png\" alt=\"Arma lan&#xE7;adora de granadas para jogadores do dia de pagamento 2\" class=\"wp-image-6013\"\/><figcaption class=\"wp-element-caption\">O China Puff faz parte do DLC Wolf Pack<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Por raz\u00f5es \u00f3bvias, o China Puff \u00e9 considerado um lan\u00e7ador de granadas e um dos secund\u00e1rios com danos mais graves. Esta arma do Payday 2 oferece excelente dano e precis\u00e3o; a \u00fanica desvantagem \u00e9 sua baixa muni\u00e7\u00e3o total. Este lan\u00e7ador de granadas ir\u00e1 ajud\u00e1-lo a tomar grandes grupos de inimigos rapidamente.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-5\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 3<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o Total: 6<\/li>\n\n\n\n<li>Cad\u00eancia de Tiro: 50<\/li>\n\n\n\n<li>Dano: 960<\/li>\n\n\n\n<li>Precis\u00e3o: 100<\/li>\n\n\n\n<li>Estabilidade: 96<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 18<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Artigo Relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/melhor-construcao-corpo-a-corpo-do-payday-2-em-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">A Melhor Constru\u00e7\u00e3o Corpo a Corpo do Dia de Pagamento 2<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-7-rpk-light-machine-gun-in-payday-2\">7. Metralhadora Leve RPK no Dia de Pagamento 2<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/rpk-payday-2-1024x566.png\" alt=\"RPK\" class=\"wp-image-6014\"\/><figcaption class=\"wp-element-caption\">A arma RPK faz parte do DLC #02 do Gage Weapon Pack de Payday 2.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">A RPK \u00e9 uma \u00f3tima metralhadora leve com menor taxa de tiro e precis\u00e3o, mas compensada com grande dano e a velocidade de recarga mais r\u00e1pida de sua categoria. A precis\u00e3o pode ser altamente aumentada com mods, deixando voc\u00ea com uma das armas mais mortais do Payday 2.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-6\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 100<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o Total: 300<\/li>\n\n\n\n<li>Cad\u00eancia de Tiro: 750<\/li>\n\n\n\n<li>Dano: 120<\/li>\n\n\n\n<li>Precis\u00e3o: 36<\/li>\n\n\n\n<li>Estabilidade: 8<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 5<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-8-galant-rifle\">8. Rifle Galant<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/galant-rifle-1024x566.png\" alt=\"espingarda M1 Garand\" class=\"wp-image-6015\"\/><figcaption class=\"wp-element-caption\">O Galant Rifle faz parte do jogo base e ser\u00e1 desbloqueado ap\u00f3s a miss\u00e3o secund\u00e1ria Rapid Retribution.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">O Galant Rifle, ou como todos sabem, o M1 Garand, tornou-se um item b\u00e1sico em jogos e filmes. Todos v\u00e3o reconhecer e ficar satisfeitos com o som dessa arma ejetando seu bloc clip e fazendo o famoso som &#8221;agarrado&#8221;. O Galant Rifle oferece alguns dos danos mais tremendos de sua classe e precis\u00e3o.  <\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-7\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 8<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 72<\/li>\n\n\n\n<li>Cad\u00eancia de Tiro: 600<\/li>\n\n\n\n<li>Dano: 160<\/li>\n\n\n\n<li>Precis\u00e3o: 92<\/li>\n\n\n\n<li>Estabilidade: 36<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 20<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-9-the-judge\">9. O Juiz<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"564\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-1024x564.png\" alt=\"Juiz espingarda pistola arma Payday 2\" class=\"wp-image-6016\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-1024x564.png 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-300x165.png 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-768x423.png 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-1536x846.png 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-150x83.png 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-450x248.png 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2-1200x661.png 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/The-Judge-Payday-2.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">O Juiz \u00e9 um item da comunidade desbloqueado ao ingressar no grupo Payday 2 Official no Steam.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Alguns consideram o Juiz a melhor arma secund\u00e1ria no Payday 2 devido \u00e0 sua letalidade por meio de alto dano, alta precis\u00e3o e oculta\u00e7\u00e3o. O Juiz \u00e9 a arma perfeita em emerg\u00eancias, pois permitir\u00e1 que voc\u00ea mate a maioria dos inimigos rapidamente.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-8\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 5<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 35<\/li>\n\n\n\n<li>Cad\u00eancia de Tiro: 500<\/li>\n\n\n\n<li>Dano: 155<\/li>\n\n\n\n<li>Precis\u00e3o: 60<\/li>\n\n\n\n<li>Estabilidade: 28<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 29<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Guia de constru\u00e7\u00e3o relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/melhor-payday-2-dodge-build-em-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">como concluir a melhor constru\u00e7\u00e3o de esquiva no dia de pagamento 2<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-10-union-5-56-weapon-in-payday-2\">10. Arma Union 5.56 no Dia de Pagamento 2<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"566\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-1024x566.png\" alt=\"Uni&#xE3;o 5,56 mm com luneta\" class=\"wp-image-6017\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-1024x566.png 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-300x166.png 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-768x424.png 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-1536x849.png 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-150x83.png 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-450x249.png 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2-1200x663.png 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/union-AR-payday-2.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">O Union 5.56 vem com o jogo base.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">O Union 5.56 \u00e9 o melhor rifle do jogo porque combina as melhores estat\u00edsticas de outros grandes rifles de assalto. Tem uma taxa de tiro incrivelmente alta, precis\u00e3o e estabilidade. Esta arma ser\u00e1 mortal em ambas as m\u00e3os de jogadores novos e experientes. A muni\u00e7\u00e3o para esta arma pode ser facilmente recuperada, mas tamb\u00e9m perdida rapidamente devido \u00e0 sua alta cad\u00eancia de tiro. O carregador com capacidade para 30 balas pode ser considerado o \u00fanico ponto negativo do Union 5.56.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-base-stats-9\">Estat\u00edsticas b\u00e1sicas<\/h4>\n\n<ul class=\"wp-block-list\">\n<li>Revista: 30<\/li>\n\n\n\n<li>Muni\u00e7\u00e3o total: 150<\/li>\n\n\n\n<li>Cad\u00eancia de tiro: 857<\/li>\n\n\n\n<li>Dano: 59<\/li>\n\n\n\n<li>Precis\u00e3o: 68<\/li>\n\n\n\n<li>Estabilidade: 68<\/li>\n\n\n\n<li>Oculta\u00e7\u00e3o: 20<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-wrapping-up-our-best-payday-2-guns-and-other-weapons-list\">Concluindo nossa melhor lista de armas e outras armas do Payday 2<\/h2>\n\n<p class=\"wp-block-paragraph\">Algumas armas no Payday 2 podem levar algum tempo para se acostumar, ou simplesmente encontrar a melhor maneira de us\u00e1-las com a melhor classe. Essas armas do Payday 2 s\u00e3o recomendadas e consideradas \u00f3timas em todos os cen\u00e1rios e n\u00e3o devem decepcion\u00e1-lo em nenhum assalto. Convidamos voc\u00ea a experimentar outras armas, fazer sua lista de favoritas e compartilhar conosco nos coment\u00e1rios.<\/p>\n\n<p class=\"wp-block-paragraph\">Sinta-se \u00e0 vontade para conferir outros guias em nosso site para o Payday 2. Se voc\u00ea \u00e9 um veterano, pode realmente gostar de expandir o jogo com nossa lista dos <a href=\"https:\/\/fpschampion.com\/pt-br\/5-dos-melhores-mods-do-payday-2-para-melhorar-sua-jogabilidade\/\" target=\"_blank\" rel=\"noreferrer noopener\">5 melhores mods do Payday 2<\/a> .<\/p>\n\n<p class=\"wp-block-paragraph\">Boa sorte, bom assalto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Payday 2 \u00e9 um jogo com toneladas e toneladas de conte\u00fado que sempre d\u00e1 aos jogadores coisas para fazer, conte\u00fado para desbloquear e muita divers\u00e3o sozinho ou com amigos. Payday 2 oferece aos jogadores um enorme arsenal com armas para todos os estilos de jogo, desde rifles de assalto, espingardas, franco-atiradores, armas de fogo akimbo,<\/p>\n","protected":false},"author":11,"featured_media":17143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[588],"tags":[1108],"platform":[915,669,670,631,671],"class_list":["post-30903","post","type-post","status-publish","format-standard","has-post-thumbnail","category-artigo-em-destaque","tag-payday-2-pt-br","platform-mac-os-pt-br","platform-playstation-4-pt-br","platform-trocar","platform-windowsos-pt-br","platform-xbox-one-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FPS Champion<\/title>\n<meta name=\"description\" content=\"Existem muitas armas e armas excelentes em Payday 2. Confira nossa lista dos 10 melhores para garantir que voc\u00ea saia por cima no seu pr\u00f3ximo assalto!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melhores armas e outras armas do Payday 2 (atualizado em 2023)\" \/>\n<meta property=\"og:description\" content=\"Existem muitas armas e armas excelentes em Payday 2. Confira nossa lista dos 10 melhores para garantir que voc\u00ea saia por cima no seu pr\u00f3ximo assalto!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-27T17:46:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T05:53:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Payday-2-Weapons.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Berumen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Berumen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/\"},\"author\":{\"name\":\"Andres Berumen\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/ce8e606ef4255323f19a32c6c4dd42e1\"},\"headline\":\"Melhores armas e outras armas do Payday 2 (atualizado em 2023)\",\"datePublished\":\"2022-08-27T17:46:21+00:00\",\"dateModified\":\"2023-06-04T05:53:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/\"},\"wordCount\":1309,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Payday-2-Weapons.jpeg\",\"keywords\":[\"Payday 2\"],\"articleSection\":[\"Artigo em Destaque\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Payday-2-Weapons.jpeg\",\"datePublished\":\"2022-08-27T17:46:21+00:00\",\"dateModified\":\"2023-06-04T05:53:21+00:00\",\"description\":\"Existem muitas armas e armas excelentes em Payday 2. Confira nossa lista dos 10 melhores para garantir que voc\u00ea saia por cima no seu pr\u00f3ximo assalto!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Payday-2-Weapons.jpeg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Payday-2-Weapons.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Melhores armas e outras armas do Payday 2 (atualizado em 2023)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/ce8e606ef4255323f19a32c6c4dd42e1\",\"name\":\"Andres Berumen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g\",\"caption\":\"Andres Berumen\"},\"description\":\"Andres Berumen is a passionate gamer, writer, and future game designer. Andres has participated in several gaming events such as semi-professional tournaments for Rainbow Six: Siege and one-life matches for games like Squad. His favorite food is tacos.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/author\\\/ramentheprofessional\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FPS Champion","description":"Existem muitas armas e armas excelentes em Payday 2. Confira nossa lista dos 10 melhores para garantir que voc\u00ea saia por cima no seu pr\u00f3ximo assalto!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/","og_locale":"pt_BR","og_type":"article","og_title":"Melhores armas e outras armas do Payday 2 (atualizado em 2023)","og_description":"Existem muitas armas e armas excelentes em Payday 2. Confira nossa lista dos 10 melhores para garantir que voc\u00ea saia por cima no seu pr\u00f3ximo assalto!","og_url":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/","og_site_name":"FPS Champion","article_published_time":"2022-08-27T17:46:21+00:00","article_modified_time":"2023-06-04T05:53:21+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Payday-2-Weapons.jpeg","type":"image\/jpeg"}],"author":"Andres Berumen","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Berumen","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/"},"author":{"name":"Andres Berumen","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/ce8e606ef4255323f19a32c6c4dd42e1"},"headline":"Melhores armas e outras armas do Payday 2 (atualizado em 2023)","datePublished":"2022-08-27T17:46:21+00:00","dateModified":"2023-06-04T05:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/"},"wordCount":1309,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Payday-2-Weapons.jpeg","keywords":["Payday 2"],"articleSection":["Artigo em Destaque"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/","url":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/","name":"","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Payday-2-Weapons.jpeg","datePublished":"2022-08-27T17:46:21+00:00","dateModified":"2023-06-04T05:53:21+00:00","description":"Existem muitas armas e armas excelentes em Payday 2. Confira nossa lista dos 10 melhores para garantir que voc\u00ea saia por cima no seu pr\u00f3ximo assalto!","breadcrumb":{"@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Payday-2-Weapons.jpeg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Payday-2-Weapons.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/pt-br\/melhores-armas-e-outras-armas-do-payday-2-atualizado-em-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Melhores armas e outras armas do Payday 2 (atualizado em 2023)"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/pt-br\/#website","url":"https:\/\/fpschampion.com\/pt-br\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/pt-br\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/ce8e606ef4255323f19a32c6c4dd42e1","name":"Andres Berumen","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g","caption":"Andres Berumen"},"description":"Andres Berumen is a passionate gamer, writer, and future game designer. Andres has participated in several gaming events such as semi-professional tournaments for Rainbow Six: Siege and one-life matches for games like Squad. His favorite food is tacos.","url":"https:\/\/fpschampion.com\/pt-br\/author\/ramentheprofessional\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/30903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/comments?post=30903"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/30903\/revisions"}],"predecessor-version":[{"id":30905,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/30903\/revisions\/30905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media\/17143"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media?parent=30903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/categories?post=30903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/tags?post=30903"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/platform?post=30903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}