{"id":30092,"date":"2023-02-02T04:44:12","date_gmt":"2023-02-02T04:44:12","guid":{"rendered":"https:\/\/fpschampion.com\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/"},"modified":"2023-06-04T05:44:22","modified_gmt":"2023-06-04T05:44:22","slug":"10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/","title":{"rendered":"10 \u00f3timas dicas e truques para iniciantes em Warhammer: Vermintide 2"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vermintide 2 \u00e9 o inovador matador de hordas corpo a corpo aclamado pela cr\u00edtica, que recentemente viu 10 milh\u00f5es de jogadores durante seu recente evento free-to-play antes do lan\u00e7amento de Darktide. Vermintide 2 se passa no universo Warhammer Fantasy e se concentra mais no corpo a corpo do que no corpo a corpo h\u00edbrido de Darktide e no combate \u00e0 dist\u00e2ncia com armas.<\/p>\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea \u00e9 um dos muitos novos jogadores experimentando Vermintide 2 pela primeira vez ou retornando para experimentar o fant\u00e1stico combate hack-and-slash, reunimos 10 das melhores dicas e truques de Vermintide 2 para ajud\u00e1-lo.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-1-learning-gear-power-progression\">1. Equipamento de Aprendizagem\/ Progress\u00e3o de Poder<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"427\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Gold-Chest-1024x427.jpg\" alt=\"Ba&#xFA; de ouro com pilhagem de videogame\" class=\"wp-image-8729\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Gold-Chest-1024x427.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Gold-Chest-300x125.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Gold-Chest-768x320.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Gold-Chest-150x63.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Gold-Chest-450x188.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Gold-Chest.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Quando voc\u00ea come\u00e7ar a jogar Vermintide 2, ou qualquer carreira\/classe, voc\u00ea ter\u00e1 um conjunto completo de armas e bugigangas b\u00e1sicas, cada uma com cinco poderes. O poder \u00e9 a principal maneira de o jogo aumentar seus danos, defesas e outras estat\u00edsticas.<\/p>\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode obter at\u00e9 300 de poder ao ter o poder m\u00e1ximo em todas as suas armas e bugigangas. Al\u00e9m disso, voc\u00ea tamb\u00e9m obt\u00e9m 350 de poder ao nivelar totalmente seu personagem at\u00e9 o n\u00edvel 35, mesmo que obtenha sua linha de talento final no n\u00edvel 30.<\/p>\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode obter melhores armas e materiais de cria\u00e7\u00e3o abrindo ba\u00fas ao completar miss\u00f5es, ganhar conquistas ou terminar uma corrida de Chaos Wastes. Se voc\u00ea estiver aumentando o n\u00edvel de um personagem pela primeira vez, recomendamos priorizar a obten\u00e7\u00e3o de equipamentos de n\u00edvel de poder mais alto, em vez de se preocupar com estat\u00edsticas at\u00e9 o final do jogo.<\/p>\n\n<p class=\"wp-block-paragraph\">Depois de atingir 300 de poder em todos os slots de itens, sugerimos que voc\u00ea se preocupe com estat\u00edsticas ou caracter\u00edsticas secund\u00e1rias. Quanto maior for o seu poder m\u00e9dio, maiores ser\u00e3o suas chances de melhores recompensas. Al\u00e9m disso, lembre-se de que seus ba\u00fas de recompensa melhorar\u00e3o se voc\u00ea jogar em dificuldades mais altas. Isso \u00e9 especialmente importante porque os ba\u00fas de Recrutas e Veteranos t\u00eam um limite de poder, por isso recomendamos passar para a dificuldade Campe\u00e3o assim que puder.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-2-temporary-health-is-vital-for-survival-in-vermintide-2\">2. A sa\u00fade tempor\u00e1ria \u00e9 vital para a sobreviv\u00eancia em Vermintide 2<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game-1024x575.jpg\" alt=\"sendo atingido por monstro inimigo no jogo vermintide 2\" class=\"wp-image-8730\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game-1024x575.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game-1200x674.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/being-hit-by-monster-enemy-in-vermintide-2-game.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Temp Health \u00e9 um dos principais recursos para se manter vivo em Vermintide 2. Temp Health atua como uma forma de recuperar HP perdido. Sempre que voc\u00ea sofre dano e perde um peda\u00e7o de sua sa\u00fade, voc\u00ea pode gerar lentamente Temp Health, que age como um escudo utilizando o talento de carreira de seu personagem. Vamos usar a carreira de Mercen\u00e1rio de Kruber como exemplo.<\/p>\n\n<p class=\"wp-block-paragraph\">A primeira linha de talentos para cada carreira \u00e9 semelhante entre si, e voc\u00ea deve considerar duas op\u00e7\u00f5es das tr\u00eas. Para o Mercenary, existe o Drillmaster, que d\u00e1 Temp Health por acertar v\u00e1rios inimigos em um \u00fanico golpe, ou o Mercenary&#8217;s Pride, que concede Temp Health ao acertar golpes mortais.<\/p>\n\n<p class=\"wp-block-paragraph\">Cada carreira tamb\u00e9m possui um talento que concede sa\u00fade tempor\u00e1ria ao usar um item de cura. Uma de nossas melhores dicas para jogadores iniciantes do Vermintide 2 \u00e9 nunca considerar a terceira op\u00e7\u00e3o. Seu primeiro talento \u00e9 vital para ganhar sa\u00fade tempor\u00e1ria em combate e, para Mercenary, escolher\u00edamos o Drillmaster porque est\u00e1 relacionado aos pontos fortes da carreira.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-3-blocking-parrying\">3. Bloquear e Aparar<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players-1024x575.jpg\" alt=\"bloqueio de inimigos com base na dica Vermintide 2 para novos jogadores\" class=\"wp-image-8731\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players-1024x575.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players-1200x674.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/blocking-enemies-based-on-Vermintide-2-tip-for-new-players.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Existem muitos inimigos perigosos em Vermintide 2. Esta pr\u00f3xima dica para iniciantes do Vermintide 2 ir\u00e1 ajud\u00e1-lo muito enquanto voc\u00ea est\u00e1 come\u00e7ando.<\/p>\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de adquirir Temp Health, bloquear e aparar s\u00e3o os principais benfeitores para se manter vivo em Vermintide 2. O n\u00famero de ataques que voc\u00ea pode Bloquear \u00e9 indicado pela quantidade de escudos de Vigor que voc\u00ea possui.<\/p>\n\n<p class=\"wp-block-paragraph\">Ganhar mais Vigor \u00e9 ben\u00e9fico, mas obter Redu\u00e7\u00e3o de Custo de Bloco \u00e9 muito mais importante. A redu\u00e7\u00e3o de custo do bloco permite que voc\u00ea receba mais golpes antes que seu escudo de Stamina quebre.<\/p>\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m vale a pena mencionar que os ataques pesados exigem mais Stamina para serem bloqueados, ent\u00e3o evitamos evit\u00e1-los, pois os ataques pesados s\u00e3o muito mais leg\u00edveis. Voc\u00ea tamb\u00e9m pode empurrar os inimigos para tr\u00e1s gastando um escudo de Stamina e seguindo com um ataque que pode variar em utilidade dependendo da arma. Ainda assim, independentemente da arma, voc\u00ea tamb\u00e9m deve implementar o empurr\u00e3o em seus combos de ataque.<\/p>\n\n<p class=\"wp-block-paragraph\">Aparar \u00e9 um pouco mais avan\u00e7ado e requer aprender os padr\u00f5es de ataque do inimigo. Para desviar, voc\u00ea deve iniciar sua anima\u00e7\u00e3o de bloqueio antes que o ataque do inimigo chegue. Se voc\u00ea aparar um ataque com sucesso, ouvir\u00e1 um pequeno choque met\u00e1lico de sua arma e o inimigo cambalear\u00e1 para tr\u00e1s. Voc\u00ea pode praticar aparar o Skaven menor entre as hordas, pois eles causam dano m\u00ednimo.<\/p>\n\n<p class=\"wp-block-paragraph\">Pratique esses m\u00e9todos com frequ\u00eancia. Eles pagar\u00e3o dividendos quando voc\u00ea atingir dificuldades mais altas e enfrentar inimigos mais especiais.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-4-dodging-is-living-in-vermintide-2\">4. Esquivar \u00e9 Viver em Vermintide 2<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-1024x575.jpg\" alt=\"Vermintide 2 Dwarf Jumping Cross the Screen\" class=\"wp-image-7048\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-1024x575.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-300x168.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-768x431.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-1536x862.jpg 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping-1200x674.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/10\/vermintide-2-dwarf-jumping.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Esquivar \u00e9 mais vital do que bloquear. Ele permite que voc\u00ea mude rapidamente para a esquerda, direita ou para tr\u00e1s para evitar ataques inimigos. A esquiva n\u00e3o apenas permitir\u00e1 que voc\u00ea evite danos iminentes, mas tamb\u00e9m poder\u00e1 se esquivar ao atacar, bloquear ou executar praticamente qualquer a\u00e7\u00e3o. A maioria dos jogadores mais novos subestima o qu\u00e3o vital \u00e9 a esquiva para salvar suas vidas &#8211; mas garantimos que esta dica do Vermintide 2 \u00e9 uma das principais diferen\u00e7as na conquista de dificuldades mais altas.<\/p>\n\n<p class=\"wp-block-paragraph\">Em combina\u00e7\u00e3o com esquiva e empurr\u00e3o, voc\u00ea deve se esquivar sempre que poss\u00edvel durante o combate. Mesmo enquanto se desvia para a multid\u00e3o de inimigos, esquivar-se ajudar\u00e1 voc\u00ea a evitar ataques por tr\u00e1s ou pela frente, mesmo que voc\u00ea n\u00e3o perceba.<\/p>\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m mencionamos anteriormente que \u00e9 melhor desviar de ataques pesados de seus inimigos, especialmente se eles forem Guerreiros do Caos, j\u00e1 que seu golpe a\u00e9reo pode cortar cinco escudos de Stamina. A esquiva tamb\u00e9m permite que voc\u00ea evite golpes de chefes ou monstruosidades, o que \u00e9 muito mais econ\u00f4mico do que tentar bloquear seus golpes.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-5-always-stay-together\">5. Sempre Fiquem Juntos<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together-1024x578.jpg\" alt=\"jogadores se unindo no jogo Vermintide 2 contra uma horda de zumbis como inimigos\" class=\"wp-image-8732\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together-1024x578.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together-768x434.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together-150x85.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together-450x254.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together-1200x678.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Vermintide-2-players-sticking-together.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">\u00c9 uma dica simples, mas eficaz: Vermintide 2 \u00e9 um matador de hordas baseado em equipe e, se algu\u00e9m for \u00e0 frente ou ficar para tr\u00e1s, poder\u00e1 ser sobrecarregado. Alguns veteranos de Vermintide 2 podem se gabar de que podem se controlar, mas, embora seja poss\u00edvel, todos acabam sendo pegos por um inesperado Gutter Runner.<\/p>\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m \u00e9 ben\u00e9fico ficar juntos porque certas carreiras podem fornecer buffs por ficarem pr\u00f3ximos uns dos outros. \u00c9 diferente do <a href=\"https:\/\/fpschampion.com\/pt-br\/o-que-e-coerencia-em-darktide-e-por-que-e-importante\/\" rel=\"noreferrer noopener\" target=\"_blank\">sistema Coherency de Darktide<\/a> , mas ficar com sua equipe ainda \u00e9 uma boa regra de ouro. Mesmo inimigos fracos podem se tornar opressores em n\u00fameros grandes o suficiente.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-6-share-your-healing-items\">6. Compartilhe seus itens de cura<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion-1024x575.jpg\" alt=\"Jogador segurando po&#xE7;&#xE3;o de cura\" class=\"wp-image-8733\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion-1024x575.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion-1200x674.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-holding-healing-potion.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Existem dois itens de cura em Vermintide 2: o Healing Draft e os suprimentos m\u00e9dicos. Ambos os suprimentos de cura curam voc\u00ea, mas t\u00eam vantagens diferentes.  <\/p>\n\n<p class=\"wp-block-paragraph\">O Healing Draft permite que voc\u00ea beba e cure enquanto estiver em movimento. Tamb\u00e9m pode ser passado para aliados com um slot aberto para itens de cura. Essas po\u00e7\u00f5es de sa\u00fade s\u00e3o uma \u00f3tima op\u00e7\u00e3o se voc\u00ea antecipar a necessidade de se curar no meio do combate ou se preferir permanecer m\u00f3vel. O Healing Draft cura 75 pontos de vida, substitui pontos de vida tempor\u00e1rios e limpa todos os ferimentos.<\/p>\n\n<p class=\"wp-block-paragraph\">Suprimentos m\u00e9dicos exigem que voc\u00ea fique parado para curar, mas tamb\u00e9m podem ser usados \u200b\u200bdiretamente em aliados. Suprimentos m\u00e9dicos restauram 80% da sa\u00fade perdida de um jogador enquanto substituem a sa\u00fade tempor\u00e1ria e limpam todos os ferimentos.<\/p>\n\n<p class=\"wp-block-paragraph\">Curar um aliado tamb\u00e9m limpar\u00e1 os pr\u00f3prios ferimentos, mas n\u00e3o restaurar\u00e1 os pontos de sa\u00fade, a menos que o jogador tenha uma caracter\u00edstica que o permita. A anima\u00e7\u00e3o de curar algu\u00e9m com suprimentos m\u00e9dicos sempre curar\u00e1 o alvo, mesmo que ele se afaste, desde que a anima\u00e7\u00e3o termine.<\/p>\n\n<p class=\"wp-block-paragraph\">Sempre escolheremos Suprimentos M\u00e9dicos em vez de uma Po\u00e7\u00e3o de Cura entre os dois itens de cura. Oferecemos esta dica do Vermintide 2 para voc\u00ea tamb\u00e9m porque pode fornecer mais cura quando usada em jogadores com menos sa\u00fade e pode curar aqueles que carregam Tomos.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-7-using-potions\">7. Usando Po\u00e7\u00f5es  <\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire-1024x576.jpg\" alt=\"Homem-rato explodindo com fogo verde\" class=\"wp-image-8734\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire-1024x576.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire-1200x675.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Rat-man-blasting-with-green-fire.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Tr\u00eas po\u00e7\u00f5es aumentam temporariamente sua efic\u00e1cia em combate. A Po\u00e7\u00e3o de Concentra\u00e7\u00e3o (roxo) aumenta sua taxa de recarga da Habilidade de Carreira por 10 segundos, permitindo que voc\u00ea recarregue sua Habilidade de Carreira rapidamente, com frequ\u00eancia suficiente para us\u00e1-la v\u00e1rias vezes antes que os efeitos desapare\u00e7am. Priorizar\u00edamos dar essa po\u00e7\u00e3o para carregadores que usam sua habilidade de carreira com frequ\u00eancia, como Battle Mage ou <a href=\"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/\" target=\"_blank\" rel=\"noreferrer noopener\">Waystalker<\/a> .<\/p>\n\n<p class=\"wp-block-paragraph\">A Po\u00e7\u00e3o de Velocidade (azul) aumenta suas velocidades de movimento e ataque por 10 segundos. Isso \u00e9 ben\u00e9fico para todas as carreiras, mas priorizamos dar isso a classes que prosperam em maior velocidade de ataque, como Slayers ou Witch Hunter Captains.<\/p>\n\n<p class=\"wp-block-paragraph\">Por fim, a Po\u00e7\u00e3o de For\u00e7a aumenta seu Poder por 10 segundos; este \u00e9 um impulso imediato ao seu poder, que influencia tanto o dano corpo a corpo quanto o dano \u00e0 dist\u00e2ncia. Normalmente, carreiras de impacto mais lento gostam dessa po\u00e7\u00e3o, mas n\u00f3s a recomendamos para todos.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-8-bombs-for-all\">8. Bombas para todos<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear-1024x575.jpg\" alt=\"dica de videogame para novos iniciantes no vermintide 2 para usar seus equipamentos\" class=\"wp-image-8735\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear-1024x575.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear-1200x674.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/video-game-tip-for-new-beginners-to-vermintide-2-to-use-their-gear.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">O quinto slot de equipamento \u00e9 onde os personagens podem segurar as bombas. Existem dois tipos de bombas em Vermintide: a bomba regular e a bomba incendi\u00e1ria. Esses explosivos s\u00e3o geralmente \u00fateis, mas cada um tem pontos fortes que os tornam mais adequados para determinadas situa\u00e7\u00f5es.<\/p>\n\n<p class=\"wp-block-paragraph\">As Bombas Regulares causam dano Stagger e perfurantes, tornando-as ideais para inimigos blindados e Elites. Usar bombas regulares contra chefes, elites, patrulhas ou lutas de alvo \u00fanico far\u00e1 com que recebam uma quantidade significativa de dano ou interrompam seus ataques. Combinado com o tra\u00e7o Shrapnel, eles podem ser mais f\u00e1ceis de matar depois.<\/p>\n\n<p class=\"wp-block-paragraph\">A Bomba Incendi\u00e1ria causa um pouco de atordoamento e dano, mas cobre a \u00e1rea ao redor do impacto inicial com fogo que causa dano ao longo do tempo. Voc\u00ea pode usar bombas incendi\u00e1rias para escalonar Elites e chefes, embora sejam menos eficazes do que bombas comuns. As bombas incendi\u00e1rias s\u00e3o ideais para eliminar hordas ou bloquear pontos de estrangulamento; isso \u00e0s vezes for\u00e7a os inimigos a contornar para evitar a mancha de fogo deixada para tr\u00e1s.<\/p>\n\n<p class=\"wp-block-paragraph\">Outra \u00f3tima dica profissional para iniciantes em Vermtinde 2: nunca subestime o poder das bombas neste jogo. Eles podem salvar sua vida ou tornar as lutas significativamente mais gerenci\u00e1veis. Sua efic\u00e1cia em combate s\u00f3 melhora depois que voc\u00ea v\u00ea seus pontos fortes em a\u00e7\u00e3o e pratica o arremesso.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-9-tips-to-surviving-with-tomes-and-grimoires-in-vermintide-2\">9. Dicas para sobreviver com Tomos e Grim\u00f3rios em Vermintide 2<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game-1024x576.jpg\" alt=\"Jogador com lan&#xE7;a enfrentando horda no jogo\" class=\"wp-image-8736\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game-1024x576.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game-1200x675.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Player-with-spear-facing-off-against-horde-in-game.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Tomos e Grim\u00f3rios s\u00e3o itens colecion\u00e1veis encontrados em todos os n\u00edveis de Vermintide 2. Eles est\u00e3o escondidos, \u00e0s vezes facilmente encontrados ou exigindo parkour. Ambos os colecion\u00e1veis concedem XP adicional e pontos para a &#8220;barra de saque&#8221;, que atualiza seu ba\u00fa de guerra ap\u00f3s a conclus\u00e3o da miss\u00e3o. <\/p>\n\n<p class=\"wp-block-paragraph\">Tome ocupa o terceiro slot, tamb\u00e9m conhecido como slot de cura. Cada miss\u00e3o tem tr\u00eas Tomos que podem ser encontrados, ent\u00e3o tr\u00eas em cada quatro jogadores devem ter um ao sair da miss\u00e3o. Ao carregar um Tomo, o acesso a um item de cura n\u00e3o est\u00e1 dispon\u00edvel e \u00e9 preciso trocar o Tomo por uma Po\u00e7\u00e3o de Cura ou Suprimentos M\u00e9dicos para se curar ou ser curado por um aliado com Suprimentos M\u00e9dicos.<\/p>\n\n<p class=\"wp-block-paragraph\">Grim\u00f3rios oferecem mais XP e contribui\u00e7\u00f5es para a barra de saque, mas tamb\u00e9m aplicam uma Maldi\u00e7\u00e3o a todos os membros do grupo. Esta Maldi\u00e7\u00e3o reduz o HP m\u00e1ximo de todos em 30%; se um segundo for pego, a redu\u00e7\u00e3o total de HP \u00e9 de 60%.<\/p>\n\n<p class=\"wp-block-paragraph\">Isso torna a miss\u00e3o mais desafiadora de ser conclu\u00edda, e os Grim\u00f3rios desaparecem do invent\u00e1rio de um jogador se ele morrer enquanto o segura. Certifique-se de proteger quem est\u00e1 segurando o Grimoire, ou ent\u00e3o voc\u00ea pode perder o b\u00f4nus de XP.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-10-learn-weapon-combos-the-most-important-vermintide-2-tip-for-beginners\">10. Aprenda Combos de Armas &#8211; A Dica Mais Importante do Vermintide 2 para Iniciantes<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons-1024x576.jpg\" alt=\"Melhores dicas e truques para derrotar o inimigo ogro em Vermintide 2 com armas corpo a corpo\" class=\"wp-image-8737\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons-1024x576.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons-1200x675.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Best-tips-and-tricks-for-defeating-ogre-enemy-in-Vermintide-2-with-melee-weapons.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Por fim, \u00e9 essencial aprender combos de armas. Comparado ao arsenal mais extenso de Darktide, Vermintide 2 tem uma variedade menor, por\u00e9m mais refinada, de armas corpo a corpo e rev\u00f3lveres. Cada arma corpo a corpo pode entrela\u00e7ar ataques leves e pesados para construir novas cadeias de combina\u00e7\u00e3o, em vez de apenas encadear ataques leves ou pesados.<\/p>\n\n<p class=\"wp-block-paragraph\">Poder\u00edamos falar sobre esse assunto por horas e demoraria ainda mais para mostrar uma d\u00fazia de armas. Portanto, destacaremos brevemente uma arma em Vermintide 2 para discutir seus combos e ilustrar o que queremos dizer nesta dica. A Espada Longa Bretoniana \u00e9 uma das melhores armas brancas do arsenal de Kruber.<\/p>\n\n<p class=\"wp-block-paragraph\">O Bretonnian Longsword tem ataques pesados incr\u00edveis que t\u00eam varreduras verticais ou amplas. Um dos muitos combos que podem ser usados para a espada \u00e9 para controle de multid\u00e3o, j\u00e1 que alguns movimentos atingem apenas um alvo em vez de cortar v\u00e1rios.<\/p>\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea deseja cortar com a Espada Longa Bretoniana, recomendamos iniciar o combo com o seguinte:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Dois Ataques Pesados<\/li>\n\n\n\n<li>Seguido por um ataque leve<\/li>\n\n\n\n<li>Um Ataque Pesado, <\/li>\n\n\n\n<li>Um Ataque Leve<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Repita o combo trocando um ataque pesado e um ataque leve.<\/p>\n\n<p class=\"wp-block-paragraph\">Voc\u00ea interromper\u00e1 o combo de clivagem se usar um ataque extra pesado ou leve. A arma precisa de dois ataques pesados e um leve para come\u00e7ar, ent\u00e3o alterne entre um ataque pesado e um leve. Pode parecer complicado no papel, mas coloc\u00e1-lo em pr\u00e1tica em um manequim-alvo ajudar\u00e1 voc\u00ea a come\u00e7ar a cortar hordas de homens-rato.<\/p>\n\n<p class=\"wp-block-paragraph\">Todas as armas t\u00eam algum combo que voc\u00ea pode encontrar ou tentar aprender sozinho; alguns s\u00e3o mais complicados do que outros. Recomendamos ler a dica de ferramenta da arma para descobrir seus pontos fortes e fun\u00e7\u00f5es antes de lev\u00e1-la para a batalha.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion-to-our-top-10-tips-and-tricks-for-vermintide-2-beginners\">Conclus\u00e3o de nossas 10 principais dicas e truques para iniciantes em Vermintide 2<\/h2>\n\n<p class=\"wp-block-paragraph\">Essa \u00e9 a nossa lista das melhores dicas e truques que voc\u00ea deve aprender no Vermintide 2 como iniciante. Esperan\u00e7osamente, essas dicas ir\u00e3o ajud\u00e1-lo em seu longo caminho de batalha contra as hordas de adoradores de Skaven e Chaos. Se voc\u00ea gostou da nossa lista e quer saber mais sobre o jogo, confira nossa <a href=\"https:\/\/fpschampion.com\/vermintide-2-class-tier-list\/\" target=\"_blank\" rel=\"noreferrer noopener\">lista de n\u00edveis para as melhores e piores classes de Vermintide 2<\/a> .<\/p>\n\n<p class=\"wp-block-paragraph\">Por enquanto, feliz ca\u00e7a!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vermintide 2 \u00e9 o inovador matador de hordas corpo a corpo aclamado pela cr\u00edtica, que recentemente viu 10 milh\u00f5es de jogadores durante seu recente evento free-to-play antes do lan\u00e7amento de Darktide. Vermintide 2 se passa no universo Warhammer Fantasy e se concentra mais no corpo a corpo do que no corpo a corpo h\u00edbrido de<\/p>\n","protected":false},"author":6,"featured_media":20627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[588],"tags":[1168,1167],"platform":[669,631,671,672],"class_list":["post-30092","post","type-post","status-publish","format-standard","has-post-thumbnail","category-artigo-em-destaque","tag-martelo-de-guerra","tag-vermintide-2-pt-br","platform-playstation-4-pt-br","platform-windowsos-pt-br","platform-xbox-one-pt-br","platform-xbox-series-x-s-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vermintide 2 - As 10 principais dicas e truques para iniciantes | FPS Champion<\/title>\n<meta name=\"description\" content=\"Se voc\u00ea est\u00e1 apenas come\u00e7ando no Vermintide 2 ou precisa de uma atualiza\u00e7\u00e3o, essas 10 dicas ir\u00e3o ajud\u00e1-lo a se levantar e come\u00e7ar a dominar o jogo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 \u00f3timas dicas e truques para iniciantes em Warhammer: Vermintide 2\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea est\u00e1 apenas come\u00e7ando no Vermintide 2 ou precisa de uma atualiza\u00e7\u00e3o, essas 10 dicas ir\u00e3o ajud\u00e1-lo a se levantar e come\u00e7ar a dominar o jogo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-02T04:44:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T05:44:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1576\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"10 \u00f3timas dicas e truques para iniciantes em Warhammer: Vermintide 2\",\"datePublished\":\"2023-02-02T04:44:12+00:00\",\"dateModified\":\"2023-06-04T05:44:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/\"},\"wordCount\":2430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg\",\"keywords\":[\"martelo de guerra\",\"Vermintide 2\"],\"articleSection\":[\"Artigo em Destaque\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/\",\"name\":\"Vermintide 2 - As 10 principais dicas e truques para iniciantes | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg\",\"datePublished\":\"2023-02-02T04:44:12+00:00\",\"dateModified\":\"2023-06-04T05:44:22+00:00\",\"description\":\"Se voc\u00ea est\u00e1 apenas come\u00e7ando no Vermintide 2 ou precisa de uma atualiza\u00e7\u00e3o, essas 10 dicas ir\u00e3o ajud\u00e1-lo a se levantar e come\u00e7ar a dominar o jogo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg\",\"width\":1576,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 \u00f3timas dicas e truques para iniciantes em Warhammer: Vermintide 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vermintide 2 - As 10 principais dicas e truques para iniciantes | FPS Champion","description":"Se voc\u00ea est\u00e1 apenas come\u00e7ando no Vermintide 2 ou precisa de uma atualiza\u00e7\u00e3o, essas 10 dicas ir\u00e3o ajud\u00e1-lo a se levantar e come\u00e7ar a dominar o jogo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/","og_locale":"pt_BR","og_type":"article","og_title":"10 \u00f3timas dicas e truques para iniciantes em Warhammer: Vermintide 2","og_description":"Se voc\u00ea est\u00e1 apenas come\u00e7ando no Vermintide 2 ou precisa de uma atualiza\u00e7\u00e3o, essas 10 dicas ir\u00e3o ajud\u00e1-lo a se levantar e come\u00e7ar a dominar o jogo.","og_url":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/","og_site_name":"FPS Champion","article_published_time":"2023-02-02T04:44:12+00:00","article_modified_time":"2023-06-04T05:44:22+00:00","og_image":[{"width":1576,"height":900,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg","type":"image\/jpeg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"10 \u00f3timas dicas e truques para iniciantes em Warhammer: Vermintide 2","datePublished":"2023-02-02T04:44:12+00:00","dateModified":"2023-06-04T05:44:22+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/"},"wordCount":2430,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg","keywords":["martelo de guerra","Vermintide 2"],"articleSection":["Artigo em Destaque"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/","url":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/","name":"Vermintide 2 - As 10 principais dicas e truques para iniciantes | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg","datePublished":"2023-02-02T04:44:12+00:00","dateModified":"2023-06-04T05:44:22+00:00","description":"Se voc\u00ea est\u00e1 apenas come\u00e7ando no Vermintide 2 ou precisa de uma atualiza\u00e7\u00e3o, essas 10 dicas ir\u00e3o ajud\u00e1-lo a se levantar e come\u00e7ar a dominar o jogo.","breadcrumb":{"@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/02\/Tips-to-Surviving-in-Vermintide-2-for-Beginners.jpg","width":1576,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/pt-br\/10-otimas-dicas-e-truques-para-iniciantes-em-warhammer-vermintide-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"10 \u00f3timas dicas e truques para iniciantes em Warhammer: Vermintide 2"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/pt-br\/#website","url":"https:\/\/fpschampion.com\/pt-br\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/pt-br\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/pt-br\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/30092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/comments?post=30092"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/30092\/revisions"}],"predecessor-version":[{"id":30102,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/30092\/revisions\/30102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media\/20627"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media?parent=30092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/categories?post=30092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/tags?post=30092"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/platform?post=30092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}