{"id":29615,"date":"2023-03-31T02:03:42","date_gmt":"2023-03-31T02:03:42","guid":{"rendered":"https:\/\/fpschampion.com\/warhammer-vermintide-2-waystalker-build-guide\/"},"modified":"2023-06-04T05:40:12","modified_gmt":"2023-06-04T05:40:12","slug":"warhammer-vermintide-2-waystalker-build-guide","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/","title":{"rendered":"Warhammer: Vermintide 2 Waystalker Build &amp; Guide"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Waystalker \u00e9 um personagem muito divertido em Vermintide 2, com habilidades excepcionais de arco e flecha e a capacidade de navegar no campo de batalha com agilidade e precis\u00e3o. Se voc\u00ea \u00e9 um jogador experiente procurando melhorar seu jogo ou um novato tentando encontrar seu caminho, este guia de constru\u00e7\u00e3o lhe dar\u00e1 uma vis\u00e3o aprofundada de tudo o que voc\u00ea precisa saber sobre a jogabilidade do Waystalker em Vermintide 2.<\/p>\n\n<p class=\"wp-block-paragraph\">De op\u00e7\u00f5es de habilidades e talentos a carregamentos de equipamentos e estrat\u00e9gias de combate, temos tudo o que voc\u00ea precisa. Ent\u00e3o pegue seu arco e vamos mergulhar juntos no mundo do Waystalker.<\/p>\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os Waystalkers em Vermintide 2?<\/h2>\n\n<p class=\"wp-block-paragraph\">Invadir as terras sagradas dos elfos \u00e9 um crime que tem um alto pre\u00e7o, muitas vezes resultando em uma flechada r\u00e1pida no pesco\u00e7o a mais de um quil\u00f4metro de dist\u00e2ncia. Waystalkers, tamb\u00e9m conhecidos como Waywatchers, guardam os caminhos ocultos de Athel Loren, permanecendo vigilantes contra todos os tipos de intrusos. Esses Guardi\u00f5es da Floresta s\u00e3o atiradores de elite talentosos entre os Elfos da Floresta, e Kerillian constantemente se gaba disso para seus aliados &#8220;mortais&#8221;.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-waystalker-skills-and-traits\">Habilidades e caracter\u00edsticas do Waystalker<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-career-skill-trueshot-volley\"><strong>Habilidade de carreira: Trueshot Volley<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Kerillian dispara uma saraivada de flechas que perseguem os inimigos em seu caminho.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Trueshot Volley \u00e9 uma das habilidades mais f\u00e1ceis de usar em Vermintide 2, mas precisa ser dominada um pouco. As pessoas costumam se referir ao Trueshot Volley como &#8220;o bot\u00e3o de matar gr\u00e1tis&#8221;, porque o voleio Kerillian atira em alvos. A saraivada de flechas buscar\u00e1 e percorrer\u00e1 o maior n\u00famero poss\u00edvel de alvos, priorizando tiros na cabe\u00e7a.<\/p>\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea mirar o Volley em um alvo, todas as flechas ir\u00e3o priorizar aquele alvo, permitindo que voc\u00ea d\u00ea um tiro em Chaos Warriors, ou tocar no bot\u00e3o matar\u00e1 meia horda.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-passive-abilities\"><strong>Habilidades Passivas<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Amaranthe: Kerillian regenera 3 pontos de vida a cada 10 segundos quando est\u00e1 com menos de metade dos pontos de vida.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Amaranthe n\u00e3o afeta drasticamente a constru\u00e7\u00e3o do Waystalker em Vermintide 2. No entanto, fornece muita capacidade de sobreviv\u00eancia ao longo do tempo, e alguns talentos aumentam a pot\u00eancia desse passivo.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Arrow-storm: Aumenta a capacidade de muni\u00e7\u00e3o em 100%<\/li>\n\n\n\n<li>Arco do Waywatcher: Alcance efetivo duplo para armas de longo alcance<\/li>\n\n\n\n<li>Asrai Vigil: Ganhe um recurso de zoom em armas de longo alcance. Vinculado \u00e0 arma especial por padr\u00e3o.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-all-melee-weapons-for-your-waystalker-build-in-vermintide-2\"><strong>Todas as armas corpo a corpo<\/strong> para o seu Waystalker Build em Vermintide 2<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Espada<\/li>\n\n\n\n<li>Adagas Duplas<\/li>\n\n\n\n<li>Espadas Duplas<\/li>\n\n\n\n<li>Espada e Adaga<\/li>\n\n\n\n<li>Gl\u00e1dio<\/li>\n\n\n\n<li>espada larga<\/li>\n\n\n\n<li>Lan\u00e7a \u00c9lfica<\/li>\n\n\n\n<li>Elven Axe (requer Back to Ubersreik DLC)<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-best-melee-weapons-for-waystalker\">Melhores armas corpo a corpo para Waystalker<\/h3>\n\n<p class=\"wp-block-paragraph\">Existem muitas \u00f3timas op\u00e7\u00f5es de armas corpo a corpo para o Waystalker, mas como elas s\u00e3o focadas em combate \u00e0 dist\u00e2ncia, usamos a Espada e a Adaga. A combina\u00e7\u00e3o Espada e Adaga oferece o melhor dos dois mundos, combinando os conjuntos de movimentos de Espadas Duplas e Adagas.<\/p>\n\n<p class=\"wp-block-paragraph\">Essa combina\u00e7\u00e3o de armas fornece um conjunto de movimentos muito s\u00f3lido, com \u00f3timos ataques leves para limpar a horda e um poderoso ataque X-slash e facada descendente que \u00e9 incr\u00edvel para lidar com armaduras. A espada e a adaga t\u00eam benef\u00edcios para todas as situa\u00e7\u00f5es, mas n\u00e3o superam outras op\u00e7\u00f5es.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Artigo Relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-grail-knight-build-and-guide\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vermintide 2 Grail Knight Build and Guide<\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-honorable-mentions-for-melee-weapons\">Men\u00e7\u00f5es Honrosas para Armas Brancas <\/h2>\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea quer uma arma incr\u00edvel para eliminar hordas, pegue as Espadas Duplas; no entanto, seu moveset \u00e9 um pouco carente de ataques de precis\u00e3o para alvos blindados. Como alternativa, use as adagas duplas se precisar de ainda mais poder de perfura\u00e7\u00e3o de armadura. Essas adagas s\u00e3o incrivelmente r\u00e1pidas e t\u00eam um excelente conjunto de movimentos para perfurar inimigos blindados, mas t\u00eam um alcance muito curto e baixa resist\u00eancia.<\/p>\n\n<p class=\"wp-block-paragraph\">Entre as espadas duplas e adagas, depende se voc\u00ea precisa eliminar hordas mais rapidamente ou eliminar elites ou especiais mais rapidamente. No entanto, pegue a espada e a adaga se quiser uma boa arma vers\u00e1til.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-all-ranged-weapons-for-waystalker\"><strong>Todas as armas de longo alcance para Waystalker<\/strong><\/h2>\n\n<ul class=\"wp-block-list\">\n<li>arco veloz<\/li>\n\n\n\n<li>arco longo<\/li>\n\n\n\n<li>Hagbane Shortbow<\/li>\n\n\n\n<li>Moonfire Bow (requer <a href=\"https:\/\/store.steampowered.com\/app\/1592630\/Warhammer_Vermintide_2__Forgotten_Relics_Pack\/\" target=\"_blank\" rel=\"noreferrer noopener\">o DLC Forgotten Relics<\/a> )<\/li>\n\n\n\n<li>Briar Javelin (requer o DLC Sister of the Thorn)<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-the-best-ranged-weapon-for-waystalker\">A melhor arma de longo alcance para Waystalker<\/h3>\n\n<p class=\"wp-block-paragraph\">O Waystalker \u00e9 o equivalente de Vermintide 2 a uma constru\u00e7\u00e3o de atirador. Mesmo ao escolher um arco de curto alcance, o Waystalker n\u00e3o sofre danos de queda t\u00e3o significativamente quanto outras carreiras. Ainda assim, o Longbow \u00e9 a melhor ferramenta do Waystalker. Ele tem uma boa quantidade de muni\u00e7\u00e3o gra\u00e7as ao passivo de Kerillian, e \u00e9 \u00f3timo de perto, mas tem um desempenho ainda melhor ao acertar alvos priorit\u00e1rios \u00e0 dist\u00e2ncia.<\/p>\n\n<p class=\"wp-block-paragraph\">O Longbow \u00e9 facilmente a melhor op\u00e7\u00e3o para todos os alcances, danos e versatilidade. Esta arma tamb\u00e9m \u00e9 not\u00e1vel contra alvos blindados, e sua falta de muni\u00e7\u00e3o \u00e9 compensada pela passiva do Waystalker. \u00c9 uma arma adequada para um Wood Elf.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-honorable-mentions-for-ranged-weapons\">Men\u00e7\u00f5es Honrosas para Armas de Longo Alcance<\/h3>\n\n<p class=\"wp-block-paragraph\">Embora o Briar Javelin seja mais adequado para a Handmaiden, n\u00e3o podemos negar que \u00e9 uma arma extremamente poderosa. O Briar Javelin tem quase tudo o que se precisa em uma arma de longo alcance: grande dano, capacidade de perfura\u00e7\u00e3o de armadura, capacidade de penetrar em v\u00e1rios inimigos e muni\u00e7\u00e3o ilimitada; no entanto, seu alcance \u00e9 limitado se n\u00e3o for cuidadosamente apontado.<\/p>\n\n<p class=\"wp-block-paragraph\">O Briar Javelin \u00e9 excepcionalmente forte, mas n\u00e3o combina bem com muitos talentos Waytalker. Al\u00e9m disso, a muni\u00e7\u00e3o extra passiva d\u00e1 apenas uma lan\u00e7a adicional, que \u00e9 mais adequada para outros arcos.<\/p>\n\n<h2 class=\"wp-block-heading\">Melhores talentos de Waystalker para sua constru\u00e7\u00e3o<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Talent-choices-for-your-Waystalker-1024x461.jpg\" alt=\"Escolhas de talentos para sua classe de personagem Waystalker no jogo\" class=\"wp-image-10398\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Talent-choices-for-your-Waystalker-1024x461.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Talent-choices-for-your-Waystalker-300x135.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Talent-choices-for-your-Waystalker-768x346.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Talent-choices-for-your-Waystalker-150x68.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Talent-choices-for-your-Waystalker-450x203.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Talent-choices-for-your-Waystalker.jpg 1193w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\">Talentos de n\u00edvel 5 para usar em seu Waystalker Build em Vermintide 2<\/h3>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Weavebond<\/td><td>Sede da Dr\u00edade<\/td><td>Ben\u00e7\u00e3o de Ariel<\/td><\/tr><tr><td>Golpes cr\u00edticos corpo a corpo e tiros na cabe\u00e7a concedem 2 de Sa\u00fade Tempor\u00e1ria. Headshots cr\u00edticos restauram o dobro.<\/td><td>Atingir v\u00e1rios inimigos com um golpe concede sa\u00fade tempor\u00e1ria com base no n\u00famero de alvos atingidos. M\u00e1ximo de 5 inimigos.<\/td><td>Curar-se com um Kit de Primeiros Socorros ou uma Po\u00e7\u00e3o de Cura tamb\u00e9m cura aliados pr\u00f3ximos em 20% de sua vida m\u00e1xima, removendo tamb\u00e9m quaisquer Ferimentos.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Para nossa constru\u00e7\u00e3o, usamos Weavebond, j\u00e1 que a Espada e a Adaga e o Arco Longo s\u00e3o f\u00e1ceis de acertar tiros na cabe\u00e7a. Se voc\u00ea quiser usar as Dual Swords ou outra arma como a Glaive, use Dryad&#8217;s Thirst.<\/p>\n\n<h3 class=\"wp-block-heading\">Talentos de n\u00edvel 10<\/h3>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>tiro de sangue<\/td><td>tiros serrilhados<\/td><td>Alacridade de Drakira<\/td><\/tr><tr><td>Depois de matar um inimigo com um ataque corpo a corpo, Kerillian dispara uma flecha adicional com seu pr\u00f3ximo ataque \u00e0 dist\u00e2ncia feito em 10 segundos. (A segunda flecha n\u00e3o consome muni\u00e7\u00e3o.)<\/td><td>Inimigos atingidos por ataques \u00e0 dist\u00e2ncia n\u00e3o venenosos sangram para causar dano extra. (Inst\u00e2ncias deste sangramento se acumulam)<\/td><td>Tiros na cabe\u00e7a \u00e0 dist\u00e2ncia aumentam a velocidade de ataque em 15% por 5 segundos.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Blood Shot \u00e9 o melhor talento para Waystalkers que gostam de misturar corpo a corpo com ataques \u00e0 dist\u00e2ncia. Depois de matar um \u00fanico inimigo, Blood Shot d\u00e1 ao fogo uma flecha extra em seu pr\u00f3ximo tiro de arco, dobrando seu dano.<\/p>\n\n<p class=\"wp-block-paragraph\">Isso combina um maravilhoso loop de jogo de eliminar alguns inimigos corpo a corpo e, em seguida, mudar para o seu arco para acertar um tiro duplo na cabe\u00e7a em um Elite ou Especial.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Guia Relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-handmaiden-build-and-guide\/\" target=\"_blank\" rel=\"noreferrer noopener\">Warhammer: Vermintide 2 Handmaiden Build and Guide<\/a><\/p>\n\n<h3 class=\"wp-block-heading\">Talentos n\u00edvel 15<\/h3>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Esteio<\/td><td>Assassino<\/td><td>Pot\u00eancia Aprimorada<\/td><\/tr><tr><td>Cause 40% a mais de dano a inimigos cambaleantes. Cada acerto contra um inimigo escalonado adiciona outra contagem de escalonamento. O dano b\u00f4nus \u00e9 aumentado para 60% contra inimigos afetados por mais de um efeito de escalonamento.<br\/><\/td><td>Cause 20% a mais de dano a inimigos cambaleantes. Cada acerto contra um inimigo atordoado adiciona outra contagem de atordoamento. Tiros na cabe\u00e7a e acertos cr\u00edticos infligem 40% de dano b\u00f4nus, assim como ataques contra inimigos atingidos por mais de um efeito de atordoamento.<\/td><td>Aumenta o n\u00edvel de poder total em 7,5%.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Assassino \u00e9 a nossa op\u00e7\u00e3o favorita para esta linha, pois tem sinergia com tiros na cabe\u00e7a e acertos cr\u00edticos. Al\u00e9m disso, Assassin fornece dano extra ao atingir alvos escalonados e normalmente \u00e9 a melhor op\u00e7\u00e3o para qualquer classe que possa escolher esse talento. <\/p>\n\n<p class=\"wp-block-paragraph\">No entanto, como o Waytalker \u00e9 uma classe de longo alcance, o uso de Enhanced Power tamb\u00e9m \u00e9 comum. Se voc\u00ea gosta de combate \u00e0 dist\u00e2ncia e corpo a corpo, escolha Assassin, mas se quiser se concentrar mais em combate \u00e0 dist\u00e2ncia, escolha Enhanced Power.<\/p>\n\n<h3 class=\"wp-block-heading\">Talentos n\u00edvel 20<\/h3>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Abra\u00e7o de Isha<\/td><td>Flechas Espirituais<\/td><td>Locus Rejuvenescedor<\/td><\/tr><tr><td>Aumenta a sa\u00fade de Kerillian obtida de Amaranthe em 50%.<\/td><td>Amaranthe reduz o cooldown de Trueshot Volley em 5% a cada tick, mas n\u00e3o restaura mais a sa\u00fade.<\/td><td>Amaranthe tamb\u00e9m afeta os outros membros do grupo.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Spirit Arrows \u00e9 de longe o melhor talento para a sua compila\u00e7\u00e3o Vermintide 2 Waystalker nesta linha. As Flechas Espirituais convertem seu passivo de cura em uma redu\u00e7\u00e3o do tempo de espera para sua Salva de Tiro Certeiro. Ter sua habilidade de carreira fora do cooldown o m\u00e1ximo poss\u00edvel aumentar\u00e1 significativamente seu dano em todas as fases do jogo.<\/p>\n\n<p class=\"wp-block-paragraph\">Talentos n\u00edvel 25<\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Ca\u00e7adora Fervorosa<\/td><td>Ricochete<\/td><td>Foco Asrai<\/td><\/tr><tr><td>Matar um especial ou elite aumenta a velocidade de movimento em 15% por 10 segundos.<\/td><td>As flechas de Kerillian agora ricocheteiam, ricocheteando at\u00e9 3 vezes ou at\u00e9 atingir um inimigo.<\/td><td>Reduz o cooldown de Trueshot Volley em 20%.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Asrai Focus \u00e9 o melhor talento nesta linha. Combinar com Spirit Arrows e Asrai Focus reduz drasticamente o cooldown de Trueshot Volley. \u00c9 importante priorizar a escolha de talentos que aprimorem sua habilidade de carreira, pois ela tem o poder de matar uma Patrulha de Elites inteira sozinha. H\u00e1 uma raz\u00e3o pela qual essa habilidade \u00e9 chamada de &#8220;bot\u00e3o de morte gr\u00e1tis&#8221;.<\/p>\n\n<h3 class=\"wp-block-heading\">Talentos de n\u00edvel 30 para o seu Vermintide 2 Waystalker Build<\/h3>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>tiro perfurante<\/td><td>arco carregado<\/td><td>Recompensa de Kurnous<\/td><\/tr><tr><td>Trueflight Volley dispara um tiro perfurante causando dano pesado. Tiro na cabe\u00e7a reembolsa 100% do cooldown.<\/td><td>Trueshot Volley dispara uma flecha adicional.<\/td><td>Matar um inimigo especial ou de elite com Trueflight Volley restaura 30% da muni\u00e7\u00e3o.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, pegue Loaded Bow. Este talento lhe d\u00e1 uma flecha extra para o seu Trueshot Volley, resultando em mais mortes e danos. Loaded Bow n\u00e3o parece acrescentar muito no papel, mas, na pr\u00e1tica, afeta significativamente seu poder de matar.<\/p>\n\n<p class=\"wp-block-paragraph\">Alternativamente, vemos jogadores Waytalker pegando a Recompensa de Kurnous, e \u00e9 uma boa op\u00e7\u00e3o secund\u00e1ria, mas se torna in\u00fatil quando voc\u00ea sabe como administrar sua muni\u00e7\u00e3o. Al\u00e9m disso, o Trait de arma Conservative Shooter compensa a necessidade da Recompensa de Kurnous assim que voc\u00ea entra no final do jogo, ent\u00e3o Loaded Bow \u00e9 a melhor escolha.<\/p>\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o do nosso Vermintide 2 Waystalker Build &amp; Guide<\/h2>\n\n<p class=\"wp-block-paragraph\">Essa \u00e9 a nossa constru\u00e7\u00e3o e guia para o Waystalker em Vermintide 2. Al\u00e9m do imensamente poderoso Trueshot Volley, o Waystalker \u00e9 uma excelente classe para aqueles que gostam da est\u00e9tica dos Elfos ou prosperam em combates de longo alcance.  <\/p>\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea gostou da nossa lista e quer saber mais sobre as v\u00e1rias classes do Vermintide 2, confira nosso guia sobre <a href=\"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-bounty-hunter-build-guide\/\" target=\"_blank\" rel=\"noreferrer noopener\">como jogar o Bounty Hunter<\/a> ou <a href=\"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-battle-wizard-build-guide\/\" target=\"_blank\" rel=\"noreferrer noopener\">como construir um Battle Wizard no Vermintide 2<\/a> .<\/p>\n\n<p class=\"wp-block-paragraph\">Por enquanto, Boa Ca\u00e7a!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Waystalker \u00e9 um personagem muito divertido em Vermintide 2, com habilidades excepcionais de arco e flecha e a capacidade de navegar no campo de batalha com agilidade e precis\u00e3o. Se voc\u00ea \u00e9 um jogador experiente procurando melhorar seu jogo ou um novato tentando encontrar seu caminho, este guia de constru\u00e7\u00e3o lhe dar\u00e1 uma vis\u00e3o<\/p>\n","protected":false},"author":6,"featured_media":23707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[628],"tags":[1168,1167],"platform":[669,631,671,672],"class_list":["post-29615","post","type-post","status-publish","format-standard","has-post-thumbnail","category-guias-pt-br","tag-martelo-de-guerra","tag-vermintide-2-pt-br","platform-playstation-4-pt-br","platform-windowsos-pt-br","platform-xbox-one-pt-br","platform-xbox-series-x-s-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vermintide 2 - Waystalker Build &amp; Guide | FPS Champion<\/title>\n<meta name=\"description\" content=\"Um guia abrangente sobre como construir e jogar com a classe de personagem de longo alcance Waytalker em Warhammer: Vermintide 2.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warhammer: Vermintide 2 Waystalker Build &amp; Guide\" \/>\n<meta property=\"og:description\" content=\"Um guia abrangente sobre como construir e jogar com a classe de personagem de longo alcance Waytalker em Warhammer: Vermintide 2.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T02:03:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T05:40:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Waystalker-guide-in-Vermintide-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1576\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Warhammer: Vermintide 2 Waystalker Build &amp; Guide\",\"datePublished\":\"2023-03-31T02:03:42+00:00\",\"dateModified\":\"2023-06-04T05:40:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/\"},\"wordCount\":1903,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Waystalker-guide-in-Vermintide-2.jpg\",\"keywords\":[\"martelo de guerra\",\"Vermintide 2\"],\"articleSection\":[\"Guias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/\",\"name\":\"Vermintide 2 - Waystalker Build & Guide | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Waystalker-guide-in-Vermintide-2.jpg\",\"datePublished\":\"2023-03-31T02:03:42+00:00\",\"dateModified\":\"2023-06-04T05:40:12+00:00\",\"description\":\"Um guia abrangente sobre como construir e jogar com a classe de personagem de longo alcance Waytalker em Warhammer: Vermintide 2.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Waystalker-guide-in-Vermintide-2.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Waystalker-guide-in-Vermintide-2.jpg\",\"width\":1576,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/warhammer-vermintide-2-waystalker-build-guide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warhammer: Vermintide 2 Waystalker Build &amp; Guide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/pt-br\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vermintide 2 - Waystalker Build & Guide | FPS Champion","description":"Um guia abrangente sobre como construir e jogar com a classe de personagem de longo alcance Waytalker em Warhammer: Vermintide 2.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/","og_locale":"pt_BR","og_type":"article","og_title":"Warhammer: Vermintide 2 Waystalker Build &amp; Guide","og_description":"Um guia abrangente sobre como construir e jogar com a classe de personagem de longo alcance Waytalker em Warhammer: Vermintide 2.","og_url":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/","og_site_name":"FPS Champion","article_published_time":"2023-03-31T02:03:42+00:00","article_modified_time":"2023-06-04T05:40:12+00:00","og_image":[{"width":1576,"height":900,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Waystalker-guide-in-Vermintide-2.jpg","type":"image\/jpeg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Warhammer: Vermintide 2 Waystalker Build &amp; Guide","datePublished":"2023-03-31T02:03:42+00:00","dateModified":"2023-06-04T05:40:12+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/"},"wordCount":1903,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Waystalker-guide-in-Vermintide-2.jpg","keywords":["martelo de guerra","Vermintide 2"],"articleSection":["Guias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/","url":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/","name":"Vermintide 2 - Waystalker Build & Guide | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Waystalker-guide-in-Vermintide-2.jpg","datePublished":"2023-03-31T02:03:42+00:00","dateModified":"2023-06-04T05:40:12+00:00","description":"Um guia abrangente sobre como construir e jogar com a classe de personagem de longo alcance Waytalker em Warhammer: Vermintide 2.","breadcrumb":{"@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Waystalker-guide-in-Vermintide-2.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/03\/Waystalker-guide-in-Vermintide-2.jpg","width":1576,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/pt-br\/warhammer-vermintide-2-waystalker-build-guide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Warhammer: Vermintide 2 Waystalker Build &amp; Guide"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/pt-br\/#website","url":"https:\/\/fpschampion.com\/pt-br\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/pt-br\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/pt-br\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/pt-br\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/29615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/comments?post=29615"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/29615\/revisions"}],"predecessor-version":[{"id":29620,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/posts\/29615\/revisions\/29620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media\/23707"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/media?parent=29615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/categories?post=29615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/tags?post=29615"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/pt-br\/wp-json\/wp\/v2\/platform?post=29615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}