{"id":32773,"date":"2022-06-29T04:11:26","date_gmt":"2022-06-29T04:11:26","guid":{"rendered":"https:\/\/fpschampion.com\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/"},"modified":"2023-06-04T06:08:56","modified_gmt":"2023-06-04T06:08:56","slug":"comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/","title":{"rendered":"Comment utiliser l&rsquo;hydre dans Halo Infinite Multiplayer Arena"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Halo 5: Guardians avait g\u00e9n\u00e9ralement des sentiments mitig\u00e9s \u00e0 son \u00e9gard lors de sa premi\u00e8re sortie. C&rsquo;\u00e9tait principalement parce que l&rsquo;histoire \u00e9tait d\u00e9cevante pour beaucoup de joueurs. Beaucoup ont \u00e9galement estim\u00e9 que l&rsquo;introduction des jetpacks et des propulseurs rendait le jeu moins semblable \u00e0 un jeu Halo. Les propulseurs reverraient leur chemin dans Halo Infinite en tant que ramassage d&rsquo;\u00e9quipement. Halo 5 n&rsquo;est pas n\u00e9cessairement connu pour ses nouvelles introductions d&rsquo;armes. Cependant, une arme s&rsquo;est d\u00e9marqu\u00e9e et est revenue dans Halo Infinite : l&rsquo;Hydra.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;Hydra est de retour dans Halo Infinite mieux que jamais. Avec sa capacit\u00e9 \u00e0 se verrouiller sur des cibles, \u00e0 infliger des d\u00e9g\u00e2ts acceptables et \u00e0 fonctionner dans n&rsquo;importe quelle situation, cette arme est id\u00e9ale pour les nouveaux arrivants et les joueurs exp\u00e9riment\u00e9s.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-hydra-general-information\">Informations g\u00e9n\u00e9rales sur l&rsquo;hydre<\/h2>\n\n<ul class=\"wp-block-list\"><li><strong>Type d&rsquo;arme :<\/strong> Lanceur<\/li><li><strong>Fabricant :<\/strong> Chalybs Defense Solutions<\/li><li><strong>Type de munitions\u00a0:<\/strong> explosives\/cin\u00e9tiques<\/li><li>Taille du chargeur : 6<\/li><li>Cadence de tir\u00a0: semi-automatique<\/li><li><strong>Perfect Time To Kill (multijoueur) :<\/strong> 3 tirs (non guid\u00e9s), 4 tirs (guid\u00e9s)<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">L&rsquo;Hydra est un lanceur dans Halo Infinite qui tire six mini-roquettes ou micro-missiles. Cette arme est \u00e9galement semi-automatique mais a une cadence de tir fixe. Vous ne pouvez pas tirer aussi vite que vous le souhaitez m\u00eame s&rsquo;il est semi-automatique. Cependant, vous pouvez maintenir le bouton de tir enfonc\u00e9 pour continuer \u00e0 tirer automatiquement.<\/p>\n\n<p class=\"wp-block-paragraph\">Dans Halo Infinite, l&rsquo;hydre subit des d\u00e9g\u00e2ts d&rsquo;\u00e9claboussure. Ne vous attendez pas \u00e0 ce que les d\u00e9g\u00e2ts des \u00e9claboussures ou le rayon soient au m\u00eame niveau que le M41 SPNKR (lance-roquettes). Le rayon d&rsquo;explosion est petit, cependant, il est toujours tr\u00e8s possible de tuer plusieurs ennemis en m\u00eame temps avec. Ils doivent juste \u00eatre regroup\u00e9s. Les types de jeu objectifs sont parfaits pour cette arme.<\/p>\n\n<p class=\"wp-block-paragraph\">Le m\u00e9canisme unique est que cette arme permet au joueur de choisir entre des missiles guid\u00e9s ou non guid\u00e9s. Lorsque vous utilisez des missiles non guid\u00e9s, l&rsquo;Hydra inflige plus de d\u00e9g\u00e2ts, mais vous ne toucherez pas les autres joueurs \u00e0 longue distance. Les missiles guid\u00e9s sont tr\u00e8s pr\u00e9cis m\u00eame \u00e0 des distances extr\u00eamement longues. Ce mode fait cependant moins de d\u00e9g\u00e2ts, n\u00e9cessitant un tir suppl\u00e9mentaire pour tuer la personne.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Guide connexe:<\/strong> <a href=\"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comment gravir les \u00e9chelons du multijoueur de Halo Infinite<\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-best-maps-to-use-the-hydra-in-halo-infinite\">Meilleures cartes pour utiliser l&rsquo;hydre dans Halo Infinite<\/h2>\n\n<p class=\"wp-block-paragraph\">L&rsquo;hydre est l&rsquo;une des armes les plus polyvalentes de Halo Infinite. Cette arme fonctionne parfaitement pour n&rsquo;importe quelle carte. M\u00eame si elle n&rsquo;appara\u00eet que sur les cartes Big Team Battle et Behemoth, vous pouvez toujours rencontrer cette arme sur toutes les cartes en fonction du <a href=\"https:\/\/fpschampion.com\/fr\/couverture-complete-des-nouveaux-modes-de-jeu-de-halo-infinite-dans-la-saison-2\/\" target=\"_blank\" rel=\"noopener\">mode de jeu<\/a> auquel vous jouez.<\/p>\n\n<p class=\"wp-block-paragraph\">Dans la plupart des cas, il est pr\u00e9f\u00e9rable de ne pas utiliser les missiles guid\u00e9s sur les cartes Arena. \u00c0 moins que cette carte ne soit Behemoth, car cette carte est plus grande que les autres. Cependant, pour d&rsquo;autres cartes, il n&rsquo;est pas vraiment n\u00e9cessaire de verrouiller les adversaires \u00e0 moins que votre objectif ne soit tout simplement horrible. Si tel est le cas, vous devriez vous entra\u00eener davantage \u00e0 Halo Infinite avec l&rsquo;Hydra.<\/p>\n\n<p class=\"wp-block-paragraph\">En revanche, n&rsquo;ayez pas peur d&rsquo;utiliser le mode de tir guid\u00e9 sur les modes Big Team Battle. Vous infligerez des d\u00e9g\u00e2ts aux joueurs \u00e0 une bonne distance. Ce ne sera pas celui d&rsquo;un Sniper ou <a href=\"https:\/\/fpschampion.com\/fr\/comment-maitriser-le-fusil-de-choc-dans-halo-infinite\/\" target=\"_blank\" rel=\"noreferrer noopener\">d&rsquo;un Shock Rifle dans Halo Infinite<\/a> , mais ce sera proche. Utiliser ce mode de tir tout en jouant en d\u00e9fense est une strat\u00e9gie l\u00e9gitime. Vous \u00e9liminerez tous les joueurs essayant de capturer un point ou de voler votre drapeau.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-hydra-tips-and-tricks\">Trucs et astuces Hydra<\/h2>\n\n<p class=\"wp-block-paragraph\">La polyvalence d&rsquo;Hydra est ce qui la distingue des <a href=\"https:\/\/fpschampion.com\/fr\/toutes-les-armes-halo-infinite-classees-du-meilleur-au-pire-liste-des-niveaux-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">autres armes dans Halo Infinite<\/a> . Si vous \u00eates s\u00fbr de votre objectif, l&rsquo;utilisation de missiles non guid\u00e9s est votre meilleur pari pour tuer. Ce mode est essentiel dans les combats rapproch\u00e9s car les missiles guid\u00e9s sont pratiquement inutiles dans cette situation.<\/p>\n\n<p class=\"wp-block-paragraph\">Les nouveaux joueurs de Halo Infinite doivent savoir quand \u00e9changer les modes de tir Hydra quand cela est n\u00e9cessaire. En dehors de cela, l&rsquo;Hydra est une arme facile \u00e0 prendre en main et \u00e0 utiliser. Il y a cependant quelques petits conseils qui m\u00e9ritent d&rsquo;\u00eatre not\u00e9s.<\/p>\n\n<h3 class=\"wp-block-heading\">D\u00e9g\u00e2ts caus\u00e9s par les \u00e9claboussures<\/h3>\n\n<p class=\"wp-block-paragraph\">L&rsquo;hydre a un petit rayon de souffle quelle que soit la variation de tir que vous utilisez. Vous pouvez l&rsquo;utiliser \u00e0 votre avantage pour \u00e9liminer ou endommager plusieurs joueurs essayant de capturer un point. De plus, il est parfois pr\u00e9f\u00e9rable de tirer sur le sol ou le mur pr\u00e8s de votre adversaire au lieu de viser des coups directs. Quelques d\u00e9g\u00e2ts valent mieux que pas de d\u00e9g\u00e2ts du tout. Les d\u00e9g\u00e2ts des \u00e9claboussures sont mieux utilis\u00e9s lors de l&rsquo;utilisation du mode de tir non guid\u00e9.<\/p>\n\n<h3 class=\"wp-block-heading\">Verrouillez-vous sur de longues distances avec l&rsquo;hydre dans Halo Infinite<\/h3>\n\n<p class=\"wp-block-paragraph\">Lorsque vous jouez sur des cartes Big Team Battle qui ont de grands espaces, cette arme est une aubaine. L&rsquo;Hydra peut facilement \u00e9liminer vos ennemis dans le multijoueur de Halo Infinite de tr\u00e8s loin lorsque vous utilisez les missiles verrouill\u00e9s et guid\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">Cela prend quelques secondes pour se verrouiller, mais une fois qu&rsquo;il est sur quelqu&rsquo;un, commencez \u00e0 tirer. Vous toucherez tr\u00e8s probablement tous les coups \u00e0 moins qu&rsquo;ils ne courent \u00e0 couvert. Cette arme peut m\u00eame rivaliser avec le <a href=\"https:\/\/fpschampion.com\/fr\/comment-utiliser-le-fusil-de-combat-br75-dans-halo-infinite-multiplayer\/\" target=\"_blank\" rel=\"noopener\">Battle Rifle<\/a> sur de longues distances.<\/p>\n\n<h3 class=\"wp-block-heading\">L&rsquo;Hydra peut abattre facilement les v\u00e9hicules a\u00e9riens dans Halo Infinite<\/h3>\n\n<p class=\"wp-block-paragraph\">La fonction de verrouillage fonctionne \u00e9galement pour les v\u00e9hicules. Bien que cette arme ne soit pas id\u00e9ale pour abattre des v\u00e9hicules terrestres, elle abattre facilement des v\u00e9hicules a\u00e9riens. Les v\u00e9hicules a\u00e9riens ont moins de couverture et moins de mobilit\u00e9. Verrouillez-vous avec l&rsquo;hydre dans Halo Infinite et vous ne devriez pas manquer. Il faudra environ 6 ou 7 coups pour abattre un Banshee et un Wasp.<\/p>\n\n<h3 class=\"wp-block-heading\">Missile non guid\u00e9 \u00e0 courte port\u00e9e<\/h3>\n\n<p class=\"wp-block-paragraph\">Cela a \u00e9t\u00e9 abord\u00e9 un peu plus t\u00f4t dans l&rsquo;article. Si vous vous trouvez dans une bataille rapproch\u00e9e avec cette arme, utiliser le mode de tir non guid\u00e9 est la meilleure solution dans cette situation. Non seulement cela fait plus de d\u00e9g\u00e2ts, mais vous aurez \u00e9galement plus de contr\u00f4le sur la destination de vos missiles.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Guide connexe:<\/strong> <a href=\"https:\/\/fpschampion.com\/fr\/5-conseils-pour-vous-aider-a-atteindre-le-rang-onyx-dans-halo-infinite\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comment atteindre le rang Onyx dans Halo Infinite<\/a><\/p>\n\n<h3 class=\"wp-block-heading\">Annuler le rechargement<\/h3>\n\n<p class=\"wp-block-paragraph\">L&rsquo;animation de rechargement de l&rsquo;hydre peut \u00eatre annul\u00e9e \u00e0 tout moment dans Halo Infinite. L&rsquo;animation de rechargement permet au joueur de recharger chaque mini fus\u00e9e individuellement. Cela permet d&rsquo;achever facilement un adversaire avec un dernier coup au lieu d&rsquo;attendre toute l&rsquo;animation de rechargement. Les joueurs exp\u00e9riment\u00e9s pourront tirer une fus\u00e9e d\u00e8s qu&rsquo;elle sera charg\u00e9e, annulant de nombreuses images d&rsquo;animation. Dans Halo Infinite, chaque seconde compte.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusion<\/h2>\n\n<p class=\"wp-block-paragraph\">Pour la plupart, de nombreuses armes de Halo Infinite sont \u00e9quilibr\u00e9es et fonctionnent dans diverses situations. La m\u00eame chose peut \u00eatre dite pour l&rsquo;hydre. Cette arme fonctionne \u00e0 n&rsquo;importe quelle distance, ce qui est rare pour une arme. Peu d&rsquo;armes peuvent faire de bons d\u00e9g\u00e2ts \u00e0 n&rsquo;importe quelle distance. En plus de cela, l&rsquo;Hydra est excellente en mode multijoueur Halo Infinite en tant qu&rsquo;arme anti-a\u00e9rienne.<\/p>\n\n<p class=\"wp-block-paragraph\">Ce qui rend cette arme encore plus utile, c&rsquo;est qu&rsquo;elle n&rsquo;est pas une arme puissante. Vous pouvez donc le trouver assez facilement sur les supports d&rsquo;armes. Sa capacit\u00e9 \u00e0 suivre des cibles verrouill\u00e9es, de l&rsquo;infanterie ou des v\u00e9hicules, fait de cette arme une force avec laquelle il faut compter.<\/p>\n\n<p class=\"wp-block-paragraph\">Que pensez-vous du retour de l&rsquo;Hydra dans Halo Infinite ? Faites le nous savoir dans les commentaires.<\/p>\n\n<p class=\"wp-block-paragraph\">Pour plus <a href=\"https:\/\/fpschampion.com\/fr\/5-astuces-halo-infinite-pour-ameliorer-votre-gameplay-saison-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">de trucs et astuces Halo Infinite<\/a> , consultez notre <a href=\"https:\/\/fpschampion.com\/fr\/comment-utiliser-le-ravageur-dans-halo-infinite-multiplayer\/\" target=\"_blank\" rel=\"noreferrer noopener\">guide sur la fa\u00e7on d&rsquo;utiliser l&rsquo;arme Ravager<\/a> en multijoueur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Halo 5: Guardians avait g\u00e9n\u00e9ralement des sentiments mitig\u00e9s \u00e0 son \u00e9gard lors de sa premi\u00e8re sortie. C&rsquo;\u00e9tait principalement parce que l&rsquo;histoire \u00e9tait d\u00e9cevante pour beaucoup de joueurs. Beaucoup ont \u00e9galement estim\u00e9 que l&rsquo;introduction des jetpacks et des propulseurs rendait le jeu moins semblable \u00e0 un jeu Halo. Les propulseurs reverraient leur chemin dans Halo Infinite<\/p>\n","protected":false},"author":1,"featured_media":15181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[580],"tags":[1539],"platform":[635,648,657],"class_list":["post-32773","post","type-post","status-publish","format-standard","has-post-thumbnail","category-article-en-vedette","tag-halo-infini","platform-windowsos-fr","platform-xbox-one-fr","platform-xbox-serie-x-s"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment utiliser l&#039;hydre dans Halo Infinite Multiplayer Arena | FPS Champion<\/title>\n<meta name=\"description\" content=\"L&#039;hydre est une arme pr\u00e9f\u00e9r\u00e9e des fans qui revient dans Halo Infinite. Notre guide complet vous montrera ce que vous devez faire pour dominer avec !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment utiliser l&#039;hydre dans Halo Infinite Multiplayer Arena\" \/>\n<meta property=\"og:description\" content=\"L&#039;hydre est une arme pr\u00e9f\u00e9r\u00e9e des fans qui revient dans Halo Infinite. Notre guide complet vous montrera ce que vous devez faire pour dominer avec !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T04:11:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T06:08:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Hydra-Weapon-in-Halo-Infinite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2448\" \/>\n\t<meta property=\"og:image:height\" content=\"1179\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"John\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/\"},\"author\":{\"name\":\"John\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/46c4155ed84016df7368a97955a3a8ed\"},\"headline\":\"Comment utiliser l&rsquo;hydre dans Halo Infinite Multiplayer Arena\",\"datePublished\":\"2022-06-29T04:11:26+00:00\",\"dateModified\":\"2023-06-04T06:08:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/\"},\"wordCount\":1372,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Hydra-Weapon-in-Halo-Infinite.jpg\",\"keywords\":[\"Halo infini\"],\"articleSection\":[\"Article en Vedette\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/\",\"name\":\"Comment utiliser l'hydre dans Halo Infinite Multiplayer Arena | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Hydra-Weapon-in-Halo-Infinite.jpg\",\"datePublished\":\"2022-06-29T04:11:26+00:00\",\"dateModified\":\"2023-06-04T06:08:56+00:00\",\"description\":\"L'hydre est une arme pr\u00e9f\u00e9r\u00e9e des fans qui revient dans Halo Infinite. Notre guide complet vous montrera ce que vous devez faire pour dominer avec !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Hydra-Weapon-in-Halo-Infinite.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Hydra-Weapon-in-Halo-Infinite.jpg\",\"width\":2448,\"height\":1179,\"caption\":\"Hydra | Source: Halo Infinite Screenshot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment utiliser l&rsquo;hydre dans Halo Infinite Multiplayer Arena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/46c4155ed84016df7368a97955a3a8ed\",\"name\":\"John\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"caption\":\"John\"},\"description\":\"John has been playing video games for almost 30 years. From the days of Sim Ant until now, he's been a fan of just about all genres of video games, including FPS games. He has taken on reporting on new and old games as a passion project and really just enjoys being able to inform and guide other like-minded players.\",\"sameAs\":[\"https:\\\/\\\/fpschampion.com\"],\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/author\\\/fpschamp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment utiliser l'hydre dans Halo Infinite Multiplayer Arena | FPS Champion","description":"L'hydre est une arme pr\u00e9f\u00e9r\u00e9e des fans qui revient dans Halo Infinite. Notre guide complet vous montrera ce que vous devez faire pour dominer avec !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment utiliser l'hydre dans Halo Infinite Multiplayer Arena","og_description":"L'hydre est une arme pr\u00e9f\u00e9r\u00e9e des fans qui revient dans Halo Infinite. Notre guide complet vous montrera ce que vous devez faire pour dominer avec !","og_url":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/","og_site_name":"FPS Champion","article_published_time":"2022-06-29T04:11:26+00:00","article_modified_time":"2023-06-04T06:08:56+00:00","og_image":[{"width":2448,"height":1179,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Hydra-Weapon-in-Halo-Infinite.jpg","type":"image\/jpeg"}],"author":"John","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"John","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/"},"author":{"name":"John","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/46c4155ed84016df7368a97955a3a8ed"},"headline":"Comment utiliser l&rsquo;hydre dans Halo Infinite Multiplayer Arena","datePublished":"2022-06-29T04:11:26+00:00","dateModified":"2023-06-04T06:08:56+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/"},"wordCount":1372,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Hydra-Weapon-in-Halo-Infinite.jpg","keywords":["Halo infini"],"articleSection":["Article en Vedette"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/","url":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/","name":"Comment utiliser l'hydre dans Halo Infinite Multiplayer Arena | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Hydra-Weapon-in-Halo-Infinite.jpg","datePublished":"2022-06-29T04:11:26+00:00","dateModified":"2023-06-04T06:08:56+00:00","description":"L'hydre est une arme pr\u00e9f\u00e9r\u00e9e des fans qui revient dans Halo Infinite. Notre guide complet vous montrera ce que vous devez faire pour dominer avec !","breadcrumb":{"@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Hydra-Weapon-in-Halo-Infinite.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/06\/Hydra-Weapon-in-Halo-Infinite.jpg","width":2448,"height":1179,"caption":"Hydra | Source: Halo Infinite Screenshot"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/fr\/comment-utiliser-lhydre-dans-halo-infinite-multiplayer-arena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Comment utiliser l&rsquo;hydre dans Halo Infinite Multiplayer Arena"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/fr\/#website","url":"https:\/\/fpschampion.com\/fr\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/fr\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/46c4155ed84016df7368a97955a3a8ed","name":"John","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","caption":"John"},"description":"John has been playing video games for almost 30 years. From the days of Sim Ant until now, he's been a fan of just about all genres of video games, including FPS games. He has taken on reporting on new and old games as a passion project and really just enjoys being able to inform and guide other like-minded players.","sameAs":["https:\/\/fpschampion.com"],"url":"https:\/\/fpschampion.com\/fr\/author\/fpschamp\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/32773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/comments?post=32773"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/32773\/revisions"}],"predecessor-version":[{"id":32780,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/32773\/revisions\/32780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media\/15181"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media?parent=32773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/categories?post=32773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/tags?post=32773"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/platform?post=32773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}