{"id":31833,"date":"2022-05-10T05:43:46","date_gmt":"2022-05-10T05:43:46","guid":{"rendered":"https:\/\/fpschampion.com\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/"},"modified":"2023-06-04T06:01:53","modified_gmt":"2023-06-04T06:01:53","slug":"rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/","title":{"rendered":"Rangs dans Halo Infinite &#8211; Tout ce que vous devez savoir sur l&rsquo;ar\u00e8ne class\u00e9e"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Halo Infinite a adopt\u00e9 une approche diff\u00e9rente du syst\u00e8me de classement par rapport aux entr\u00e9es pr\u00e9c\u00e9dentes de la s\u00e9rie. Les rangs ne sont gagn\u00e9s que par le jeu class\u00e9 dans Halo Infinity cette fois-ci. Aujourd&rsquo;hui, nous allons passer en revue tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement de Halo Infinite.<\/p>\n\n<p class=\"wp-block-paragraph\">La plupart s&rsquo;accordent \u00e0 dire que l&rsquo;un des meilleurs syst\u00e8mes de classement provenait de Halo: Reach, que, malheureusement, le MCC ne recr\u00e9e pas du tout. Le syst\u00e8me Halo: Reach \u00e9tait un syst\u00e8me de classement simple qui affichait un embl\u00e8me de titre \u00e0 c\u00f4t\u00e9 de votre nom pour ceux qui ne le savaient pas. 343 industries continueraient \u00e0 imiter le style de Reach dans Halos 4 &amp; 5. Pourtant, ils ont compl\u00e8tement chang\u00e9 le syst\u00e8me de classement de Halo Infinite.<\/p>\n\n<p class=\"wp-block-paragraph\">Bien qu&rsquo;il s&rsquo;agisse d&rsquo;un changement diff\u00e9rent, il est int\u00e9ressant de noter que 343 a mis en place un syst\u00e8me similaire \u00e0 la Master Chief Collection mais pas \u00e0 Halo Infinite. Dans Halo Infinite, vous n&rsquo;obtenez un classement de compte que si vous jouez dans la zone class\u00e9e. La progression de n&rsquo;importe quelle passe de combat n&rsquo;accumule aucune progression de niveau de compte comme les jeux pr\u00e9c\u00e9dents; seul votre classement s&rsquo;affiche dans la zone class\u00e9e. Cela \u00e9tant dit, entrons dans le syst\u00e8me de classement de Halo Infinite.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-ranks-for-halo-infinite\">Classements pour Halo Infinite<\/h2>\n\n<p class=\"wp-block-paragraph\">Le syst\u00e8me de zones class\u00e9es de Halo Infinite est similaire au classement de Halo 5. Il vous oblige \u00e0 terminer dix matchs de placement avant de vous placer dans un syst\u00e8me d&rsquo;\u00e9valuation des scores.<\/p>\n\n<p class=\"wp-block-paragraph\">Du niveau inf\u00e9rieur au niveau sup\u00e9rieur, les rangs sont les suivants\u00a0:<\/p>\n\n<ul class=\"wp-block-list\"><li>BRONZE (1-6)<\/li><li>ARGENT (1-6)<\/li><li>OR (1-6)<\/li><li>PLATINE (1-6)<\/li><li>DIAMANT (1-6)<\/li><li>ONYX<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s vos dix matchs de placement initiaux, le rang le plus \u00e9lev\u00e9 que vous pouvez atteindre est Diamant 5. Cependant, une diff\u00e9rence majeure signal\u00e9e est que les joueurs l&rsquo;ont d\u00e9couvert gr\u00e2ce \u00e0 la premi\u00e8re saison rocheuse de Halo Infinites. Votre cote de score est li\u00e9e \u00e0 votre K\/D et \u00e0 vos performances dans le match, principalement en termes de victoire ou de d\u00e9faite. Bien s\u00fbr, gagner compte toujours pour l&rsquo;escalade, mais si vous accumuliez de nombreuses victoires et m\u00e9dailles dans ce match, vous grimperiez quand m\u00eame rapidement les \u00e9chelons. Cela a amen\u00e9 les joueurs \u00e0 jouer pour tuer plut\u00f4t que pour l&rsquo;objectif de la premi\u00e8re saison de Halo. Ce syst\u00e8me est encore tr\u00e8s susceptible de se produire dans la deuxi\u00e8me saison de Halo Infinite, Lone Wolves, mais est susceptible de changer.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Article connexe :<\/strong> <a href=\"https:\/\/fpschampion.com\/fr\/comment-baisser-votre-arme-dans-halo-infinite-pour-gagner-en-visibilite\/\" target=\"_blank\" rel=\"noreferrer noopener\">Comment baisser votre arme dans Halo Infinite<\/a><\/p>\n\n<h2 class=\"wp-block-heading\">Jouer class\u00e9<\/h2>\n\n<p class=\"wp-block-paragraph\">Lors de la lecture de Class\u00e9 dans Halo Infinite, 343 Industries a apport\u00e9 l&rsquo;aspect le plus comp\u00e9titif de Halo Esports et a mis en place des param\u00e8tres similaires sur lesquels jouent les professionnels. Vous jouez dans une ar\u00e8ne 4v4, et votre chargement de d\u00e9part initial est juste un fusil de combat et des grenades sans arme de poing. Les hitmakers de mini-cartes et de grenades sont d\u00e9sactiv\u00e9s et le tir ami est activ\u00e9.<\/p>\n\n<p class=\"wp-block-paragraph\">Vous pouvez faire la queue pour l&rsquo;ar\u00e8ne class\u00e9e avec le jeu crois\u00e9 activ\u00e9 ou le contr\u00f4leur ou le clavier et la souris uniquement. Il existe \u00e9galement une option solo\/duo chaque fois que vous s\u00e9lectionnez une option d&rsquo;entr\u00e9e diff\u00e9rente. Sinon, si vous voulez jouer avec un groupe entier de quatre personnes, vous ne pouvez choisir que le jeu crois\u00e9 ouvert quoi qu&rsquo;il arrive. Les ar\u00e8nes class\u00e9es solo\/duo et ouvertes ont des classements diff\u00e9rents.<\/p>\n\n<p class=\"wp-block-paragraph\">Vous devrez vous battre pour deux classements diff\u00e9rents si vous passez constamment de jouer seul ou avec un ami \u00e0 toute une f\u00eate. Si vous d\u00e9cidez de jouer avec des amis, vous ne pouvez mettre en file d&rsquo;attente l&rsquo;ar\u00e8ne class\u00e9e que s&rsquo;ils se trouvent dans un classement proche du v\u00f4tre. Cela emp\u00eache les joueurs d&rsquo;Onyx d&rsquo;avoir un joueur d&rsquo;argent dans leur \u00e9quipe pour maintenir les niveaux de comp\u00e9tence plus \u00e9quilibr\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">Les modes actuels auxquels vous pouvez vous attendre \u00e0 jouer dans l&rsquo;ar\u00e8ne class\u00e9e sont\u00a0:<\/p>\n\n<ul class=\"wp-block-list\"><li>Tueur<\/li><li>Capturer le drapeau<\/li><li>Excentrique<\/li><li>Bastions<\/li><li>roi de la colline<\/li><\/ul>\n\n<h2 class=\"wp-block-heading\">\u00c0 quelle fr\u00e9quence les classements sont-ils r\u00e9initialis\u00e9s dans Halo Infinite ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Les classements sont programm\u00e9s pour \u00eatre r\u00e9initialis\u00e9s \u00e0 la fin de chaque saison. Vous pouvez trouver combien de jours il reste dans la saison dans le menu de pr\u00e9visualisation du Battle Pass et des d\u00e9fis hebdomadaires. La deuxi\u00e8me saison de Halo Infinite, Lone Wolves, se termine le 8 novembre, avec plus de 150 jours restants dans la saison en cours. Il y a eu une r\u00e9initialisation pr\u00e9coce du classement au cours des trois derniers mois de la premi\u00e8re saison de Halo Infinite.<\/p>\n\n<p class=\"wp-block-paragraph\">Pourtant, la raison de la r\u00e9initialisation anticip\u00e9e \u00e9tait les ajustements de classement mondiaux. Nous ne pouvons pas juger si une autre r\u00e9initialisation anticip\u00e9e aura lieu au cours de la deuxi\u00e8me saison, mais nous ne comptons pas dessus. Si vous avez obtenu un classement \u00e9lev\u00e9 \u00e0 la fin de la saison, votre prochaine s\u00e9rie de matchs de placement devrait vous aider \u00e0 revenir \u00e0 votre classement pr\u00e9c\u00e9dent, afin que les joueurs de haut rang n&rsquo;aient pas \u00e0 remonter de l&rsquo;argent ou du bronze \u00e0 nouveau.<\/p>\n\n<h2 class=\"wp-block-heading\">R\u00e9flexions finales sur les rangs Halo Infinite<\/h2>\n\n<p class=\"wp-block-paragraph\">C&rsquo;\u00e9tait notre aper\u00e7u du syst\u00e8me actuel d&rsquo;ar\u00e8ne class\u00e9e de Halo Infinite. En revanche, la communaut\u00e9 a rat\u00e9 le classement de l&rsquo;h\u00e9bergement des pr\u00e9c\u00e9dents jeux Halo pour les joueurs occasionnels et comp\u00e9titifs. Le nouveau syst\u00e8me de classement a encore quelques ajustements \u00e0 faire, mais se concentrer sur l&rsquo;utilisation des param\u00e8tres comp\u00e9titifs tout en jouant \u00e0 l&rsquo;ar\u00e8ne class\u00e9e est un ajout bienvenu au jeu. Vous pouvez les trouver ici si vous souhaitez voir tous <a href=\"https:\/\/fpschampion.com\/fr\/couverture-complete-des-nouveaux-modes-de-jeu-de-halo-infinite-dans-la-saison-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">les nouveaux modes de jeu<\/a> et <a href=\"https:\/\/fpschampion.com\/fr\/tout-ce-que-nous-savons-sur-la-saison-2-de-halo-infinite-jusqua-present\/\" target=\"_blank\" rel=\"noreferrer noopener\">les modifications apport\u00e9es \u00e0 Lone Wolves<\/a> . Bonne chasse, Spartiates !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Halo Infinite a adopt\u00e9 une approche diff\u00e9rente du syst\u00e8me de classement par rapport aux entr\u00e9es pr\u00e9c\u00e9dentes de la s\u00e9rie. Les rangs ne sont gagn\u00e9s que par le jeu class\u00e9 dans Halo Infinity cette fois-ci. Aujourd&rsquo;hui, nous allons passer en revue tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement de Halo Infinite.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1610],"tags":[1539],"platform":[635,648,657],"class_list":["post-31833","post","type-post","status-publish","format-standard","category-esports-fr","tag-halo-infini","platform-windowsos-fr","platform-xbox-one-fr","platform-xbox-serie-x-s"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FPS Champion<\/title>\n<meta name=\"description\" content=\"Nous couvrons tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement dans Halo Infinite. Les changements r\u00e9cents signifient que les rangs sont g\u00e9r\u00e9s diff\u00e9remment.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rangs dans Halo Infinite - Tout ce que vous devez savoir sur l&#039;ar\u00e8ne class\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Nous couvrons tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement dans Halo Infinite. Les changements r\u00e9cents signifient que les rangs sont g\u00e9r\u00e9s diff\u00e9remment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T05:43:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T06:01:53+00:00\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Rangs dans Halo Infinite &#8211; Tout ce que vous devez savoir sur l&rsquo;ar\u00e8ne class\u00e9e\",\"datePublished\":\"2022-05-10T05:43:46+00:00\",\"dateModified\":\"2023-06-04T06:01:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/\"},\"wordCount\":1058,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"keywords\":[\"Halo infini\"],\"articleSection\":[\"eSports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\"},\"datePublished\":\"2022-05-10T05:43:46+00:00\",\"dateModified\":\"2023-06-04T06:01:53+00:00\",\"description\":\"Nous couvrons tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement dans Halo Infinite. Les changements r\u00e9cents signifient que les rangs sont g\u00e9r\u00e9s diff\u00e9remment.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rangs dans Halo Infinite &#8211; Tout ce que vous devez savoir sur l&#8217;ar\u00e8ne class\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FPS Champion","description":"Nous couvrons tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement dans Halo Infinite. Les changements r\u00e9cents signifient que les rangs sont g\u00e9r\u00e9s diff\u00e9remment.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/","og_locale":"fr_FR","og_type":"article","og_title":"Rangs dans Halo Infinite - Tout ce que vous devez savoir sur l'ar\u00e8ne class\u00e9e","og_description":"Nous couvrons tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement dans Halo Infinite. Les changements r\u00e9cents signifient que les rangs sont g\u00e9r\u00e9s diff\u00e9remment.","og_url":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/","og_site_name":"FPS Champion","article_published_time":"2022-05-10T05:43:46+00:00","article_modified_time":"2023-06-04T06:01:53+00:00","author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jake Butala","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Rangs dans Halo Infinite &#8211; Tout ce que vous devez savoir sur l&rsquo;ar\u00e8ne class\u00e9e","datePublished":"2022-05-10T05:43:46+00:00","dateModified":"2023-06-04T06:01:53+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/"},"wordCount":1058,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"keywords":["Halo infini"],"articleSection":["eSports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/","url":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/","name":"","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/#website"},"datePublished":"2022-05-10T05:43:46+00:00","dateModified":"2023-06-04T06:01:53+00:00","description":"Nous couvrons tout ce que vous devez savoir sur le nouveau syst\u00e8me de classement dans Halo Infinite. Les changements r\u00e9cents signifient que les rangs sont g\u00e9r\u00e9s diff\u00e9remment.","breadcrumb":{"@id":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/fr\/rangs-dans-halo-infinite-tout-ce-que-vous-devez-savoir-sur-larene-classee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Rangs dans Halo Infinite &#8211; Tout ce que vous devez savoir sur l&#8217;ar\u00e8ne class\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/fr\/#website","url":"https:\/\/fpschampion.com\/fr\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/fr\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/fr\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/comments?post=31833"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31833\/revisions"}],"predecessor-version":[{"id":31838,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31833\/revisions\/31838"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media?parent=31833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/categories?post=31833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/tags?post=31833"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/platform?post=31833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}