{"id":31354,"date":"2022-07-09T04:04:47","date_gmt":"2022-07-09T04:04:47","guid":{"rendered":"https:\/\/fpschampion.com\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/"},"modified":"2023-06-04T05:58:36","modified_gmt":"2023-06-04T05:58:36","slug":"ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/","title":{"rendered":"O\u00f9 trouver le Sledgehammer dans Project Zomboid et comment l&rsquo;utiliser"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Dans le jeu Project Zomboid, vous pouvez trouver de nombreux objets diff\u00e9rents pour vous aider \u00e0 survivre. L&rsquo;un des plus importants est le marteau de forgeron. Les joueurs peuvent utiliser cette arme puissante pour d\u00e9truire les obstacles, se d\u00e9fendre contre les zombies et bien plus encore. Ce guide vous indiquera o\u00f9 trouver la masse dans Project Zomboid !<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-does-the-sledgehammer-do-in-project-zomboid\">Que fait la masse dans Project Zomboid ?<\/h2>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Le marteau est une arme de m\u00eal\u00e9e \u00e0 deux mains qui peut \u00e9galement \u00eatre utilis\u00e9e comme outil lors de l&rsquo;interaction avec certains objets. La chose remarquable \u00e0 propos de cette arme est qu&rsquo;elle inflige les d\u00e9g\u00e2ts les plus \u00e9lev\u00e9s de toutes les armes de m\u00eal\u00e9e du jeu. De plus, en raison de son large swing, le marteau peut frapper plusieurs ennemis simultan\u00e9ment dans Project Zomboid.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">L&rsquo;inconv\u00e9nient du marteau est qu&rsquo;il s&rsquo;agit d&rsquo;une arme relativement lente \u00e0 manier. Vous vous exposerez aux attaques rapides des zombies tout en le balan\u00e7ant si vous ne faites pas attention. Au-del\u00e0 de cela, manier la grosse arme est \u00e9galement tr\u00e8s fatigant, vous utiliserez donc beaucoup d&rsquo;\u00e9nergie et devrez <a href=\"https:\/\/fpschampion.com\/fr\/comment-dormir-dans-project-zomboid-un-guide-complet\/\">dormir plus t\u00f4t dans Project Zomboid<\/a> .<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-using-the-sledgehammer-as-a-tool\">Utiliser le marteau comme outil<\/h3>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Le marteau de forgeron peut \u00e9galement \u00eatre utilis\u00e9 comme outil en dehors du combat. Lorsqu&rsquo;il est utilis\u00e9 sur des objets particuliers, tels que des portes ou des murs, le marteau peut \u00eatre utilis\u00e9 pour les briser. Il peut \u00eatre pratique de d\u00e9truire des murs lorsque vos issues de secours sont bloqu\u00e9es ou verrouill\u00e9es. Vous pouvez \u00e9galement l&rsquo;utiliser pour remodeler vos refuges ou atteindre des espaces rares et inaccessibles \u00e0 l&rsquo;int\u00e9rieur des b\u00e2timents.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Un endroit id\u00e9al pour prendre votre masse pour vous amuser avec les murs est une installation de stockage. Le marteau facilite l&rsquo;acc\u00e8s \u00e0 ces espaces verrouill\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">La masse est l&rsquo;un des outils les plus polyvalents du jeu. En fait, vous pouvez m\u00eame utiliser le marteau pour abattre des arbres au cas o\u00f9 vous voudriez fabriquer des planches de bois pour <a href=\"https:\/\/fpschampion.com\/fr\/comment-embarquer-windows-dans-project-zomboid\/\" target=\"_blank\" rel=\"noreferrer noopener\">monter des fen\u00eatres dans Project Zomboid<\/a> . Cependant, c&rsquo;est un outil m\u00e9diocre pour cela, et nous vous recommandons vraiment d&rsquo;utiliser la hache. De plus, les haches sont \u00e9galement beaucoup plus faciles \u00e0 trouver dans Project Zomboid que le marteau.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-find-the-sledgehammer-in-project-zomboid\">Comment trouver le Sledgehammer dans Project Zomboid<\/h2>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Le marteau de forgeron de Project Zomboid est l&rsquo;un des objets les plus rares du jeu. Par cons\u00e9quent, vous ne pouvez pas toujours le trouver au m\u00eame endroit. Cela \u00e9tant dit, nous vous aiderons \u00e0 obtenir le Sledgehammer dans Project Zomboid en partageant avec vous les endroits les plus courants o\u00f9 il peut appara\u00eetre.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Comme pour la plupart des objets du jeu, les emplacements d&rsquo;apparition les plus courants pour cet objet sont ceux o\u00f9 vous vous attendez g\u00e9n\u00e9ralement \u00e0 le trouver. Les chantiers de construction et les ateliers d&rsquo;outillage sont les endroits les plus \u00e9vidents pour trouver le marteau de forgeron dans Project Zomboid. La plupart des villes sur la carte ont au moins un magasin d&rsquo;outils, alors faites-en votre premier arr\u00eat lorsque vous cherchez le marteau.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Vous pouvez \u00e9galement le trouver couramment dans les caisses d&rsquo;entrep\u00f4t, les abris de jardin, les garages et les salles d&rsquo;approvisionnement. \u00c0 peu pr\u00e8s partout o\u00f9 vous vous attendez \u00e0 en trouver un dans la vraie vie, vous avez une chance d\u00e9cente d&rsquo;en d\u00e9couvrir un dans le jeu. C&rsquo;est ce qui rend Project Zomboid si unique. Les d\u00e9veloppeurs ont fait un travail fantastique pour recr\u00e9er notre monde et cr\u00e9er une exp\u00e9rience immersive\u00a0!<\/p>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-1024x576.jpg\" alt=\"\" class=\"wp-image-4492\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-1024x576.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-1536x864.jpg 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid-1200x675.jpg 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/warehouse-in-project-zomboid.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Vous pouvez trouver le SledgeHammer dans des caisses d&rsquo;entrep\u00f4t dans Project Zomboid. Ne tirez pas sur un mort-vivant en regardant.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">N&rsquo;oubliez pas que le marteau a un taux d&rsquo;apparition inf\u00e9rieur \u00e0 la plupart des autres outils et armes de m\u00eal\u00e9e du jeu en raison de sa puissance et de son utilit\u00e9.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-where-to-find-the-sledgehammer-in-the-west-point-area-of-project-zomboid\">O\u00f9 trouver le Sledgehammer dans la zone West Point de Project Zomboid<\/h3>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">West Point compte un grand nombre de sites industriels. Si vous \u00eates dans cette r\u00e9gion, nous vous recommandons fortement de commencer par regarder dans les caisses trouv\u00e9es dans ces sites industriels. Cela vous donne de nombreux emplacements d&rsquo;apparition potentiels pour rechercher le Sledgehammer dans Project Zomboid.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Si vous n&rsquo;avez pas de chance, concentrez-vous sur sa recherche dans les caisses des entrep\u00f4ts \u00e0 proximit\u00e9. Les \u00e9tag\u00e8res m\u00e9talliques des entrep\u00f4ts valent \u00e9galement la peine d&rsquo;\u00eatre examin\u00e9es si vous n&rsquo;en avez pas encore trouv\u00e9es.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Le dernier endroit o\u00f9 vous devriez chercher \u00e0 West Point le Sledgehammer dans Project Zomboid est ses magasins d&rsquo;outils. Si vous \u00e9puisez tous ces emplacements \u00e0 West Point, votre meilleur pari est de regarder au hasard dans des endroits o\u00f9 vous pensez qu&rsquo;il est susceptible d&rsquo;appara\u00eetre, comme indiqu\u00e9 ci-dessus.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-does-the-sledgehammer-look-like\">\u00c0 quoi ressemble le marteau de forgeron\u00a0?<\/h2>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Dans Project Zomboied, vous pouvez trouver le marteau dans deux variantes diff\u00e9rentes. La variante la plus apparente a une poign\u00e9e standard non color\u00e9e avec une grande t\u00eate quelque peu arrondie.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Dans la variante la moins \u00e9vidente, le Sledgehammer de Project Zomboid ressemble plus \u00e0 un long marteau. Il a un manche teint\u00e9 de rouge et une t\u00eate carr\u00e9e. Ce marteau est beaucoup plus difficile \u00e0 rep\u00e9rer, car la couleur rouge vous fait souvent penser qu&rsquo;il s&rsquo;agit d&rsquo;un outil diff\u00e9rent de celui que la plupart des joueurs ont l&rsquo;habitude de voir dans les quincailleries.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-final-thoughts\">R\u00e9flexions finales<\/h2>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Nous esp\u00e9rons que vous avez appr\u00e9ci\u00e9 notre guide sur o\u00f9 trouver le marteau de forgeron dans Project Zomboid. Cet outil puissant peut \u00eatre b\u00e9n\u00e9fique, \u00e0 la fois au combat et comme outil pour casser des objets. Avec sa raret\u00e9, cependant, il peut \u00eatre difficile \u00e0 trouver. Nous vous recommandons de rechercher les emplacements de spawn les plus courants d\u00e9crits ci-dessus si vous avez du mal \u00e0 en trouver un.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Si vous avez d&rsquo;autres questions ou suggestions pour les joueurs \u00e0 la recherche de l&#8217;emplacement du marteau, n&rsquo;h\u00e9sitez pas \u00e0 nous laisser un commentaire ci-dessous. Et assurez-vous de consulter nos autres guides pendant que vous \u00eates ici! Nous avons un <a href=\"https:\/\/fpschampion.com\/fr\/comment-saccroupir-et-se-faufiler-dans-project-zomboid-le-guide-furtif-ultime\/\" target=\"_blank\" rel=\"noreferrer noopener\">guide complet de Project Zomboid pour s&rsquo;accroupir et se faufiler<\/a> qui est une lecture incontournable pour les nouveaux joueurs qui cherchent \u00e0 se d\u00e9placer sur la carte.<\/p>\n\n<p class=\"wp-block-paragraph\" id=\"45f911e2-bd31-4628-891f-aeb2b62fa2ec\">Bonne chasse!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le jeu Project Zomboid, vous pouvez trouver de nombreux objets diff\u00e9rents pour vous aider \u00e0 survivre. L&rsquo;un des plus importants est le marteau de forgeron. Les joueurs peuvent utiliser cette arme puissante pour d\u00e9truire les obstacles, se d\u00e9fendre contre les zombies et bien plus encore. Ce guide vous indiquera o\u00f9 trouver la masse dans<\/p>\n","protected":false},"author":1,"featured_media":15401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[580],"tags":[1587],"platform":[946,910,635],"class_list":["post-31354","post","type-post","status-publish","format-standard","has-post-thumbnail","category-article-en-vedette","tag-projet-zomboide","platform-linux-fr","platform-mac-os-fr","platform-windowsos-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FPS Champion<\/title>\n<meta name=\"description\" content=\"Dans notre guide complet, nous vous montrerons o\u00f9 trouver le marteau de forgeron dans Project Zomboid et comment l&#039;utiliser comme arme et outil !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u00f9 trouver le Sledgehammer dans Project Zomboid et comment l&#039;utiliser\" \/>\n<meta property=\"og:description\" content=\"Dans notre guide complet, nous vous montrerons o\u00f9 trouver le marteau de forgeron dans Project Zomboid et comment l&#039;utiliser comme arme et outil !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-09T04:04:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T05:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/finding-sledgehammer-project-zomboid.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"John\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/\"},\"author\":{\"name\":\"John\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/46c4155ed84016df7368a97955a3a8ed\"},\"headline\":\"O\u00f9 trouver le Sledgehammer dans Project Zomboid et comment l&rsquo;utiliser\",\"datePublished\":\"2022-07-09T04:04:47+00:00\",\"dateModified\":\"2023-06-04T05:58:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/\"},\"wordCount\":1094,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/finding-sledgehammer-project-zomboid.jpg\",\"keywords\":[\"Projet Zombo\u00efde\"],\"articleSection\":[\"Article en Vedette\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/finding-sledgehammer-project-zomboid.jpg\",\"datePublished\":\"2022-07-09T04:04:47+00:00\",\"dateModified\":\"2023-06-04T05:58:36+00:00\",\"description\":\"Dans notre guide complet, nous vous montrerons o\u00f9 trouver le marteau de forgeron dans Project Zomboid et comment l'utiliser comme arme et outil !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/finding-sledgehammer-project-zomboid.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/finding-sledgehammer-project-zomboid.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Source: ProjectZomboid.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O\u00f9 trouver le Sledgehammer dans Project Zomboid et comment l&#8217;utiliser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/46c4155ed84016df7368a97955a3a8ed\",\"name\":\"John\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g\",\"caption\":\"John\"},\"description\":\"John has been playing video games for almost 30 years. From the days of Sim Ant until now, he's been a fan of just about all genres of video games, including FPS games. He has taken on reporting on new and old games as a passion project and really just enjoys being able to inform and guide other like-minded players.\",\"sameAs\":[\"https:\\\/\\\/fpschampion.com\"],\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/author\\\/fpschamp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FPS Champion","description":"Dans notre guide complet, nous vous montrerons o\u00f9 trouver le marteau de forgeron dans Project Zomboid et comment l'utiliser comme arme et outil !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/","og_locale":"fr_FR","og_type":"article","og_title":"O\u00f9 trouver le Sledgehammer dans Project Zomboid et comment l'utiliser","og_description":"Dans notre guide complet, nous vous montrerons o\u00f9 trouver le marteau de forgeron dans Project Zomboid et comment l'utiliser comme arme et outil !","og_url":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/","og_site_name":"FPS Champion","article_published_time":"2022-07-09T04:04:47+00:00","article_modified_time":"2023-06-04T05:58:36+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/finding-sledgehammer-project-zomboid.jpg","type":"image\/jpeg"}],"author":"John","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"John","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/"},"author":{"name":"John","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/46c4155ed84016df7368a97955a3a8ed"},"headline":"O\u00f9 trouver le Sledgehammer dans Project Zomboid et comment l&rsquo;utiliser","datePublished":"2022-07-09T04:04:47+00:00","dateModified":"2023-06-04T05:58:36+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/"},"wordCount":1094,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/finding-sledgehammer-project-zomboid.jpg","keywords":["Projet Zombo\u00efde"],"articleSection":["Article en Vedette"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/","url":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/","name":"","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/finding-sledgehammer-project-zomboid.jpg","datePublished":"2022-07-09T04:04:47+00:00","dateModified":"2023-06-04T05:58:36+00:00","description":"Dans notre guide complet, nous vous montrerons o\u00f9 trouver le marteau de forgeron dans Project Zomboid et comment l'utiliser comme arme et outil !","breadcrumb":{"@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/finding-sledgehammer-project-zomboid.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/07\/finding-sledgehammer-project-zomboid.jpg","width":1920,"height":1080,"caption":"Source: ProjectZomboid.com"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/fr\/ou-trouver-le-sledgehammer-dans-project-zomboid-et-comment-lutiliser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"O\u00f9 trouver le Sledgehammer dans Project Zomboid et comment l&#8217;utiliser"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/fr\/#website","url":"https:\/\/fpschampion.com\/fr\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/fr\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/46c4155ed84016df7368a97955a3a8ed","name":"John","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56694a56d758a60e71a5b6f4f39e5cf3eca04ad8b3aa96108167c028378aa4b8?s=96&d=mm&r=g","caption":"John"},"description":"John has been playing video games for almost 30 years. From the days of Sim Ant until now, he's been a fan of just about all genres of video games, including FPS games. He has taken on reporting on new and old games as a passion project and really just enjoys being able to inform and guide other like-minded players.","sameAs":["https:\/\/fpschampion.com"],"url":"https:\/\/fpschampion.com\/fr\/author\/fpschamp\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/comments?post=31354"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31354\/revisions"}],"predecessor-version":[{"id":31360,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31354\/revisions\/31360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media\/15401"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media?parent=31354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/categories?post=31354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/tags?post=31354"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/platform?post=31354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}