{"id":31001,"date":"2022-08-24T02:55:35","date_gmt":"2022-08-24T02:55:35","guid":{"rendered":"https:\/\/fpschampion.com\/meilleure-construction-de-payday-2-melee-en-2023\/"},"modified":"2023-06-04T05:54:29","modified_gmt":"2023-06-04T05:54:29","slug":"meilleure-construction-de-payday-2-melee-en-2023","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/","title":{"rendered":"Meilleure construction de Payday 2 Melee en 2023"},"content":{"rendered":"\n<p>Payday 2 est un jeu coop\u00e9ratif PvE exceptionnel qui permet aux joueurs d&rsquo;y jouer comme bon leur semble. Si vous voulez faire flamber des armes \u00e0 feu, vous le pouvez; coup d&rsquo;oeil sournois? Tu l&rsquo;as eu; ou frappez-vous simplement tous ceux qui croisent votre chemin\u00a0? Bien s\u00fbr vous pouvez! Payday 2 est un jeu plein de possibilit\u00e9s ; les joueurs peuvent jouer chaque mission une centaine de fois avec des r\u00e9sultats diff\u00e9rents.<\/p>\n\n<p>Cet article couvrira certaines des meilleures armes, decks et avantages de m\u00eal\u00e9e pour r\u00e9ussir avec votre construction de m\u00eal\u00e9e dans Payday 2. Les armes de m\u00eal\u00e9e dans Payday peuvent \u00eatre difficiles \u00e0 utiliser ; ici, nous vous donnerons \u00e9galement quelques conseils pour r\u00e9ussir avec eux.<\/p>\n\n<h2 class=\"wp-block-heading\">Aper\u00e7u de notre guide de construction de m\u00eal\u00e9e pour Payday 2<\/h2>\n\n<p>Payday 2 est un jeu con\u00e7u autour des armes, avec un arsenal si massif et une quantit\u00e9 incroyable d&rsquo;options de personnalisation et de vari\u00e9t\u00e9 d&rsquo;armes \u00e0 feu. Jouer au jeu avec uniquement des armes de m\u00eal\u00e9e peut \u00eatre \u00e9trange, diff\u00e9rent et stimulant. Vous devrez combattre divers ennemis \u00e0 travers des hordes, il est donc fondamental de choisir la bonne construction pour l&rsquo;occasion.<\/p>\n\n<p>Cet article vous aidera \u00e0 choisir le bon \u00e9quipement et la bonne arme de m\u00eal\u00e9e pour r\u00e9ussir votre mission.<\/p>\n\n<h2 class=\"wp-block-heading\">Meilleures armes de m\u00eal\u00e9e pour une construction de m\u00eal\u00e9e dans Payday 2<\/h2>\n\n<p>Pour ce guide, nous nous concentrerons principalement sur les armes de m\u00eal\u00e9e gratuites incluses dans le jeu de base et qui peuvent \u00eatre d\u00e9bloqu\u00e9es en jouant \u00e0 Payday 2. Gardez \u00e0 l&rsquo;esprit que si vous avez certains des <a href=\"https:\/\/fpschampion.com\/fr\/les-5-meilleurs-packs-dlc-payday-2-a-obtenir-en-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">packs DLC pour Payday 2<\/a> , vous pouvez trouver des rempla\u00e7ants pour les armes incluses dans cette liste. Certaines armes DLC sont des versions l\u00e9g\u00e8rement modifi\u00e9es des armes gratuites avec des statistiques plus \u00e9lev\u00e9es.<\/p>\n\n<p>Avant de continuer, nous ne parlerons pas d&rsquo;armure car ce serait une pr\u00e9f\u00e9rence personnelle selon que vous vouliez \u00eatre un tank ou avoir plus de vitesse de d\u00e9placement.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-stainless-steel-syringe\">Seringue en acier inoxydable<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/stainless-steel-syringe-payday-2-1024x564.png\" alt=\"seringue en acier inoxydable pour une excellente construction Payday 2 Melee\" class=\"wp-image-5818\"\/><\/figure>\n\n<p>La seringue en acier inoxydable inflige des d\u00e9g\u00e2ts de base de 30 points de vie en \u00e9change d&rsquo;une dissimulation \u00e9lev\u00e9e et d&rsquo;un effet de poison qui inflige des d\u00e9g\u00e2ts sur la dur\u00e9e aux ennemis qu&rsquo;elle touche.<\/p>\n\n<p>D\u00e9g\u00e2ts : 30 (80)<\/p>\n\n<p>Renversement\u00a0: 30 (80)<\/p>\n\n<p>Temps de charge : 1,5 secondes<\/p>\n\n<p>Port\u00e9e\u00a0: 150<\/p>\n\n<p>Dissimulation : 30 <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-weapon-butt\">Crosse d&rsquo;arme<\/h3>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"565\" height=\"262\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/weapon-butt-Payday-2-melee-build.jpg\" alt=\"crosse d'arme\" class=\"wp-image-5819\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/weapon-butt-Payday-2-melee-build.jpg 565w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/weapon-butt-Payday-2-melee-build-300x139.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/weapon-butt-Payday-2-melee-build-150x70.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/weapon-butt-Payday-2-melee-build-450x209.jpg 450w\" sizes=\"(max-width: 565px) 100vw, 565px\" \/><\/figure>\n<\/div>\n<p>Le Weapon Butt est probablement l&rsquo;une des armes de m\u00eal\u00e9e les plus rapides de Payday 2 avec de faibles d\u00e9g\u00e2ts mais un temps de recharge de 0 secondes.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9g\u00e2ts : 30<\/li>\n\n\n\n<li>Renversement\u00a0: 30<\/li>\n\n\n\n<li>Temps de charge : 0 secondes<\/li>\n\n\n\n<li>Port\u00e9e\u00a0: 150<\/li>\n\n\n\n<li>Dissimulation : 30 <\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-nova-chank\">Nova Chank<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"564\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-1024x564.png\" alt=\"brosse &#xE0; dents nova chank avec pointe aiguis&#xE9;e\" class=\"wp-image-5820\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-1024x564.png 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-300x165.png 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-768x423.png 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-1536x847.png 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-150x83.png 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-450x248.png 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush-1200x662.png 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/toothbrush.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Pour d\u00e9verrouiller le Nova Chank, vous devez terminer The Hoxton Breakout Heist et Free Hoxton. Cette arme de m\u00eal\u00e9e est une brosse \u00e0 dents adapt\u00e9e comme arme. Semblable au Weapon Butt, le Nova Chank offre une grande vitesse de swing vous permettant de prendre les ennemis plus rapidement.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9g\u00e2ts : 30 (80)<\/li>\n\n\n\n<li>Renversement\u00a0: 30 (80)<\/li>\n\n\n\n<li>Temps de charge : 2 secondes<\/li>\n\n\n\n<li>Port\u00e9e\u00a0: 150<\/li>\n\n\n\n<li>Dissimulation : 30 <\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-el-verdugo\">El Verdugo<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"565\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-1024x565.png\" alt=\"verdugo pour le chargement du couteau dans le jour de paie 2\" class=\"wp-image-5821\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-1024x565.png 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-300x166.png 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-768x424.png 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-1536x848.png 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-150x83.png 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-450x248.png 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette-1200x662.png 1200w, https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/machette.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>C&rsquo;est votre arme de m\u00eal\u00e9e si vous voulez vous sentir comme un dur \u00e0 cuire. Cette arme est une machette et est l&rsquo;une des armes libres avec le plus de d\u00e9g\u00e2ts. Le seul inconv\u00e9nient est qu&rsquo;il est \u00e0 un point d&rsquo;avoir une dissimulation parfaite.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9g\u00e2ts : 70(450)<\/li>\n\n\n\n<li>Renversement\u00a0: 70 (450)<\/li>\n\n\n\n<li>Temps de charge : 4 secondes<\/li>\n\n\n\n<li>Port\u00e9e\u00a0: 225<\/li>\n\n\n\n<li>Dissimulation : 29<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-electrical-brass-knuckles\">Electrical Brass Knuckles <\/h3>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/electric-brass-knuckles-1024x564.png\" alt=\"bruss knuckles avec charge &#xE9;lectrique en cours de livraison\" class=\"wp-image-5822\"\/><\/figure>\n\n<p>Les coups de poing \u00e9lectriques en laiton ont des d\u00e9g\u00e2ts lents mais \u00e9changent un effet b\u00e9n\u00e9fique. Chaque ennemi touch\u00e9 est \u00e9lectrocut\u00e9 et leurs actions sont interrompues.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9g\u00e2ts : 20<\/li>\n\n\n\n<li>Renversement\u00a0: 20<\/li>\n\n\n\n<li>Temps de charge : 2 secondes<\/li>\n\n\n\n<li>Port\u00e9e\u00a0: 200<\/li>\n\n\n\n<li>Dissimulation : 30 <\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-pounder\">Pounder<\/h3>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/DqtO47N4VdDtrNTk02sR8CMnMrLPrseyNQq7adiJu9liUeEML-_UsabB0lgJGaLU5Gq6IObHkaSfezFu6KLPUmI-KniiG9MqXQcBYO7s-adpdZXJWQg5fh4Famb-cwE7vUvBkBU6KtKST1km7nZadCM\" alt=\"Pistolet &#xE0; clous Pounder pour un chargement complet en m&#xEA;l&#xE9;e sur salaire 2\"\/><\/figure>\n\n<p>Le Pounder est un pistolet \u00e0 clous avec des d\u00e9g\u00e2ts importants mais un temps de rechargement lent et pas une excellente dissimulation mais extr\u00eamement amusant \u00e0 utiliser. Cette arme fait partie de l&rsquo;objet Wolf Pack.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9g\u00e2ts : 70 (450)<\/li>\n\n\n\n<li>Renversement\u00a0: 70 (450)<\/li>\n\n\n\n<li>Temps de charge : 4 secondes<\/li>\n\n\n\n<li>Port\u00e9e\u00a0: 200<\/li>\n\n\n\n<li>Dissimulation : 27<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-primary-and-secondary-weapons-should-you-add-to-your-melee-build\">Quelles armes primaires et secondaires devriez-vous ajouter \u00e0 votre build de m\u00eal\u00e9e\u00a0?<\/h2>\n\n<p>Les armes que vous s\u00e9lectionnez pour cette version sont pour la plupart sans importance. Nous vous recommandons d&rsquo;apporter des armes \u00e0 dissimulation \u00e9lev\u00e9e afin que vous puissiez remplir autant d&rsquo;objectifs que possible avant d&rsquo;alerter les gardes. Si vous finissez par vraiment favoriser la dissimulation, nous avons \u00e9galement un guide de la <a href=\"https:\/\/fpschampion.com\/fr\/meilleure-version-furtive-de-payday-2-en-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">meilleure version furtive de Payday 2<\/a> \u00e0 consid\u00e9rer.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-best-perk-decks-for-melee-builds-in-payday-2\">Meilleurs decks d&rsquo;avantages pour les constructions de m\u00eal\u00e9e dans Payday 2<\/h2>\n\n<p>Choisir le bon Perk Deck pour ce type de construction jouera un r\u00f4le \u00e9norme car il vous donnera des effets passifs qui am\u00e9lioreront consid\u00e9rablement vos chances de survie avec ce type de style de jeu.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-infiltrator\">Agent infiltr\u00e9<\/h3>\n\n<p>L&rsquo;Infiltrateur est un sp\u00e9cialiste du combat rapproch\u00e9 avec des statistiques am\u00e9lior\u00e9es pour les joueurs proches des ennemis.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Overdog\u00a0: 12\u00a0% de d\u00e9g\u00e2ts en moins lorsqu&rsquo;il est entour\u00e9 de trois ennemis ou plus<\/li>\n\n\n\n<li>Casse-casque\u00a0: 25\u00a0% de d\u00e9g\u00e2ts par tir \u00e0 la t\u00eate<\/li>\n\n\n\n<li>Blendin In: 1+ dissimulation, la vitesse de d\u00e9placement est moins affect\u00e9e de 15% si le joueur utilise une armure et 45% d&rsquo;XP suppl\u00e9mentaire apr\u00e8s avoir termin\u00e9 des jours et des travaux<\/li>\n\n\n\n<li>Combat rapproch\u00e9 avanc\u00e9\u00a0: 8\u00a0% de d\u00e9g\u00e2ts en moins si le joueur est \u00e0 distance moyenne des ennemis<\/li>\n\n\n\n<li>Drain de vie : effectuer une attaque au corps \u00e0 corps r\u00e9g\u00e9n\u00e8re 20 % de la sant\u00e9 des joueurs. Il se produit toutes les 10 secondes<\/li>\n<\/ul>\n\n<p>Voici quelques avantages de l&rsquo;utilisation de ce Perk Deck pour cette classe.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-sociopath\">sociopathe<\/h3>\n\n<p>Cet avantage partage certaines similitudes avec le deck Infiltrator Perk, mais la diff\u00e9rence est que celui-ci profite \u00e0 l&rsquo;armure du joueur.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Overdog\u00a0: 12\u00a0% de d\u00e9g\u00e2ts en moins lorsqu&rsquo;il est entour\u00e9 de trois ennemis ou plus<\/li>\n\n\n\n<li>Casse-casque\u00a0: 25\u00a0% de d\u00e9g\u00e2ts par tir \u00e0 la t\u00eate<\/li>\n\n\n\n<li>Tension : Tuer un ennemi r\u00e9g\u00e9n\u00e8re 30 % d&rsquo;armure en plus. Il se produit toutes les 1 seconde. Le joueur gagne \u00e9galement 10% d&rsquo;armure suppl\u00e9mentaire<\/li>\n\n\n\n<li>Blendin In: 1+ dissimulation, la vitesse de d\u00e9placement est moins affect\u00e9e de 15% si le joueur utilise une armure et 45% d&rsquo;XP suppl\u00e9mentaire apr\u00e8s avoir termin\u00e9 des jours et des travaux<\/li>\n\n\n\n<li>Clean Hit: Tuer un ennemi avec une arme de m\u00eal\u00e9e r\u00e9g\u00e9n\u00e8re 10% de sant\u00e9. Lorsque le joueur est \u00e0 moyenne distance des ennemis, il subit 8% de d\u00e9g\u00e2ts en moins<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-yakuza\">Yakuza<\/h3>\n\n<p>Le Yakuza Perk Deck est con\u00e7u pour les loups risqu\u00e9s et solitaires et profitera principalement aux joueurs avec peu de d\u00e9g\u00e2ts.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Si le joueur a une sant\u00e9 faible, le taux de r\u00e9cup\u00e9ration d&rsquo;armure augmentera. Si la sant\u00e9 d&rsquo;un joueur est inf\u00e9rieure \u00e0 25%, le joueur gagnera jusqu&rsquo;\u00e0 20% de taux de r\u00e9cup\u00e9ration d&rsquo;armure<\/li>\n\n\n\n<li>Casse-casque\u00a0: 25\u00a0% de d\u00e9g\u00e2ts par tir \u00e0 la t\u00eate<\/li>\n\n\n\n<li>Hebi Irezumi : Plus la sant\u00e9 est faible, plus le joueur gagne en vitesse de d\u00e9placement. Si la sant\u00e9 est inf\u00e9rieure \u00e0 25%, le joueur gagnera jusqu&rsquo;\u00e0 20% de vitesse de d\u00e9placement<\/li>\n\n\n\n<li>Oni Irezumi\u00a0: tous les effets d&rsquo;\u00e9tat de berserker dans ce deck d&rsquo;avantages commenceront \u00e0 50\u00a0%  <\/li>\n\n\n\n<li>Bonus d&rsquo;ach\u00e8vement de deck : la possibilit\u00e9 d&rsquo;obtenir un objet de meilleure qualit\u00e9 au cours d&rsquo;une mission est augment\u00e9e de 10 %.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-best-skills-for-melee-builds-in-payday-2\">Meilleures comp\u00e9tences pour les constructions de m\u00eal\u00e9e dans Payday 2<\/h2>\n\n<p>Les comp\u00e9tences donneront \u00e9galement aux joueurs des avantages sp\u00e9cifiques en fonction de leur style de jeu.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-counterstrike\">Counter Strike<\/h3>\n\n<p>Vous pouvez contre-attaquer les ennemis et les renverser si vous chargez votre arme de m\u00eal\u00e9e.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-berserker\">Berserker<\/h3>\n\n<p>Si votre sant\u00e9 est faible, vous infligerez plus de d\u00e9g\u00e2ts avec n&rsquo;importe quelle arme de m\u00eal\u00e9e.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-martial-arts\">Martial Arts<\/h3>\n\n<p>50\u00a0% de d\u00e9g\u00e2ts en moins des attaques de m\u00eal\u00e9e et les chances d&rsquo;abattre un ennemi sont augment\u00e9es.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-bloodthirst\">Bloodthirst<\/h3>\n\n<p>Chaque kill augmente les d\u00e9g\u00e2ts de 100% de votre prochaine attaque de m\u00eal\u00e9e jusqu&rsquo;\u00e0 un maximum de 1600%<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-pumping-iron\">Fer \u00e0 pomper<\/h3>\n\n<p>Les attaques de m\u00eal\u00e9e contre des ennemis non sp\u00e9ciaux font plus de d\u00e9g\u00e2ts.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-second-wind\">Second Wind<\/h3>\n\n<p>Si votre armure se brise, la vitesse de d\u00e9placement sera augment\u00e9e de 30% pendant cinq secondes vous permettant d&rsquo;\u00e9chapper \u00e0 des situations compliqu\u00e9es.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-iron-man\">Iron Man<\/h3>\n\n<p>La valeur totale de l&rsquo;armure est augment\u00e9e de 30 %. C&rsquo;est g\u00e9nial et vous permettra de subir plus de d\u00e9g\u00e2ts lorsque vous basculerez notre meilleure version de m\u00eal\u00e9e Payday 2.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-best-equipment-and-throwables-for-melee-builds-in-payday-2\">Meilleur \u00e9quipement et jetables pour les constructions de m\u00eal\u00e9e dans Payday 2<\/h2>\n\n<p>L&rsquo;\u00e9quipement, comme les sacs de ravitaillement et les objets jetables, d\u00e9pend principalement de vos pr\u00e9f\u00e9rences personnelles. Ici, nous vous recommanderons ce qui a fonctionn\u00e9 pour nous.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/h39mR8BQr9oM830iDbp3s2wJsE_FHttDaDdYNsNudlbYNXLeReYxtxdNOaIQMosBmnzUJbLYZHkHgOxxCkwYHmkxzcohkWxOh77VPqdLUXwSNMuonHUHTXRl-WpARXl053NVOQ8CFayC3J3lxNgt3qY\" alt=\"\"\/><\/figure>\n\n<h3 class=\"wp-block-heading\" id=\"h-doctor-armor-bag\">Docteur\/Armure Sac<\/h3>\n\n<p>Le sac m\u00e9decin ou armure vous permettra de refaire le plein de sant\u00e9 ou d&rsquo;armure si besoin.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-sentry-gun\">Mitrailleuse :<\/h3>\n\n<p>Le Sentry Gun fournira une couverture en tirant automatiquement sur vos ennemis. Le Sentry Gun utilisera des munitions de votre r\u00e9serve et peut \u00eatre d\u00e9truit.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-ecm-jammer\">Brouilleur ECM<\/h3>\n\n<p>Une fois plac\u00e9, le brouilleur ECM peut neutraliser les ennemis dans un certain rayon. Le brouilleur ECM ne peut \u00eatre utilis\u00e9 qu&rsquo;une seule fois.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-concussion-smoke-grenade\">Commotion c\u00e9r\u00e9brale \/ Grenade fumig\u00e8ne<\/h3>\n\n<p>Quoi que vous choisissiez parmi ces deux grenades, cela vous aidera \u00e0 \u00e9tourdir ou \u00e0 aveugler vos ennemis afin que vous puissiez r\u00e9duire la distance entre vous et eux.<\/p>\n\n<h2 class=\"wp-block-heading\">Conclusion de notre meilleur guide de construction de Payday 2 Melee<\/h2>\n\n<p>Ce type de construction de m\u00eal\u00e9e peut \u00eatre extr\u00eamement amusant \u00e0 jouer dans Payday 2 mais difficile en m\u00eame temps. Nous vous conseillons de commencer avec des difficult\u00e9s moindres, surtout si vous n&rsquo;\u00eates pas un joueur exp\u00e9riment\u00e9 de Payday 2. Nous esp\u00e9rons que vous avez trouv\u00e9 ce guide utile et, plus important encore, nous esp\u00e9rons que vous vous amuserez beaucoup \u00e0 jouer lors de vos braquages.<\/p>\n\n<p>Pour d&rsquo;autres super chargements, consultez notre <a href=\"https:\/\/fpschampion.com\/fr\/meilleure-construction-dodge-payday-2-en-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">meilleure version d&rsquo;esquive de Payday 2<\/a> ! \u00catre super agile peut \u00eatre assez amusant mais difficile \u00e0 r\u00e9aliser. Pour des chargements encore plus int\u00e9ressants, consultez notre <a href=\"https:\/\/fpschampion.com\/fr\/5-des-meilleurs-builds-payday-2-mise-a-jour-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">liste des 5 meilleures versions de Payday 2<\/a> . Cela vous incitera sans aucun doute \u00e0 essayer de nouvelles combinaisons d&rsquo;armes et d&rsquo;avantages\u00a0!<\/p>\n\n<p>Bonne chance, bon braquage\u00a0!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Payday 2 est un jeu coop\u00e9ratif PvE exceptionnel qui permet aux joueurs d&rsquo;y jouer comme bon leur semble. Si vous voulez faire flamber des armes \u00e0 feu, vous le pouvez; coup d&rsquo;oeil sournois? Tu l&rsquo;as eu; ou frappez-vous simplement tous ceux qui croisent votre chemin\u00a0? Bien s\u00fbr vous pouvez! Payday 2 est un jeu plein<\/p>\n","protected":false},"author":11,"featured_media":16865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[580],"tags":[1105],"platform":[653,946,647,635,648],"class_list":{"0":"post-31001","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-article-en-vedette","8":"tag-payday-2-fr","9":"platform-changer","10":"platform-linux-fr","11":"platform-playstation-4-fr","12":"platform-windowsos-fr","13":"platform-xbox-one-fr"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Meilleure construction de Payday 2 Melee en 2023 | FPS Champion<\/title>\n<meta name=\"description\" content=\"Vous aimez vous battre de pr\u00e8s et personnellement? Nous avons la meilleure version de m\u00eal\u00e9e de Payday 2 pour 2023 qui inclut des am\u00e9liorations et des consid\u00e9rations modernes !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meilleure construction de Payday 2 Melee en 2023\" \/>\n<meta property=\"og:description\" content=\"Vous aimez vous battre de pr\u00e8s et personnellement? Nous avons la meilleure version de m\u00eal\u00e9e de Payday 2 pour 2023 qui inclut des am\u00e9liorations et des consid\u00e9rations modernes !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-24T02:55:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T05:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Best-Melee-Build-in-Payday-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andres Berumen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Berumen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/\"},\"author\":{\"name\":\"Andres Berumen\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/ce8e606ef4255323f19a32c6c4dd42e1\"},\"headline\":\"Meilleure construction de Payday 2 Melee en 2023\",\"datePublished\":\"2022-08-24T02:55:35+00:00\",\"dateModified\":\"2023-06-04T05:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/\"},\"wordCount\":1723,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Best-Melee-Build-in-Payday-2.png\",\"keywords\":[\"Payday 2\"],\"articleSection\":[\"Article en Vedette\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/\",\"name\":\"Meilleure construction de Payday 2 Melee en 2023 | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Best-Melee-Build-in-Payday-2.png\",\"datePublished\":\"2022-08-24T02:55:35+00:00\",\"dateModified\":\"2023-06-04T05:54:29+00:00\",\"description\":\"Vous aimez vous battre de pr\u00e8s et personnellement? Nous avons la meilleure version de m\u00eal\u00e9e de Payday 2 pour 2023 qui inclut des am\u00e9liorations et des consid\u00e9rations modernes !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Best-Melee-Build-in-Payday-2.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Best-Melee-Build-in-Payday-2.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/meilleure-construction-de-payday-2-melee-en-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meilleure construction de Payday 2 Melee en 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/ce8e606ef4255323f19a32c6c4dd42e1\",\"name\":\"Andres Berumen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g\",\"caption\":\"Andres Berumen\"},\"description\":\"Andres Berumen is a passionate gamer, writer, and future game designer. Andres has participated in several gaming events such as semi-professional tournaments for Rainbow Six: Siege and one-life matches for games like Squad. His favorite food is tacos.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/author\\\/ramentheprofessional\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Meilleure construction de Payday 2 Melee en 2023 | FPS Champion","description":"Vous aimez vous battre de pr\u00e8s et personnellement? Nous avons la meilleure version de m\u00eal\u00e9e de Payday 2 pour 2023 qui inclut des am\u00e9liorations et des consid\u00e9rations modernes !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Meilleure construction de Payday 2 Melee en 2023","og_description":"Vous aimez vous battre de pr\u00e8s et personnellement? Nous avons la meilleure version de m\u00eal\u00e9e de Payday 2 pour 2023 qui inclut des am\u00e9liorations et des consid\u00e9rations modernes !","og_url":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/","og_site_name":"FPS Champion","article_published_time":"2022-08-24T02:55:35+00:00","article_modified_time":"2023-06-04T05:54:29+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Best-Melee-Build-in-Payday-2.png","type":"image\/png"}],"author":"Andres Berumen","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Andres Berumen","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/"},"author":{"name":"Andres Berumen","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/ce8e606ef4255323f19a32c6c4dd42e1"},"headline":"Meilleure construction de Payday 2 Melee en 2023","datePublished":"2022-08-24T02:55:35+00:00","dateModified":"2023-06-04T05:54:29+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/"},"wordCount":1723,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Best-Melee-Build-in-Payday-2.png","keywords":["Payday 2"],"articleSection":["Article en Vedette"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/","url":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/","name":"Meilleure construction de Payday 2 Melee en 2023 | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Best-Melee-Build-in-Payday-2.png","datePublished":"2022-08-24T02:55:35+00:00","dateModified":"2023-06-04T05:54:29+00:00","description":"Vous aimez vous battre de pr\u00e8s et personnellement? Nous avons la meilleure version de m\u00eal\u00e9e de Payday 2 pour 2023 qui inclut des am\u00e9liorations et des consid\u00e9rations modernes !","breadcrumb":{"@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Best-Melee-Build-in-Payday-2.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Best-Melee-Build-in-Payday-2.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/fr\/meilleure-construction-de-payday-2-melee-en-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Meilleure construction de Payday 2 Melee en 2023"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/fr\/#website","url":"https:\/\/fpschampion.com\/fr\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/fr\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/ce8e606ef4255323f19a32c6c4dd42e1","name":"Andres Berumen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/86577d2b804269bfdff1650116b8237f6f29da203bac78d6c0b3613ca86373ab?s=96&d=mm&r=g","caption":"Andres Berumen"},"description":"Andres Berumen is a passionate gamer, writer, and future game designer. Andres has participated in several gaming events such as semi-professional tournaments for Rainbow Six: Siege and one-life matches for games like Squad. His favorite food is tacos.","url":"https:\/\/fpschampion.com\/fr\/author\/ramentheprofessional\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/comments?post=31001"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31001\/revisions"}],"predecessor-version":[{"id":31007,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/31001\/revisions\/31007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media\/16865"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media?parent=31001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/categories?post=31001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/tags?post=31001"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/platform?post=31001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}