{"id":29246,"date":"2023-04-06T05:13:18","date_gmt":"2023-04-06T05:13:18","guid":{"rendered":"https:\/\/fpschampion.com\/guide-complet-des-debutants-sombres-et-plus-sombres\/"},"modified":"2023-06-04T00:15:11","modified_gmt":"2023-06-04T00:15:11","slug":"guide-complet-des-debutants-sombres-et-plus-sombres","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/","title":{"rendered":"Guide complet des d\u00e9butants sombres et plus sombres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dark and Darker est un dungeon-crawler PvPvE brutal et hardcore inspir\u00e9 des mondes et de la narration fantastiques classiques des ann\u00e9es 90. Rassemblez vos amis ou aventurez-vous seul dans des donjons sombres \u00e0 la recherche de butin, de tr\u00e9sors et bien plus encore, tout en combattant des hordes de morts-vivants ou d&rsquo;autres cr\u00e9atures mythiques. <\/p>\n\n<p class=\"wp-block-paragraph\">Dark and Darker est un jeu difficile, surtout si vous \u00eates nouveau dans les jeux de looter d&rsquo;extraction tels que Escape from Tarkov ou Hunt: Showdown, il est donc naturel de sortir de votre premi\u00e8re manche ensanglant\u00e9 et vaincu.<\/p>\n\n<p class=\"wp-block-paragraph\">Comprendre l&rsquo;objectif, le combat et la boucle de jeu globale du jeu est un peu complexe car Dark and Darker n&rsquo;a pas de didacticiel appropri\u00e9. Ce guide du d\u00e9butant Dark and Darker vous aidera \u00e0 expliquer tous les d\u00e9tails et informations essentiels pour commencer votre aventure.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-choosing-a-class\">Choisir une classe<\/h2>\n\n<p class=\"wp-block-paragraph\">Avant de vous lancer dans le donjon, vous devez choisir une classe. Le choix d&rsquo;une classe est important, non seulement pour le type de butin que vous souhaitez acqu\u00e9rir et leurs diff\u00e9rences de combat et d&rsquo;autres capacit\u00e9s. Ce jeu utilise un syst\u00e8me RPG classique similaire \u00e0 D&amp;D, avec des personnages de m\u00eal\u00e9e et \u00e0 distance utilisant des d\u00e9g\u00e2ts physiques ou magiques.<\/p>\n\n<p class=\"wp-block-paragraph\">Vos options pour les cours sont les suivantes\u00a0:<\/p>\n\n<h3 class=\"wp-block-heading\">Combattant<\/h3>\n\n<p class=\"wp-block-paragraph\">Le combattant est une excellente classe de m\u00eal\u00e9e polyvalente car il peut utiliser presque toutes les armures ou armes du jeu. Ils ont la plus grande vari\u00e9t\u00e9 de constructions, ce qui en fait des adversaires agiles ou tanky. Ils constituent une excellente classe polyvalente, mais ma\u00eetre de rien. Si cela vous convient parfaitement, en particulier au d\u00e9but, nous vous recommandons de consulter notre <a href=\"https:\/\/fpschampion.com\/fr\/dark-and-darker-construction-et-guide-polyvalents-de-chasseurs-de-remparts\/\" target=\"_blank\" rel=\"noreferrer noopener\">version polyvalente de Dark and Darker Fighter<\/a> .<\/p>\n\n<h3 class=\"wp-block-heading\">Voyou<\/h3>\n\n<p class=\"wp-block-paragraph\">Le Rogue est une classe de m\u00eal\u00e9e agile qui porte une armure l\u00e9g\u00e8re mais utilise les poisons et la furtivit\u00e9 \u00e0 son avantage. Ils ont une vitesse d&rsquo;interaction extr\u00eamement \u00e9lev\u00e9e, ce qui leur permet d&rsquo;ouvrir les portes et les coffres plus rapidement. Ils ont \u00e9galement des crochets illimit\u00e9s pour tous les coffres que vous rencontrez et des poisons pour r\u00e9duire les ennemis.<\/p>\n\n<p class=\"wp-block-paragraph\">Ex\u00e9cuter une <a href=\"https:\/\/fpschampion.com\/fr\/construction-et-guide-detailles-de-dark-and-darker-rogue\/\" target=\"_blank\" rel=\"noreferrer noopener\">construction de voyou assassin dans Dark and Darker<\/a> est un excellent moyen d&rsquo;infliger des d\u00e9g\u00e2ts massifs \u00e0 une seule cible aux boss et aux ennemis sp\u00e9ciaux.<\/p>\n\n<h3 class=\"wp-block-heading\">Barbare<\/h3>\n\n<p class=\"wp-block-paragraph\">Le barbare est lent mais puissant. Ils sont l&rsquo;une des classes de m\u00eal\u00e9e les plus lentes, mais ils peuvent tirer des classes blind\u00e9es l\u00e9g\u00e8res avec un seul tir \u00e0 la t\u00eate. <a href=\"https:\/\/fpschampion.com\/fr\/guide-de-construction-et-de-classe-des-barbares-sombres-et-plus-sombres\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les meilleures constructions barbares de Dark and Darker<\/a> ont beaucoup de pouvoir destructeur, leur permettant de casser des portes ou des coffres d&rsquo;un seul coup.<\/p>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-1024x576.jpg\" alt=\"Barbare dans Dark and Darker\" class=\"wp-image-10597\" srcset=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-1024x576.jpg 1024w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-300x169.jpg 300w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-768x432.jpg 768w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-1536x864.jpg 1536w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-150x84.jpg 150w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-450x253.jpg 450w, https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Barbarian-Class-Build-in-Dark-and-Darker-Game-1200x675.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\">Clerc<\/h3>\n\n<p class=\"wp-block-paragraph\">Le clerc est le c\u0153ur du groupe, apportant des soins et des buffs \u00e0 son \u00e9quipe. Le clerc porte une armure de plaques mais n&rsquo;a pas un arsenal incroyable pour se d\u00e9fendre. Leur magie de gu\u00e9rison est presque essentielle pour combattre les boss.<\/p>\n\n<h3 class=\"wp-block-heading\">Ranger<\/h3>\n\n<p class=\"wp-block-paragraph\">Le <a href=\"https:\/\/fpschampion.com\/fr\/guide-detaille-de-construction-et-de-classe-de-dark-and-darker-ranger\/\">Ranger<\/a> est une classe \u00e0 distance insaisissable qui se sp\u00e9cialise dans l&rsquo;utilisation d&rsquo;un arc et de fl\u00e8ches. Les Rangers sont la meilleure classe de tireurs d&rsquo;\u00e9lite et peuvent installer des pi\u00e8ges lorsque les adversaires les poussent. Ils apportent \u00e9galement un feu de camp pour aider \u00e0 restaurer la sant\u00e9 et les sorts des clercs et des sorciers.<\/p>\n\n<h3 class=\"wp-block-heading\">Magicien<\/h3>\n\n<p class=\"wp-block-paragraph\">Le magicien est le canon de verre de Dark and Darker. <a href=\"https:\/\/fpschampion.com\/fr\/guide-et-construction-de-lassistant-sombre-et-plus-sombre\/\" target=\"_blank\" rel=\"noreferrer noopener\">La meilleure version de l&rsquo;assistant Dark and Darker<\/a> aura beaucoup de magie de zone d&rsquo;effet et quelques sorts de buff. C&rsquo;est l&rsquo;une des classes les plus difficiles \u00e0 apprendre, avec un gameplay \u00e0 haut risque et \u00e0 haute r\u00e9compense.<\/p>\n\n<p class=\"wp-block-paragraph\">Que vous jouiez en solo ou en groupe, votre d\u00e9cision fait toute la diff\u00e9rence. Outre les compositions d&rsquo;\u00e9quipe, si vous jouez en groupe, nous vous recommandons d&rsquo;avoir un combattant, un clerc et un ranger pour une \u00e9quipe bien \u00e9quilibr\u00e9e. Si vous jouez en solo, nous vous recommandons Fighter car il s&rsquo;agit d&rsquo;une classe polyvalente simple et merveilleuse.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-equipping-perks-and-skills\">\u00c9quiper des avantages et des comp\u00e9tences<\/h2>\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir choisi leur classe, les d\u00e9butants Dark and Dark doivent choisir leurs avantages et leurs capacit\u00e9s passives avant de commencer \u00e0 se soucier de l&rsquo;armure et des armes.<\/p>\n\n<p class=\"wp-block-paragraph\">Les comp\u00e9tences sont naturellement li\u00e9es \u00e0 Q et E et changent le style de jeu de votre classe. Vos comp\u00e9tences n&rsquo;ont g\u00e9n\u00e9ralement aucune limite \u00e0 part quelques comp\u00e9tences comme Second Wind d&rsquo;un combattant. La plupart des comp\u00e9tences, comme un jugement de clerc, n&rsquo;ont aucun co\u00fbt et un temps de recharge de 40 secondes ne fait que le limiter.<\/p>\n\n<p class=\"wp-block-paragraph\">En ce qui concerne vos passifs, vous en obtiendrez plus \u00e0 mesure que vous montez de niveau, mais vous \u00eates limit\u00e9 \u00e0 un lorsque vous cr\u00e9ez votre personnage pour la premi\u00e8re fois. Vos passifs peuvent \u00e9galement modifier votre style de jeu, comme la capacit\u00e9 d&rsquo;un voleur \u00e0 crocheter ou la capacit\u00e9 unique d&rsquo;un barbare \u00e0 d\u00e9foncer les portes.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-guide-to-choosing-the-right-map-gamemode-for-beginners-in-dark-and-darker\">Guide pour choisir la bonne carte\/mode de jeu pour les d\u00e9butants dans Dark and Darker<\/h2>\n\n<p class=\"wp-block-paragraph\">D&rsquo;apr\u00e8s les tests de jeu r\u00e9cents et au moment de la r\u00e9daction, Dark and Darker n&rsquo;a que trois modes. Le ch\u00e2teau oubli\u00e9 est le mode standard du jeu, offrant des butins r\u00e9guliers et permettant \u00e0 des groupes de un \u00e0 trois joueurs de jouer.<\/p>\n\n<p class=\"wp-block-paragraph\">Le second est une version plus difficile du mode Forgotten Castle appel\u00e9 High-Roller, qui n\u00e9cessite de l&rsquo;or pour entrer mais offre de meilleures r\u00e9compenses et objets de valeur.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-goblin-caves\">Grottes gobelines<\/h3>\n\n<p class=\"wp-block-paragraph\">Enfin, le mode le plus r\u00e9cent est The Goblin Caves, qui propose une carte diff\u00e9rente et des ennemis exclusifs aux joueurs solo. Dans l&rsquo;ensemble, nous recommandons la carte Forgotten Castle aux d\u00e9butants de Dark and Darker qui lisent ce guide. Pourtant, si vous ne voulez absolument pas rencontrer de plus grandes \u00e9quipes, restez avec The Goblin Caves.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-finding-gear-and-treasures\">Trouver du mat\u00e9riel et des tr\u00e9sors<\/h2>\n\n<p class=\"wp-block-paragraph\">La principale raison pour laquelle tout le monde plonge dans le donjon est de trouver de meilleurs \u00e9quipements, armes et autres objets de valeur. D\u00e8s que vous d\u00e9marrez une course de donjon, recherchez des coffres et des cercueils et gardez l&rsquo;\u0153il ouvert pour de petits bibelots \u00e9parpill\u00e9s occasionnellement sur le sol des \u00e9tag\u00e8res.<\/p>\n\n<p class=\"wp-block-paragraph\">Si vous avez de la chance, vous trouverez des am\u00e9liorations, et nous vous recommandons d&rsquo;\u00e9quiper imm\u00e9diatement tout ce que vous pouvez porter et de jeter votre seul \u00e9quipement gris sur le sol.<\/p>\n\n<p class=\"wp-block-paragraph\">Dark and Darker suit le format standard de raret\u00e9 des \u00e9l\u00e9ments de couleur RPG que des centaines de jeux utilisent depuis des ann\u00e9es. <\/p>\n\n<p class=\"wp-block-paragraph\">Votre personnage commencera toujours avec des objets gris, mais vous pouvez trouver les \u00e9l\u00e9ments suivants\u00a0:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Commun(Blanc) Pas d&rsquo;enchantement <\/li>\n\n\n\n<li>Inhabituel(Vert) +1 Enchantement <\/li>\n\n\n\n<li>Rare(Bleu) +2 Enchantements<\/li>\n\n\n\n<li>Epic (Violet) +3 Enchantements<\/li>\n\n\n\n<li>L\u00e9gendaire (Orange) +4 Enchantements<\/li>\n\n\n\n<li>Unique (jaune) +5 enchantements<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Outre des dizaines d&rsquo;armes et d&rsquo;\u00e9quipements, vous pouvez trouver de nombreux bibelots et de l&rsquo;or dans la poche arri\u00e8re de l&rsquo;arm\u00e9e de morts-vivants du donjon. Les parchemins, les bracelets en or et bien plus encore peuvent tous \u00eatre \u00e9chang\u00e9s contre de l&rsquo;or \u00e0 la taverne, alors prenez ce que vous pouvez.<\/p>\n\n<p class=\"wp-block-paragraph\">Il est normal de ne pas savoir \u00e0 quel prix chaque fois se vendra, alors prenez note de la quantit\u00e9 d&rsquo;articles sp\u00e9cifiques \u00e9chang\u00e9s afin de pouvoir prioriser ou \u00e9viter des bibelots sp\u00e9cifiques.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-stat-randomization\">Randomisation des statistiques<\/h2>\n\n<p class=\"wp-block-paragraph\">Plus la raret\u00e9 est \u00e9lev\u00e9e, plus l&rsquo;objet est fort, mais ce n&rsquo;est que parfois le cas. Les enchantements sur l&rsquo;\u00e9quipement et les armes sont al\u00e9atoires, et certaines de ses statistiques de base sont \u00e9galement al\u00e9atoires. Par exemple, deux armes de m\u00eame raret\u00e9 peuvent avoir des statistiques de base et des enchantements diff\u00e9rents.<\/p>\n\n<p class=\"wp-block-paragraph\">Cela rend certaines armes plus pr\u00e9cieuses et maintient le syst\u00e8me de butin du jeu un peu plus profond. Une fois que votre inventaire ou votre r\u00e9serve commence \u00e0 se remplir et que vous cherchez \u00e0 vendre une partie de votre \u00e9quipement \u00e0 d&rsquo;autres joueurs, notez les statistiques de vos objets car cela pourrait augmenter le prix.<\/p>\n\n<p class=\"wp-block-paragraph\">Les armes avec +1 \u00e0 tous les attributs ou plus se vendront beaucoup pour les autres joueurs. Cependant, la valeur du march\u00e9 deviendra plus solide une fois que Dark and Darker sera compl\u00e8tement sorti, alors ne vous inqui\u00e9tez pas de conna\u00eetre tous les meilleurs objets \u00e0 vendre lors des premiers tests de jeu.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-escape-the-dungeon\">Comment s&rsquo;\u00e9chapper du donjon<\/h2>\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir rempli votre sac \u00e0 dos de butin et massacr\u00e9 une douzaine de morts-vivants, vous devez <a href=\"https:\/\/fpschampion.com\/fr\/comment-extraire-et-survivre-dans-dark-and-darker\/\" target=\"_blank\" rel=\"noreferrer noopener\">extraire<\/a> pour vous assurer que tout ce butin s&rsquo;en sortira. Comme il s&rsquo;agit d&rsquo;un jeu hardcore, tout votre butin reste sur votre corps si votre personnage meurt pendant une course. Trouver un portail et l&rsquo;extraire est le seul moyen de garantir votre butin.<\/p>\n\n<p class=\"wp-block-paragraph\">Contrairement \u00e0 <a href=\"https:\/\/fpschampion.com\/fr\/tag\/evadez-vous-de-tarkov\/\" target=\"_blank\" rel=\"noreferrer noopener\">Escape from Tarkov<\/a> , Dark and Darker a un anneau qui enferme lentement le donjon comme la temp\u00eate dans Fortnite. Une fois que le cercle devient plus petit \u00e0 la fin d&rsquo;une course, des portails bleus et rouges appara\u00eetront autour de la carte. Les portails bleus apparaissent individuellement et en ouvrir un vous ram\u00e8nera \u00e0 la taverne.<\/p>\n\n<p class=\"wp-block-paragraph\">Si vous prenez un portail rouge, vous irez plus loin dans le donjon, augmentant la difficult\u00e9 des ennemis et les chances de r\u00e9compenses rares. Si vous prenez le portail rouge, vous pouvez \u00e9galement combattre des boss extr\u00eamement difficiles, mais les portails bleus apparaissent au centre de l&rsquo;anneau si vous survivez. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-dark-and-darker-beginners-must-overcome-pvp-encounters\">Les d\u00e9butants sombres et plus sombres doivent surmonter les rencontres PvP<\/h2>\n\n<p class=\"wp-block-paragraph\">Enfin, Dark and Darker est un jeu PvPvE, et d&rsquo;autres joueurs se prom\u00e8nent \u00e9galement dans ce donjon sombre \u00e0 la recherche du m\u00eame tr\u00e9sor que vous recherchez. Parfois, vous pouvez persuader d&rsquo;autres aventuriers avec le chat vocal du jeu, mais la plupart recherchent un combat.<\/p>\n\n<p class=\"wp-block-paragraph\">La grande diff\u00e9rence entre le PvP et le PvE est que les monstres ont tendance \u00e0 \u00eatre pr\u00e9visibles, et vous pouvez faire la diff\u00e9rence entre un monstre et un joueur ennemi en raison de leurs mouvements et du bruit de leurs pas.<\/p>\n\n<p class=\"wp-block-paragraph\">Le PvP peut \u00eatre difficile, mais c&rsquo;est aussi le point central de l&rsquo;exp\u00e9rience Dark and Darker, alors choisissez de vous engager dans autant ou aussi peu de combats que possible. Vous pouvez charger t\u00eate baiss\u00e9e dans le combat ou \u00e9viter les autres joueurs au mieux de vos capacit\u00e9s. Cependant, une fois que vous vous serez familiaris\u00e9 avec les classes de Dark and Darker, vous saurez exactement \u00e0 quoi vous faites face.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wrap-up-on-our-beginners-guide-for-dark-and-darker\">R\u00e9capitulez sur notre guide du d\u00e9butant pour Dark and Darker<\/h2>\n\n<p class=\"wp-block-paragraph\">C&rsquo;est notre petit guide du d\u00e9butant pour Dark and Darker. Dans l&rsquo;ensemble, ce robot d&rsquo;exploration de donjon brutal est l&rsquo;un des jeux les plus m\u00e9diatis\u00e9s de l&rsquo;ann\u00e9e \u00e9coul\u00e9e, et nous ne pouvons pas attendre sa sortie compl\u00e8te pour pouvoir parcourir les profondeurs sans restriction de temps. <\/p>\n\n<p class=\"wp-block-paragraph\">Si vous avez appr\u00e9ci\u00e9 notre aper\u00e7u du jeu et que vous souhaitez en savoir plus, consultez notre autre guide sur <a href=\"https:\/\/fpschampion.com\/fr\/comment-lancer-des-sorts-dans-dark-and-darker\/\" target=\"_blank\" rel=\"noreferrer noopener\">la fa\u00e7on de lancer des sorts dans Dark and Darker<\/a> . <\/p>\n\n<p class=\"wp-block-paragraph\">Pour l&rsquo;instant, bonne chasse !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dark and Darker est un dungeon-crawler PvPvE brutal et hardcore inspir\u00e9 des mondes et de la narration fantastiques classiques des ann\u00e9es 90. Rassemblez vos amis ou aventurez-vous seul dans des donjons sombres \u00e0 la recherche de butin, de tr\u00e9sors et bien plus encore, tout en combattant des hordes de morts-vivants ou d&rsquo;autres cr\u00e9atures mythiques. Dark<\/p>\n","protected":false},"author":6,"featured_media":24021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[632],"tags":[901],"platform":[635],"class_list":["post-29246","post","type-post","status-publish","format-standard","has-post-thumbnail","category-guides-fr","tag-sombre-et-plus-sombre","platform-windowsos-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Guide complet des d\u00e9butants sombres et plus sombres | FPS Champion<\/title>\n<meta name=\"description\" content=\"Lisez la suite pour trouver tout ce que vous devez savoir pour bien faire en tant que d\u00e9butant Dark and Darker dans ce guide d\u00e9taill\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide complet des d\u00e9butants sombres et plus sombres\" \/>\n<meta property=\"og:description\" content=\"Lisez la suite pour trouver tout ce que vous devez savoir pour bien faire en tant que d\u00e9butant Dark and Darker dans ce guide d\u00e9taill\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T05:13:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T00:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Dark-and-Darker-Beginners.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1576\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Guide complet des d\u00e9butants sombres et plus sombres\",\"datePublished\":\"2023-04-06T05:13:18+00:00\",\"dateModified\":\"2023-06-04T00:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/\"},\"wordCount\":1930,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Dark-and-Darker-Beginners.jpg\",\"keywords\":[\"Sombre et plus sombre\"],\"articleSection\":[\"Guides\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/\",\"name\":\"Guide complet des d\u00e9butants sombres et plus sombres | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Dark-and-Darker-Beginners.jpg\",\"datePublished\":\"2023-04-06T05:13:18+00:00\",\"dateModified\":\"2023-06-04T00:15:11+00:00\",\"description\":\"Lisez la suite pour trouver tout ce que vous devez savoir pour bien faire en tant que d\u00e9butant Dark and Darker dans ce guide d\u00e9taill\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Dark-and-Darker-Beginners.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Dark-and-Darker-Beginners.jpg\",\"width\":1576,\"height\":899},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/guide-complet-des-debutants-sombres-et-plus-sombres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guide complet des d\u00e9butants sombres et plus sombres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/fr\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Guide complet des d\u00e9butants sombres et plus sombres | FPS Champion","description":"Lisez la suite pour trouver tout ce que vous devez savoir pour bien faire en tant que d\u00e9butant Dark and Darker dans ce guide d\u00e9taill\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/","og_locale":"fr_FR","og_type":"article","og_title":"Guide complet des d\u00e9butants sombres et plus sombres","og_description":"Lisez la suite pour trouver tout ce que vous devez savoir pour bien faire en tant que d\u00e9butant Dark and Darker dans ce guide d\u00e9taill\u00e9.","og_url":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/","og_site_name":"FPS Champion","article_published_time":"2023-04-06T05:13:18+00:00","article_modified_time":"2023-06-04T00:15:11+00:00","og_image":[{"width":1576,"height":899,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Dark-and-Darker-Beginners.jpg","type":"image\/jpeg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jake Butala","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Guide complet des d\u00e9butants sombres et plus sombres","datePublished":"2023-04-06T05:13:18+00:00","dateModified":"2023-06-04T00:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/"},"wordCount":1930,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Dark-and-Darker-Beginners.jpg","keywords":["Sombre et plus sombre"],"articleSection":["Guides"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/","url":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/","name":"Guide complet des d\u00e9butants sombres et plus sombres | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Dark-and-Darker-Beginners.jpg","datePublished":"2023-04-06T05:13:18+00:00","dateModified":"2023-06-04T00:15:11+00:00","description":"Lisez la suite pour trouver tout ce que vous devez savoir pour bien faire en tant que d\u00e9butant Dark and Darker dans ce guide d\u00e9taill\u00e9.","breadcrumb":{"@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Dark-and-Darker-Beginners.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Dark-and-Darker-Beginners.jpg","width":1576,"height":899},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/fr\/guide-complet-des-debutants-sombres-et-plus-sombres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Guide complet des d\u00e9butants sombres et plus sombres"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/fr\/#website","url":"https:\/\/fpschampion.com\/fr\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/fr\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/fr\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/fr\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/29246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/comments?post=29246"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/29246\/revisions"}],"predecessor-version":[{"id":29255,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/posts\/29246\/revisions\/29255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media\/24021"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/media?parent=29246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/categories?post=29246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/tags?post=29246"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/fr\/wp-json\/wp\/v2\/platform?post=29246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}