{"id":31980,"date":"2022-04-14T04:43:15","date_gmt":"2022-04-14T04:43:15","guid":{"rendered":"https:\/\/fpschampion.com\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/"},"modified":"2023-06-04T06:03:15","modified_gmt":"2023-06-04T06:03:15","slug":"todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/","title":{"rendered":"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Para sorpresa y asombro de la comunidad de Halo, 343 le dio a Halo MCC una actualizaci\u00f3n masiva con Floodfight Update. Muchos no esperaban esta actualizaci\u00f3n, especialmente porque Halo Infinite est\u00e1 programada para su segunda temporada a principios de mayo. Si bien esta actualizaci\u00f3n se burl\u00f3 de agregar m\u00e1s contenido nuevo para ODST Firefight, este parche tambi\u00e9n trajo muchos cambios adicionales.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-the-flood-returns\">El diluvio regresa<\/h2>\n\n<p class=\"wp-block-paragraph\">El enfoque principal de esta actualizaci\u00f3n se deriva del modo de juego Firefight basado en olas de Halo ODST. Todas las diferentes formas de Flood han llegado a Firefight, junto con algunas condiciones y mec\u00e1nicas completamente nuevas que nunca se incluyeron en el lanzamiento original del juego. El civil infectado, ODST y Elite Major se introdujeron recientemente en este modo. El Elite Major fue tra\u00eddo de vuelta mientras luc\u00eda su ic\u00f3nica armadura roja y escudos de energ\u00eda.<\/p>\n\n<p class=\"wp-block-paragraph\">Junto con estos enemigos adicionales, los jugadores muertos de ODST pueden ser infectados y resucitados por el Flood por primera vez en la historia de Halo. Todos los jugadores infectados regresan de la tumba con sus armas anteriores, lo que los convierte en una amenaza extra poderosa si ten\u00edas algo parecido a un lanzacohetes cuando moriste. Estas nuevas olas de inundaci\u00f3n tambi\u00e9n afectan el mapa en s\u00ed cada vez que ingresas a uno.<\/p>\n\n<p class=\"wp-block-paragraph\">El Diluvio aparece con una densa niebla verde que crea momentos m\u00e1s espeluznantes y atmosf\u00e9ricos como las misiones de campa\u00f1as anteriores. En esta actualizaci\u00f3n de \u00abFloodfight\u00bb para Halo, el Flood incluso trae peligros \u00fanicos como Flood Stalkers y cae desde el cielo con Flood Dispersal Pods. Por primera vez desde Halo 2, el Flood puede controlar veh\u00edculos nuevamente, adem\u00e1s de poder manejar torretas junto con varias animaciones recientemente agregadas.<\/p>\n\n<h2 class=\"wp-block-heading\">Actualizaciones de jugadores que vienen en esta actualizaci\u00f3n de Halo Master Chief Collection<\/h2>\n\n<p class=\"wp-block-paragraph\">Los Flood no son los \u00fanicos que reciben nuevas caracter\u00edsticas; se han agregado bastantes cambios para los jugadores. Por primera vez, los jugadores podr\u00e1n usar Energy Sword y Sentinel Beam en ODST. Los jugadores ahora pueden usar el mapa VISR para ver las ubicaciones de los enemigos, incluso mientras esperan para reaparecer. Los Flood no son los \u00fanicos agregados a Firefight; Los enemigos de \u00e9lite se pueden encontrar en las nuevas oleadas variantes.<\/p>\n\n<p class=\"wp-block-paragraph\">Los jugadores pueden obtener \u00abbendiciones\u00bb en diferentes mapas, como bastidores de armas que contienen rifles de batalla y rifles de asalto que no se incluyeron en el lanzamiento original de Halo 3: ODST. Algunos mapas incluyen lanzallamas, infantes de marina y oficiales de NMPD para ayudar a combatir el Flood. En las misiones nocturnas, las \u00e9lites aliadas llegan a trav\u00e9s de c\u00e1psulas de inserci\u00f3n para ayudarte contra el Flood.<\/p>\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se han importado un pu\u00f1ado de correcciones y mejoras a Halo: Reach. Un cambio notable es que los marines aliados en la Instalaci\u00f3n 04 ahora pueden ser desalojados de los veh\u00edculos y puedes intercambiar armas con ellos, al igual que en la campa\u00f1a.<\/p>\n\n<h2 class=\"wp-block-heading\">Personalizaci\u00f3n de la campa\u00f1a de Halo 4 en la actualizaci\u00f3n de Floodfight para Halo TMCC<\/h2>\n\n<p class=\"wp-block-paragraph\">Un cambio peque\u00f1o pero bienvenido es la personalizaci\u00f3n adicional de la m\u00e1scara que se agrega a la campa\u00f1a de Halo 4. Las m\u00e1scaras que ha ganado a trav\u00e9s de los pases de temporada gratuitos de Halo MCC ahora se pueden habilitar en misiones de campa\u00f1a. Sin embargo, los jugadores seguir\u00e1n apareciendo como Master Chief y no usar\u00e1n armaduras, visores o efectos de armadura personalizados como la campa\u00f1a de Halo: Reach.<\/p>\n\n<h2 class=\"wp-block-heading\">Nuevas calaveras para Halo 2: Anniversary, Halo 3 y Halo 3: ODST en la actualizaci\u00f3n de Floodfight<\/h2>\n\n<p class=\"wp-block-paragraph\">El Acrophobia Skull que se agreg\u00f3 anteriormente a Halo 3 ahora est\u00e1 disponible en Halo 2: Anniversary, lo que hace que los jugadores ya no necesiten herramientas de modificaci\u00f3n para activar este efecto. Halo 3 y ODST recibieron calaveras que eran exclusivas solo de Halo: Combat Evolved Anniversary y Halo 2 Anniversary. La lista de calaveras es:<\/p>\n\n<ul class=\"wp-block-list\"><li>Ira: los enemigos disparan sus armas m\u00e1s r\u00e1pido y con mayor frecuencia.<\/li><li>Pa\u00f1uelo \u2013 Munici\u00f3n infinita<\/li><li>Par unido \u2013 Cr\u00e1neo cooperativo: cuando un jugador muere, el otro jugador recibe un gran aumento de da\u00f1o que dura un tiempo<\/li><li>Boom: aumenta el radio de explosi\u00f3n x2<\/li><li>Parche en el ojo: las funciones de apuntado autom\u00e1tico est\u00e1n deshabilitadas para todas las armas.<\/li><li>Extranjero: los jugadores no pueden recoger ni usar las armas de las facciones opuestas.<\/li><li>Fantasma: la IA ya no retrocede ante los ataques.<\/li><li>Jacked: los jugadores solo pueden ingresar a veh\u00edculos terrestres abordando<\/li><li>Mal funcionamiento: cada vez que reapareces, se desactiva un elemento aleatorio de tu HUD<\/li><li>Master Blaster &#8211; Cr\u00e1neo cooperativo: los escudos de un jugador se recargan al nivel de overshield y solo pueden cuerpo a cuerpo mientras que el segundo jugador no tiene escudos y munici\u00f3n infinita. Los roles cambian despu\u00e9s de varias muertes enemigas.<\/li><li>Pi\u00f1ata: golpear a los enemigos hace que suelten una granada.<\/li><li>Recesi\u00f3n: cada disparo vale el doble de munici\u00f3n<\/li><li>Entonces&#8230; Enojado&#8230; &#8211; Los brutos enfurecidos explotan como granadas de fragmentaci\u00f3n si no se despachan en cuesti\u00f3n de segundos. Los valores de puntuaci\u00f3n bruta base aumentan<\/li><li>Enjambre: los cazadores son mucho m\u00e1s fuertes. Se incrementan los valores de puntuaci\u00f3n de Hunter base.<\/li><li>Eso es solo&#8230; Incorrecto: aumenta la conciencia del enemigo sobre el jugador<\/li><li>They Come Back: las formas de combate de inundaci\u00f3n generadas por las formas <a href=\"https:\/\/fpschampion.com\/es\/veremos-un-modo-de-juego-multijugador-de-halo-infinite-infection\/\" target=\"_blank\" rel=\"noreferrer noopener\">de infecci\u00f3n<\/a> que reaniman un cad\u00e1ver son mucho m\u00e1s peligrosas<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Halo 3: ODST recibe todas las calaveras mencionadas anteriormente, incluida la acrofobia y excluye &#8216;Ellos regresan&#8217;.<\/p>\n\n<h2 class=\"wp-block-heading\">51 nuevas medallas de Halo 3<\/h2>\n\n<p class=\"wp-block-paragraph\">Halo 3 tambi\u00e9n gan\u00f3 51 nuevas medallas exclusivas para multijugador. Estas medallas ya ser\u00e1n familiares para los fan\u00e1ticos de Halo, ya que est\u00e1n inspiradas en t\u00edtulos posteriores de Halo. Si desea seguir viendo solo las medallas tradicionales de Halo 3, estas medallas adicionales se pueden desactivar en el men\u00fa de configuraci\u00f3n. La lista de nuevas medallas multijugador que vienen en la actualizaci\u00f3n de Floodfight para Halo Master Chief Collection es:<\/p>\n\n<ol class=\"wp-block-list\"><li>Disparo en la cabeza: mata a un oponente dispar\u00e1ndole en la cabeza.<\/li><li>Asistencia: ayudar a un jugador a lograr una muerte.<\/li><li>Venganza: Mata al oponente responsable de tu \u00faltima muerte.<\/li><li>Matar: Matar a un oponente (solo se aplica cuando no se otorga ninguna otra medalla de matanza).<\/li><li>Vengador: mata a un oponente que recientemente mat\u00f3 a tu compa\u00f1ero de equipo.<\/li><li>Comeback Kill: Logra una muerte despu\u00e9s de morir 3 veces seguidas.<\/li><li>Recarga esto: mata a un oponente que est\u00e9 recargando.<\/li><li>Grenade Kill: mata a un oponente usando una granada de fragmentaci\u00f3n o una granada de pulso<\/li><li>Protector: salva a un compa\u00f1ero de equipo matando a su atacante.<\/li><li>Close Call: mata a un oponente mientras tu salud es baja y sobrevive.<\/li><li>Rocket Kill: mata a un oponente usando un lanzacohetes.<\/li><li>Plasma Kill: mata a un oponente usando una granada de plasma.<\/li><li>Veh\u00edculo Kill: Mata a un oponente con un veh\u00edculo. Esto incluye la torreta de sombra y la torreta de elefantes. Esto es para muertes con armas de veh\u00edculos, no para salpicaduras.<\/li><li>Veh\u00edculo destruido: destruye un veh\u00edculo enemigo.<\/li><li>Sword Kill: mata a un oponente usando una espada de energ\u00eda<\/li><li>First Strike: gana la primera muerte del partido.<\/li><li>Asistencia de destrucci\u00f3n de veh\u00edculos: ayuda a destruir un veh\u00edculo.<\/li><li>Supercombine: mata a un oponente usando un Needler.<\/li><li>Instant\u00e1nea: mata a un oponente con un rifle de francotirador sin acercar el zoom.<\/li><li>Last Strike: Consigue la muerte final.<\/li><li>Bandera Tomada: Toma la bandera de un enemigo de su base.<\/li><li>Ofensa de la colina: mata a un oponente que tenga una colina.<\/li><li>Hill Defense: mata a un oponente mientras sostienes una colina.<\/li><li>Ball Carrier Kill: mata a un oponente que tenga el Oddball.<\/li><li>Bandera devuelta: devuelve la bandera de tu equipo.<\/li><li>Primer toque: s\u00e9 el primer jugador en recoger el Oddball.<\/li><li>Fuel Rod Cannon Kill: mata a un oponente usando un Fuel Rod Cannon.<\/li><li>Primer punto: s\u00e9 el primer jugador en ganar un punto desde una colina.<\/li><li>Hammer Kill: Mata a un oponente usando un Gravity Hammer.<\/li><li>Inconcebible: Mata a 35 oponentes seguidos sin morir.<\/li><li>Unfrigginbelievable: Mata a 40 oponentes seguidos sin morir.<\/li><li>Titular de la bola: Sostenga el Oddball durante 10 segundos.<\/li><li>Guardi\u00e1n de la bola: Sostenga el Oddball durante 20 segundos.<\/li><li>Ball Master: Mant\u00e9n el Oddball durante 30 segundos.<\/li><li>Ball Hog: Sostenga el Oddball durante 45 segundos.<\/li><li>Manos m\u00e1gicas: aguanta el Oddball durante 1 minuto.<\/li><li>Flag Runner: Captura 2 banderas en un juego.<\/li><li>Campe\u00f3n de banderas: captura 3 banderas en un juego.<\/li><li>Movimientos fluidos: Consigue un Triple Kill con el bicho raro.<\/li><li>Dominio de la colina: aguanta y sobrevive en la colina durante toda su duraci\u00f3n.<\/li><li>Brute Shot Kill: mata a un oponente con un Brute Shot.<\/li><li>Sentinel Beam Kill: Mata a un oponente con un Sentinel Beam.<\/li><li>Torreta Kill: Mata a un oponente con una torreta.<\/li><li>Territorio capturado: captur\u00f3 un territorio.<\/li><li>Territorial: Mata a un oponente mientras est\u00e1s en una Zona Territorial.<\/li><li>Triunvirato: captura 3 territorios diferentes durante una partida.<\/li><li>Defensa contra bombas: protege la bomba enemiga matando a un oponente cerca de ella.<\/li><li>Bomba desactivada: desactiva la bomba.<\/li><li>Desarmado: Mata a un oponente mientras est\u00e1 armando la bomba.<\/li><li>Saboteador: planta con \u00e9xito 2 bombas que estallan durante un partido.<\/li><li>Ambientalista: Mata a un oponente con cualquier elemento din\u00e1mico en el nivel.<\/li><\/ol>\n\n<h2 class=\"wp-block-heading\">Otras adiciones que vienen en la actualizaci\u00f3n de Halo de Floodfight<\/h2>\n\n<p class=\"wp-block-paragraph\">El navegador de juegos personalizado para Halo MCC finalmente se actualiz\u00f3 con una funci\u00f3n de coincidencia r\u00e1pida. Adem\u00e1s, todos los t\u00edtulos de Halo se han agregado al navegador, lo que significa que todos los lobbies de Halo finalmente son accesibles para todos.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Art\u00edculo relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/es\/ayudaron-a-nerf-aim-en-halo-infinite\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfSe nerfe\u00f3 Halo Infinite Asim Assist?<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Las campa\u00f1as de Halo 3 y Halo 3: ODST ahora tienen habilitado el juego cruzado. Tanto los jugadores de PC como los de Xbox pueden jugar ambas campa\u00f1as de forma cooperativa en l\u00ednea entre s\u00ed.<\/p>\n\n<p class=\"wp-block-paragraph\">Halo 3: ODST Mod Tools se ha lanzado junto con esta actualizaci\u00f3n. Las herramientas de modificaci\u00f3n se pueden descargar en Steam. 343 Industries planea lanzar herramientas de modificaci\u00f3n para los t\u00edtulos restantes en MCC; pronto, todos los juegos de Halo en MCC tendr\u00e1n mods compatibles.<\/p>\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, una gran cantidad de contenido cortado e invisible no lleg\u00f3 a las temporadas anteriores de Halo MCC que 343 a\u00fan no ha lanzado. Podemos esperar que las actualizaciones futuras traigan finalmente una personalizaci\u00f3n a\u00fan m\u00e1s inesperada al juego.<\/p>\n\n<p class=\"wp-block-paragraph\">Junto con todos estos cambios, en esta actualizaci\u00f3n de Floodfight se agregaron muchas actualizaciones de la interfaz de usuario y correcciones de errores a Halo MCC. La \u00faltima actualizaci\u00f3n de MCC es un logro fant\u00e1stico para 343 Industries, y la comunidad no puede esperar m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para sorpresa y asombro de la comunidad de Halo, 343 le dio a Halo MCC una actualizaci\u00f3n masiva con Floodfight Update. Muchos no esperaban esta actualizaci\u00f3n, especialmente porque Halo Infinite est\u00e1 programada para su segunda temporada a principios de mayo. Si bien esta actualizaci\u00f3n se burl\u00f3 de agregar m\u00e1s contenido nuevo para ODST Firefight, este<\/p>\n","protected":false},"author":6,"featured_media":13132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1447],"tags":[1607],"platform":[512,513,662],"class_list":["post-31980","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-es","tag-aureola","platform-windowsos","platform-xbox-one-es","platform-xbox-series-x-s-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: TMCC<\/title>\n<meta name=\"description\" content=\"\u00a1La actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection traer\u00e1 una gran cantidad de mejoras y nuevas caracter\u00edsticas a un juego que ya es genial!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection\" \/>\n<meta property=\"og:description\" content=\"\u00a1La actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection traer\u00e1 una gran cantidad de mejoras y nuevas caracter\u00edsticas a un juego que ya es genial!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-14T04:43:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T06:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection\",\"datePublished\":\"2022-04-14T04:43:15+00:00\",\"dateModified\":\"2023-06-04T06:03:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/\"},\"wordCount\":1842,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"keywords\":[\"aureola\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/\",\"name\":\"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: TMCC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"datePublished\":\"2022-04-14T04:43:15+00:00\",\"dateModified\":\"2023-06-04T06:03:15+00:00\",\"description\":\"\u00a1La actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection traer\u00e1 una gran cantidad de mejoras y nuevas caracter\u00edsticas a un juego que ya es genial!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Floodfight-Update.jpg\",\"width\":1600,\"height\":900,\"caption\":\"Source: halowaypoint.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: TMCC","description":"\u00a1La actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection traer\u00e1 una gran cantidad de mejoras y nuevas caracter\u00edsticas a un juego que ya es genial!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/","og_locale":"es_ES","og_type":"article","og_title":"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection","og_description":"\u00a1La actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection traer\u00e1 una gran cantidad de mejoras y nuevas caracter\u00edsticas a un juego que ya es genial!","og_url":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/","og_site_name":"FPS Champion","article_published_time":"2022-04-14T04:43:15+00:00","article_modified_time":"2023-06-04T06:03:15+00:00","og_image":[{"width":1600,"height":900,"type":"image\/jpeg","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection","datePublished":"2022-04-14T04:43:15+00:00","dateModified":"2023-06-04T06:03:15+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/"},"wordCount":1842,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/es\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","keywords":["aureola"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/","url":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/","name":"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: TMCC","isPartOf":{"@id":"https:\/\/fpschampion.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","datePublished":"2022-04-14T04:43:15+00:00","dateModified":"2023-06-04T06:03:15+00:00","description":"\u00a1La actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection traer\u00e1 una gran cantidad de mejoras y nuevas caracter\u00edsticas a un juego que ya es genial!","breadcrumb":{"@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/04\/Floodfight-Update.jpg","width":1600,"height":900,"caption":"Source: halowaypoint.com"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/es\/todo-lo-que-necesitas-saber-sobre-la-actualizacion-de-floodfight-para-halo-the-master-chief-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Todo lo que necesitas saber sobre la actualizaci\u00f3n de Floodfight para Halo: The Master Chief Collection"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/es\/#website","url":"https:\/\/fpschampion.com\/es\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/es\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/es\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/31980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/comments?post=31980"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/31980\/revisions"}],"predecessor-version":[{"id":31989,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/31980\/revisions\/31989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/media\/13132"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/media?parent=31980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/categories?post=31980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/tags?post=31980"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/platform?post=31980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}