{"id":31064,"date":"2022-08-09T05:21:28","date_gmt":"2022-08-09T05:21:28","guid":{"rendered":"https:\/\/fpschampion.com\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/"},"modified":"2023-06-04T05:55:30","modified_gmt":"2023-06-04T05:55:30","slug":"los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/","title":{"rendered":"Los mejores elementos de Risk of Rain 2 de cada rareza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Risk of Rain 2 es un Rogue-Like adictivo con muchos escenarios \u00fanicos que controlan c\u00f3mo transcurre cada carrera. Cada sobreviviente puede manejar una variedad de art\u00edculos. Estos elementos se obtienen gastando dinero en cofres repartidos por el mapa por entidades invisibles denominadas directores. Cada entorno otorga puntos a los directores para gastar en mapas generados por procedimientos para distribuir elementos interactivos y enemigos en el escenario. Como resultado del proceso, cada ejecuci\u00f3n del juego se siente dr\u00e1sticamente diferente entre s\u00ed.<\/p>\n\n<p class=\"wp-block-paragraph\">Explicaremos c\u00f3mo cada rareza de art\u00edculo funciona de manera diferente entre s\u00ed y tiene medios dr\u00e1sticamente diferentes para obtenerlos. Recomendamos encarecidamente comprender el uso de cada elemento y c\u00f3mo obtener cada rareza para todos los niveles de contenido, adem\u00e1s de comprender las fortalezas y debilidades de cada sobreviviente.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-common-items-in-risk-of-rain-2\">Elementos comunes en Riesgo de lluvia 2<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Common-Items-in-RoR2-1024x387.png\" alt=\"Objetos comunes que puede querer usar para mejorar sus estad&#xED;sticas de Superviviente.\" class=\"wp-image-5313\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Seg\u00fan su hom\u00f3nimo, los elementos comunes son los elementos m\u00e1s f\u00e1ciles de obtener en Risk of Rain 2. Los cofres peque\u00f1os, que tienen un 79,2 % de posibilidades de generar elementos comunes al momento de la compra, son los segundos mayores en cualquier etapa junto con las impresoras de elementos 3D comunes. Debido al bajo costo y las altas tasas de generaci\u00f3n de estos art\u00edculos, las terminales comunes de tiendas m\u00faltiples y los cofres peque\u00f1os son los elementos interactivos que no son barriles m\u00e1s comunes en el juego temprano y tard\u00edo. Los terminales multitienda generan con frecuencia elementos comunes en las tres primeras etapas, pero siempre son poco comunes en los entornos 4 y 5.<\/p>\n\n<p class=\"wp-block-paragraph\">Aunque rara vez se realiza, tiene la opci\u00f3n de intercambiar un art\u00edculo legendario por 3 art\u00edculos comunes en la ceremonia de graduaci\u00f3n. Se recomienda si tienes un objeto legendario que da\u00f1a directamente tu estilo de juego o si el objeto com\u00fan que se muestra te ayudar\u00e1 m\u00e1s contra Mithrix en su lucha contra el jefe que tus objetos legendarios.<\/p>\n\n<p class=\"wp-block-paragraph\">Aunque hay excepciones a la regla, los elementos comunes tienden a basarse en la capacidad de acumularlos y proporcionar beneficios pasivos que pueden aumentar indefinidamente cuando obtiene duplicados del mismo elemento. Los elementos comunes se activan con frecuencia en una ejecuci\u00f3n. Pueden ayudar a su Superviviente a volverse m\u00e1s r\u00e1pido, golpear m\u00e1s r\u00e1pido, resistir mejor y tener la oportunidad de activar los efectos de impacto con m\u00e1s regularidad.<\/p>\n\n<p class=\"wp-block-paragraph\">El tama\u00f1o del beneficio est\u00e1 relacionado con la cantidad de pilas del art\u00edculo que tienes. Las excepciones a esta tradici\u00f3n ser\u00edan Gasoline, Monster Tooth, Rusted Key y Warbanner, que se activan despu\u00e9s de matar enemigos o abandonar el escenario.<\/p>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos poco comunes son a menudo una bolsa mixta. Algunos pueden proporcionar excelentes bonificaciones pasivas, mientras que <a href=\"https:\/\/fpschampion.com\/es\/los-10-peores-elementos-comunes-en-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">otros elementos comunes en RoR2 pueden ser terribles adiciones a su construcci\u00f3n<\/a> .<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-uncommon-items\">Art\u00edculos poco comunes<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/uncommon-items-in-RoR2-1024x448.png\" alt=\"Cosas poco comunes para ayudar a tu aventurero\" class=\"wp-image-5314\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos poco comunes se pueden obtener en casi todos los cofres promedio, pero generalmente tienden a ser m\u00e1s raros que los art\u00edculos comunes y se pueden obtener con m\u00e1s frecuencia que los art\u00edculos legendarios. Estos art\u00edculos tienen un 80 % de posibilidades de caer a trav\u00e9s de cofres grandes y est\u00e1n garantizados para estar en terminales multitienda en los entornos 4 y 5 en un bucle.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Art\u00edculo relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/es\/risk-of-rain-2-cross-platform-en-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00bfRisk of Rain 2 Cross Platform en 2022?<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-get-uncommon-items-in-risk-of-rain-2\">C\u00f3mo obtener art\u00edculos poco comunes en Risk of Rain 2<\/h3>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos poco comunes tambi\u00e9n se pueden obtener en cofres peque\u00f1os, pero tienen una probabilidad del 19,8 % y se obtienen aproximadamente una vez cada 5 cofres peque\u00f1os. Este cambio lo comparten las entregas multitienda bloqueadas generadas por el formulario de solicitud de env\u00edo, pero la posibilidad de obtener art\u00edculos m\u00e1s raros aumentar\u00e1 por pila.<\/p>\n\n<p class=\"wp-block-paragraph\">Es importante mencionar que las cajas de seguridad oxidadas tienen las mismas ca\u00eddas que un cofre grande pero cuestan una llave oxidada, que es un art\u00edculo com\u00fan. Tambi\u00e9n puedes obtener un art\u00edculo poco com\u00fan elegido al azar a cambio de 3 art\u00edculos comunes cuando est\u00e9s en el bazar entre tiempos o en la ceremonia de graduaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/fpschampion.com\/es\/los-10-mejores-elementos-poco-comunes-de-risk-of-rain-2-clasificados\/\" target=\"_blank\" rel=\"noreferrer noopener\">Los art\u00edculos poco comunes en Risk of Rain 2<\/a> se pueden obtener de forma gratuita una vez por etapa cuando se usa una chatarra regeneradora en una impresora de art\u00edculos poco comunes. Los art\u00edculos de esta rareza son los que aparecen con m\u00e1s frecuencia despu\u00e9s de derrotar a un jefe en un evento de teletransportador.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-notable-uncommons-items-in-ror2\">Elementos poco comunes notables en RoR2<\/h3>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos poco comunes son tan abundantes en variedad y opciones para elegir como los art\u00edculos comunes normales. A\u00fan as\u00ed, sus trucos generalmente giran en torno a la necesidad de criterios espec\u00edficos para activarlos. Por ejemplo, algunos elementos poco comunes requieren otros elementos para funcionar, como el tanque de encendido, lo que hace que los efectos de encendido inflijan un 300 % m\u00e1s de da\u00f1o con el tiempo. A menos que seas el art\u00edfice que puede aplicar un Ignite sin un elemento, deber\u00e1s emparejar el tanque de Ignici\u00f3n con mucha gasolina.<\/p>\n\n<p class=\"wp-block-paragraph\">Otros elementos con efecto incluyen el Pauldron de Berserker, que te otorga un 50% de velocidad de movimiento y un 100% de velocidad de ataque despu\u00e9s de matar a cuatro enemigos en un segundo. Algunos elementos requieren menos para activarse, como Rose Buckler, que aumenta tu armadura en 30 mientras corres, o Hopoo Feather, que te da un salto adicional por pila.<\/p>\n\n<p class=\"wp-block-paragraph\">Por supuesto, hay algunos elementos, excepto Ukulele o AtG Missile Mk.1, que son efectos de impacto. En general, los elementos poco comunes requieren m\u00e1s sinergia con los elementos comunes. Dependiendo del Superviviente o de la estructura que tengas, elementos como Death Mark podr\u00edan ser casi imposibles de activar.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-legendary-items-aka-red-items\">Art\u00edculos legendarios (tambi\u00e9n conocidos como art\u00edculos rojos)<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/legendary-items-1024x536.png\" alt=\"objetos rojos legendarios disponibles en Risk of Rain 2\" class=\"wp-image-5315\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Aunque los art\u00edculos legendarios son extremadamente dif\u00edciles de obtener al principio de una carrera, actualmente hay cuatro formas de garantizar la obtenci\u00f3n de un art\u00edculo legendario sin apostar, adem\u00e1s de las impresoras 3D, ya que requieren un art\u00edculo legendario preexistente para usar.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Art\u00edculo relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/es\/guia-y-compilacion-completa-de-risk-of-rain-2-acrid\/\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3mo desbloquear y construir Acrid en Risk of Rain 2<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-obtain-legendary-items-in-risk-of-rain-2\">C\u00f3mo obtener art\u00edculos legendarios en Risk of Rain 2<\/h3>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos legendarios se pueden obtener intercambiando 5 art\u00edculos poco comunes por un art\u00edculo legendario en el bazar entre el tiempo o en el comienzo. Tambi\u00e9n puedes obtenerlos al derrotar a la Unidad de culto de aleaci\u00f3n en Siren&#8217;s Call despu\u00e9s de destruir los huevos en el mapa. Los jugadores tambi\u00e9n pueden obtener art\u00edculos legendarios en Risk of Rain 2 de un cofre legendario generado al azar, de los garantizados en Abyssal Depths o Sundered Grove, o al romper la novena celda en Void Fields.<\/p>\n\n<p class=\"wp-block-paragraph\">Los objetos legendarios tienen un 1 % de posibilidades de aparecer en cofres peque\u00f1os, un 20 % de posibilidades de aparecer en cofres grandes y un 0,9 % de posibilidades de aparecer en un cofre adaptable. Los cofres adaptables son raros. Adem\u00e1s, pasan por los art\u00edculos comunes, poco comunes, legendarios y de equipo al momento de la compra. Esto le permite elegir un elemento si interact\u00faa cuando aparece en la vista previa.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-exemplary-red-items-in-ror2\">Elementos rojos ejemplares en RoR2<\/h3>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos legendarios ofrecen cambios catastr\u00f3ficos para tu personaje o la construcci\u00f3n de tu art\u00edculo. Estos objetos rojos son algunos de los elementos que m\u00e1s cambian el juego en Risk of Rain 2. Los elementos legendarios tambi\u00e9n son bastante f\u00e1ciles de usar, al igual que los elementos comunes, y la mayor\u00eda de las veces son similares a un pasivo adicional.<\/p>\n\n<p class=\"wp-block-paragraph\">Un elemento legendario en RoR2 que realiza esta funci\u00f3n pasiva es <a href=\"https:\/\/fpschampion.com\/es\/el-alcance-laser-en-risk-of-rain-2-una-guia-completa\/\" target=\"_blank\" rel=\"noreferrer noopener\">el alcance l\u00e1ser<\/a> , que hace que los golpes cr\u00edticos inflijan un 100 % de da\u00f1o adicional. Brilliant Behemoth tambi\u00e9n hace esto al hacer que todos tus ataques exploten en un radio de 4 m con un 60 % de da\u00f1o adicional.<\/p>\n\n<p class=\"wp-block-paragraph\">Otros <a href=\"https:\/\/fpschampion.com\/es\/los-5-mejores-elementos-legendarios-para-hacer-loops-en-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">art\u00edculos legendarios en RoR2<\/a> tienen efectos \u00fanicos como Pocket ICBM, que hace que todos los art\u00edculos y equipos de misiles disparen dos misiles adicionales y aumenten su da\u00f1o. O el mejor amigo de Dio, que te revive con tres segundos de invulnerabilidad despu\u00e9s de morir, pero el objeto se consumir\u00e1.<\/p>\n\n<p class=\"wp-block-paragraph\">Otros elementos legendarios pueden cambiar por completo tu forma de jugar, como Brainstalks. Brainstalks hace que tus habilidades tengan un tiempo de reutilizaci\u00f3n de 0,5 segundos cada vez que matas a un monstruo de \u00e9lite. Cualquier art\u00edculo legendario que adquiera tendr\u00e1 un impacto masivo en su carrera en casi cualquier Superviviente.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-special-boss-items\">Objetos especiales de jefe<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/boss-items-1024x241.png\" alt=\"art&#xED;culos de jefe amarillo\" class=\"wp-image-5316\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos de jefe son art\u00edculos \u00fanicos y poco comunes que caen de su jefe correspondiente al completar un evento de teletransportador. A veces tambi\u00e9n se les llama elementos del planeta en Risk of Rain 2. Tambi\u00e9n puede obtenerlos usando el art\u00edculo de equipo Tricornio de Trophy Hunter en un jefe, mat\u00e1ndolo instant\u00e1neamente y reemplaz\u00e1ndolo con su art\u00edculo de jefe correspondiente. La consistencia principal de estos elementos de jefe es imitar ciertas habilidades o pasivos que los jefes de teletransportador tienen en su conjunto de movimientos.<\/p>\n\n<p class=\"wp-block-paragraph\">Un ejemplo de un gran elemento de Boss en Risk of Rain 2 ser\u00eda el Genesis Loop, que hace que explotes con un 6000 % de da\u00f1o base cada vez que caes por debajo del 25 % de HP, que suelta Wandering Vagrant, que realiza una habilidad muy similar cuando luchas contra ellos.<\/p>\n\n<p class=\"wp-block-paragraph\">Otros art\u00edculos solo se adquieren visitando una etapa espec\u00edfica, como la semilla Halcyon convoca a la aurelionita durante el evento del teletransportador. Este art\u00edculo del planeta solo se puede obtener completando Boss Fight en Gilded Coast. Alcanzar este Reino Oculto requiere activar el Altar de Oro para abrir el portal a la Costa Dorada. Ambos tipos de Perlas, obtenidas al colocar Objetos Lunares en una Piscina de Limpieza, tambi\u00e9n cuentan como Objetos Planetarios.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Art\u00edculo relacionado:<\/strong> <a href=\"https:\/\/fpschampion.com\/es\/18-juegos-roguelike-llenos-de-accion-como-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">18 grandes juegos Roguelike como Risk of Rain 2<\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-lunar-items-in-risk-of-rain-2\">Elementos lunares en riesgo de lluvia 2<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/lunar-items-in-Risk-of-Rain-2-1024x310.png\" alt=\"elementos azules disponibles en RoR2\" class=\"wp-image-5317\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Los elementos lunares se pueden obtener de dos maneras, y algunos de estos elementos lunares pueden funcionar como equipos. A diferencia de los elementos de equipo tradicionales, los elementos de equipo lunar caen de manera similar a sus contrapartes pasivas. Puedes obtener art\u00edculos lunares gastando una moneda lunar en una c\u00e1psula lunar que se genera aleatoriamente en un escenario o gastando 2 monedas lunares en una c\u00e1psula lunar en el bazar entre tiempos, esta vez con una vista previa del art\u00edculo que obtendr\u00e1s.<\/p>\n\n<p class=\"wp-block-paragraph\">Los elementos lunares son elementos poderosos que tienen un costo de uso. Esta compensaci\u00f3n depende principalmente de su construcci\u00f3n, el Superviviente actual con el que est\u00e1 jugando y qu\u00e9 tan lejos est\u00e1 en la carrera. Casi siempre vale la pena elegir algunos <a href=\"https:\/\/fpschampion.com\/es\/los-5-mejores-elementos-lunares-en-risk-of-rain-2-para-derrotar-a-mithrix\/\" target=\"_blank\" rel=\"noreferrer noopener\">elementos lunares geniales en RoR2<\/a> , como el Gesto de los ahogados, que reduce el tiempo de reutilizaci\u00f3n del equipo en un 50%, pero lo activa autom\u00e1ticamente.<\/p>\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de los objetos lunares son la apuesta m\u00e1s grande que puedes hacer en Risk of Rain 2, como la trascendencia Convierte toda la salud menos una en escudos regeneradores, pero obtienes un 50 % m\u00e1s de salud m\u00e1xima. Otra gran apuesta es usar <a href=\"https:\/\/fpschampion.com\/es\/es-bueno-el-egocentrismo-en-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">el egocentrismo en Risk of Rain 2<\/a> . Transforma art\u00edculos aleatorios en su inventario en copias de s\u00ed mismo en un intervalo de tiempo fijo para obtener una bomba en \u00f3rbita que se acumula indefinidamente. Incluso hay algunos <a href=\"https:\/\/fpschampion.com\/es\/los-5-peores-articulos-azules-en-riesgo-de-lluvia-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">art\u00edculos azules terribles en Risk of Rain 2 que<\/a> casi nunca vale la pena conseguir.<\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, adquirir cuatro elementos lunares espec\u00edficos es la \u00fanica forma en que un jugador puede transformarse y jugar como <a href=\"https:\/\/fpschampion.com\/es\/como-desbloquear-y-jugar-heretic-en-risk-of-rain-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">el Superviviente oculto, Hereje<\/a> . Los elementos de Heresy cambian lentamente tu conjunto de movimientos reemplaz\u00e1ndolos con los movimientos de The Heretic hasta que te transformas completamente en ella.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-void-items\">Art\u00edculos anulados<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Void-items-in-RoR2-1024x312.png\" alt=\"objetos vac&#xED;os con brillo rosa\" class=\"wp-image-5318\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Los Objetos del Vac\u00edo se pueden obtener de dos maneras, gastando el 50% de su Salud M\u00e1xima en una Cuna del Vac\u00edo o gastando una Llave Incrustada en un Alijo Incrustado, dicha Llave solo se puede obtener abriendo una Cuna del Vac\u00edo. Cach\u00e9s incrustados te permite elegir entre 3 <a href=\"https:\/\/fpschampion.com\/es\/todos-los-articulos-vacios-en-risk-of-rain-2-clasificados-de-peor-a-mejor\/\" target=\"_blank\" rel=\"noreferrer noopener\">art\u00edculos vac\u00edos en Risk of Rain 2<\/a> , y la llave incrustada transformar\u00e1 cualquier llave oxidada que obtengas o que ya tengas con copias de s\u00ed mismo, a menos que ya no tengas llaves incrustadas en tu inventario.<\/p>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos vac\u00edos son la \u00faltima incorporaci\u00f3n en Risk of Rain 2. Estos elementos van desde elementos comunes, poco comunes, legendarios y de jefe. La tem\u00e1tica detr\u00e1s de estos elementos es que corrompen a sus contrapartes normales para agregar diferentes efectos. Forzar\u00e1n a sus contrapartes normales a hacer copias de s\u00ed mismos dentro de tu inventario, oblig\u00e1ndote a elegir entre los dos efectos b\u00e1sicos.<\/p>\n\n<p class=\"wp-block-paragraph\">Un ejemplo de objetos vac\u00edos es Needletick, que corrompe todas las dagas de tres puntas, convirtiendo su probabilidad de activar sangrado en una probabilidad de colapsar a un enemigo con un 400 % de da\u00f1o base.<\/p>\n\n<p class=\"wp-block-paragraph\">Al igual que con los elementos lunares, debe tener cuidado al recoger elementos vac\u00edos, ya que eliminan su capacidad de beneficiarse de las estad\u00edsticas o funciones de sus contrapartes normales.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-equipment\">Equipo<\/h2>\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Equipment-in-Risk-of-Rain-2-1024x397.png\" alt=\"art&#xED;culos de equipo que puedes conseguir en riesgo de lluvia 2\" class=\"wp-image-5319\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos de equipo se generan en barriles de equipo, tiendas de equipos m\u00faltiples en las etapas 3 y 5 y cofres adaptables. No comparten posibilidades de ca\u00edda con ning\u00fan otro elemento adem\u00e1s de cuando se usa el cofre adaptable, y todos funcionan de manera radicalmente diferente a otros elementos del juego.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Gu\u00eda relacionada:<\/strong> <a href=\"https:\/\/fpschampion.com\/es\/como-vencer-a-risk-of-rain-2-actualizado-con-todos-los-finales-nuevos\/\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3mo vencer el riesgo de lluvia 2<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-find-rare-equipment-in-ror2\">C\u00f3mo encontrar equipo raro en RoR2<\/h3>\n\n<p class=\"wp-block-paragraph\">Los elementos de equipo otorgan funcionalmente a cada sobreviviente una quinta habilidad, con un tiempo de reutilizaci\u00f3n relativamente largo al usarlo. Junto con el equipo de vac\u00edo, el equipo de \u00e9lite tiene la posibilidad de caer una vez cada 4000 muertes de \u00e9lite, que no se pueden obtener con ning\u00fan otro m\u00e9todo. Elite Equipment no tiene un efecto de activaci\u00f3n y, en cambio, transforma a su Superviviente en Elite mientras lo sostiene. Los mismos beneficios que obtiene un Elite se le otorgan a su Superviviente seg\u00fan la variante que equipe.<\/p>\n\n<p class=\"wp-block-paragraph\">Actualmente hay 4 elementos de equipamiento lunar, 27 de equipamiento est\u00e1ndar y 7 elementos de equipamiento de \u00e9lite en Risk of Rain 2. Dado que funcionan de manera tan diferente a otros elementos en RoR2, proporcionan efectos separados entre s\u00ed y pueden beneficiarse de construcciones completamente diferentes.<\/p>\n\n<p class=\"wp-block-paragraph\">Algunos elementos de equipo benefician la movilidad, el da\u00f1o, el impacto, la agrupaci\u00f3n, la b\u00fasqueda de elementos, la curaci\u00f3n, la negaci\u00f3n de \u00e1rea, la velocidad, la armadura y muchos otros efectos. Se recomienda aprender lo que puede hacer cada elemento de equipo, ya que var\u00edan dr\u00e1sticamente.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wrapping-up-our-risk-of-rain-2-items-guide\">Terminando nuestro riesgo de lluvia 2 Gu\u00eda de elementos<\/h2>\n\n<p class=\"wp-block-paragraph\">Eso resume nuestra gu\u00eda de todas las rarezas de art\u00edculos en Risk of Rain 2. Saber qu\u00e9 elementos tienen una mayor probabilidad de soltar qu\u00e9 tipo de elemento necesita puede ayudarlo a maximizar sus posibilidades de comenzar su construcci\u00f3n al comienzo de una carrera. Para los jugadores m\u00e1s nuevos, siempre recomendamos leer qu\u00e9 elementos se combinan bien con el Superviviente que planeas jugar actualmente, adem\u00e1s de elegir priorizar los cofres m\u00e1s peque\u00f1os al comienzo de tus carreras en lugar de los cofres m\u00e1s grandes o los Santuarios de la Suerte.<\/p>\n\n<p class=\"wp-block-paragraph\">Para obtener otra gran gu\u00eda de RoR2, consulte nuestra <a href=\"https:\/\/fpschampion.com\/es\/personajes-de-all-risk-of-rain-2-clasificados-de-peor-a-mejor\/\" target=\"_blank\" rel=\"noreferrer noopener\">lista de niveles clasificados de todos los personajes de Risk of Rain 2<\/a> . \u00a1Esperamos que te ayude a encontrar a tu pr\u00f3ximo superviviente favorito!<\/p>\n\n<p class=\"wp-block-paragraph\">Si a\u00fan no ha comprado Risk o Rain 2, no dude en obtenerlo de la <a href=\"https:\/\/store.steampowered.com\/app\/632360\/Risk_of_Rain_2\/\" target=\"_blank\" rel=\"noreferrer noopener\">tienda RoR2 Steam<\/a> . Si te gustan los juegos roguelike FPS, \u00a1estar\u00e1s muy satisfecho con esta obra maestra!<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Todas las im\u00e1genes fueron capturadas en el juego de Risk of Rain 2.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Risk of Rain 2 es un Rogue-Like adictivo con muchos escenarios \u00fanicos que controlan c\u00f3mo transcurre cada carrera. Cada sobreviviente puede manejar una variedad de art\u00edculos. Estos elementos se obtienen gastando dinero en cofres repartidos por el mapa por entidades invisibles denominadas directores. Cada entorno otorga puntos a los directores para gastar en mapas generados<\/p>\n","protected":false},"author":6,"featured_media":16460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[509],"tags":[1474],"platform":[658,511,512,513],"class_list":["post-31064","post","type-post","status-publish","format-standard","has-post-thumbnail","category-articulo-destacado","tag-riesgo-de-lluvia-2","platform-nintendo-switch","platform-playstation-4-es","platform-windowsos","platform-xbox-one-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Risk of Rain 2: los mejores art\u00edculos de cada rareza | FPS Champion<\/title>\n<meta name=\"description\" content=\"\u00bfTe preguntas qu\u00e9 elementos buscar en Risk of Rain 2 o c\u00f3mo obtener los m\u00e1s raros del juego? \u00a1Te contamos todo lo que necesitas saber!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los mejores elementos de Risk of Rain 2 de cada rareza\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe preguntas qu\u00e9 elementos buscar en Risk of Rain 2 o c\u00f3mo obtener los m\u00e1s raros del juego? \u00a1Te contamos todo lo que necesitas saber!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-09T05:21:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T05:55:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Items-in-Risk-of-Rain-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Los mejores elementos de Risk of Rain 2 de cada rareza\",\"datePublished\":\"2022-08-09T05:21:28+00:00\",\"dateModified\":\"2023-06-04T05:55:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/\"},\"wordCount\":2684,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Items-in-Risk-of-Rain-2.jpg\",\"keywords\":[\"Riesgo de lluvia 2\"],\"articleSection\":[\"Art\u00edculo Destacado\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/\",\"name\":\"Risk of Rain 2: los mejores art\u00edculos de cada rareza | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Items-in-Risk-of-Rain-2.jpg\",\"datePublished\":\"2022-08-09T05:21:28+00:00\",\"dateModified\":\"2023-06-04T05:55:30+00:00\",\"description\":\"\u00bfTe preguntas qu\u00e9 elementos buscar en Risk of Rain 2 o c\u00f3mo obtener los m\u00e1s raros del juego? \u00a1Te contamos todo lo que necesitas saber!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Items-in-Risk-of-Rain-2.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Items-in-Risk-of-Rain-2.jpg\",\"width\":1600,\"height\":792,\"caption\":\"Items in Risk of Rain 2 Come in All Shapes, Sizes, and Types\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los mejores elementos de Risk of Rain 2 de cada rareza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Risk of Rain 2: los mejores art\u00edculos de cada rareza | FPS Champion","description":"\u00bfTe preguntas qu\u00e9 elementos buscar en Risk of Rain 2 o c\u00f3mo obtener los m\u00e1s raros del juego? \u00a1Te contamos todo lo que necesitas saber!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/","og_locale":"es_ES","og_type":"article","og_title":"Los mejores elementos de Risk of Rain 2 de cada rareza","og_description":"\u00bfTe preguntas qu\u00e9 elementos buscar en Risk of Rain 2 o c\u00f3mo obtener los m\u00e1s raros del juego? \u00a1Te contamos todo lo que necesitas saber!","og_url":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/","og_site_name":"FPS Champion","article_published_time":"2022-08-09T05:21:28+00:00","article_modified_time":"2023-06-04T05:55:30+00:00","og_image":[{"width":1600,"height":792,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Items-in-Risk-of-Rain-2.jpg","type":"image\/jpeg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Los mejores elementos de Risk of Rain 2 de cada rareza","datePublished":"2022-08-09T05:21:28+00:00","dateModified":"2023-06-04T05:55:30+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/"},"wordCount":2684,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/es\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Items-in-Risk-of-Rain-2.jpg","keywords":["Riesgo de lluvia 2"],"articleSection":["Art\u00edculo Destacado"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/","url":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/","name":"Risk of Rain 2: los mejores art\u00edculos de cada rareza | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Items-in-Risk-of-Rain-2.jpg","datePublished":"2022-08-09T05:21:28+00:00","dateModified":"2023-06-04T05:55:30+00:00","description":"\u00bfTe preguntas qu\u00e9 elementos buscar en Risk of Rain 2 o c\u00f3mo obtener los m\u00e1s raros del juego? \u00a1Te contamos todo lo que necesitas saber!","breadcrumb":{"@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Items-in-Risk-of-Rain-2.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/08\/Items-in-Risk-of-Rain-2.jpg","width":1600,"height":792,"caption":"Items in Risk of Rain 2 Come in All Shapes, Sizes, and Types"},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/es\/los-mejores-elementos-de-risk-of-rain-2-de-cada-rareza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Los mejores elementos de Risk of Rain 2 de cada rareza"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/es\/#website","url":"https:\/\/fpschampion.com\/es\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/es\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/es\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/31064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/comments?post=31064"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/31064\/revisions"}],"predecessor-version":[{"id":31071,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/31064\/revisions\/31071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/media\/16460"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/media?parent=31064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/categories?post=31064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/tags?post=31064"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/platform?post=31064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}