{"id":29633,"date":"2023-04-06T04:38:58","date_gmt":"2023-04-06T04:38:58","guid":{"rendered":"https:\/\/fpschampion.com\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/"},"modified":"2023-06-04T05:40:11","modified_gmt":"2023-06-04T05:40:11","slug":"guia-y-compilacion-del-mago-oscuro-y-mas-oscuro","status":"publish","type":"post","link":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/","title":{"rendered":"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro"},"content":{"rendered":"\n<p>El mago es una clase poderosa, ca\u00f3tica pero fr\u00e1gil en Dark and Darker. Los magos son una clase vol\u00e1til que puede significar la perdici\u00f3n para ellos mismos o para el tiempo del enemigo, dependiendo de su experiencia en el lanzamiento de hechizos. El Mago es una de las clases m\u00e1s dif\u00edciles de dominar en Dark and Darker, con muy pocas opciones cuerpo a cuerpo. Por lo tanto, confiar en su poderosa pero lenta magia tiene un gran potencial de da\u00f1o, que es el principal atractivo de esta clase.<\/p>\n\n<p>Esta gu\u00eda cubrir\u00e1 las mejores construcciones de Wizard en Darker and Darker para jugadores nuevos o casuales, incluidas ventajas, pasivos, hechizos y otros consejos de juego.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wizard-build-and-guide-overview\">Descripci\u00f3n general de la gu\u00eda y compilaci\u00f3n del asistente<\/h2>\n\n<p>El mago es una clase poderosa y maravillosa en Dark and Darker, que lucha en el juego en solitario pero sobresale en grupos. Hay muchas formas diferentes de jugar al Mago, desde la cantidad de hechizos para elegir, adem\u00e1s de sus ventajas y opciones pasivas.<\/p>\n\n<p>Con todas estas ventajas, habilidades y armas combinadas, esta es nuestra configuraci\u00f3n arcana para el mago. Esta compilaci\u00f3n se enfoca principalmente en usar Arcano para infligir toneladas de da\u00f1o de explosi\u00f3n constante mientras reduce dr\u00e1sticamente el tiempo de lanzamiento de nuestros hechizos y aumenta su da\u00f1o.<\/p>\n\n<h3 class=\"wp-block-heading\">Asistentes profesionales<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Muchos hechizos AOE<\/li>\n\n\n\n<li>Algunos hechizos de mejora para ellos mismos\/miembros del grupo.<\/li>\n\n\n\n<li>Opciones de control de multitudes.<\/li>\n\n\n\n<li>Puede regenerar hechizos sin necesidad de una fogata, a diferencia del Cl\u00e9rigo.<\/li>\n\n\n\n<li>Inflige toneladas de da\u00f1o explosivo y puede ser potencialmente una de las clases m\u00e1s fuertes del juego.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Contras del mago<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Pozo de salud fr\u00e1gil y peque\u00f1o.<\/li>\n\n\n\n<li>Baja velocidad de movimiento y velocidad de interacci\u00f3n.<\/li>\n\n\n\n<li>Lucha cuando se le deja solo o cuando se juega solo.<\/li>\n\n\n\n<li>Requiere tiempo de inactividad para regenerar hechizos, lo que debilita al mago en peleas m\u00e1s largas.<\/li>\n\n\n\n<li>Extremadamente d\u00e9bil en combate cuerpo a cuerpo, por lo general muere una vez que un p\u00edcaro o un b\u00e1rbaro se acercan demasiado.<\/li>\n\n\n\n<li>Casi todos los hechizos son AOE; por lo tanto, apuntar temerariamente te har\u00e1 da\u00f1o a ti o a tus compa\u00f1eros de equipo.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-all-wizard-perks-for-your-dark-and-darker-build\">Todas las ventajas del mago para tu versi\u00f3n oscura y m\u00e1s oscura<\/h2>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td colspan=\"2\"><strong>Todas las ventajas<\/strong><\/td><\/tr><tr><td>canto r\u00e1pido<\/td><td>Aumenta la velocidad de lanzamiento de hechizos en un 20%<\/td><\/tr><tr><td>Sabio<\/td><td>Aumenta el conocimiento en un 10%<\/td><\/tr><tr><td>Comentarios arcanos<\/td><td>Infligir da\u00f1o con hechizos arcanos aumenta la velocidad de lanzamiento y el da\u00f1o m\u00e1gico base en un 1 % por acumulaci\u00f3n. M\u00e1ximo de 5 pilas. La duraci\u00f3n adicional dura 7 segundos y se reinicia con cada ataque exitoso.<\/td><\/tr><tr><td>Maestr\u00eda Arcana<\/td><td>Aumenta el da\u00f1o m\u00e1gico de los hechizos arcanos en un %5 y reduce el tiempo de lanzamiento de los hechizos arcanos en 1 segundo.<\/td><\/tr><tr><td>Derretir<\/td><td>El da\u00f1o de fuego reduce la bonificaci\u00f3n de reducci\u00f3n f\u00edsica del objetivo en un -10 % durante 5 segundos.<\/td><\/tr><tr><td>Escudo reactivo<\/td><td>Crea un escudo arcano que dura 3 segundos. Puede absorber 10 de da\u00f1o total.<\/td><\/tr><tr><td>Dominio del fuego<\/td><td>Aumenta el da\u00f1o m\u00e1gico de los hechizos de fuego en un 5 % y aumenta el estado de quemadura en 2,5 segundos.<\/td><\/tr><tr><td>Oleada de man\u00e1<\/td><td>Aumenta la bonificaci\u00f3n de da\u00f1o m\u00e1gico en un 5%.<\/td><\/tr><tr><td>escudo de hielo<\/td><td>Aumenta el \u00edndice de armadura en 20 e inflige congelaci\u00f3n en los objetivos de ataques cuerpo a cuerpo durante 0,5 segundos.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-all-wizard-class-abilities-in-dark-and-darker\">Todas las habilidades de clase de mago en Dark and Darker<\/h2>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td colspan=\"3\"><strong>todas las habilidades<\/strong><\/td><\/tr><tr><td>Meditaci\u00f3n<\/td><td>Enfriamiento: 45 segundos<\/td><td>Si\u00e9ntate en el suelo y revive hechizos a raz\u00f3n de 40 hechizos en 10 segundos.<\/td><\/tr><tr><td>Memoria de hechizos 1 y 2<\/td><td>Enfriamiento: Cero<\/td><td>Permite memorizar hechizos adicionales. <\/td><\/tr><tr><td>Enfoque intenso<\/td><td>Enfriamiento: 18 segundos<\/td><td>Reduce el tiempo de lanzamiento del siguiente hechizo a 0,1 segundos.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-the-best-wizard-perks-and-abilities\">Las mejores ventajas y habilidades del mago<\/h2>\n\n<p>Para nuestra construcci\u00f3n equilibrada arcana, tomamos las siguientes ventajas y habilidades:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Meditaci\u00f3n<\/li>\n\n\n\n<li>Memoria de hechizos 2<\/li>\n\n\n\n<li>canto r\u00e1pido<\/li>\n\n\n\n<li>Sabio<\/li>\n\n\n\n<li>Maestr\u00eda Arcana<\/li>\n\n\n\n<li>Comentarios arcanos<\/li>\n<\/ul>\n\n<p>Al momento de escribir esto, nuestra mejor configuraci\u00f3n de Dark and Darker Wizard es una configuraci\u00f3n arcana bien equilibrada. Para esta compilaci\u00f3n, nos apegamos a la meditaci\u00f3n predeterminada y usamos la ranura de memoria de hechizos 2, ya que recuperar los hechizos gastados es vital para todos los magos y no necesitas ranuras de memoria adicionales.<\/p>\n\n<p>Para Perks, comenzamos con Quick Chant en el nivel uno para aumentar la velocidad de lanzamiento de hechizos, ya que muchos Wizard Spells tardan mucho en lanzarse sin este pasivo. A continuaci\u00f3n, tomamos Sage ya que aumentar nuestro conocimiento base nos permitir\u00e1 equipar hechizos de nivel superior.<\/p>\n\n<p>Nuestra tercera Perk es Arcane Mastery, para mejorar nuestro da\u00f1o m\u00e1gico y reducir el tiempo de lanzamiento de todos los hechizos arcanos. Por \u00faltimo, tomamos Comentarios arcanos para obtener m\u00e1s da\u00f1o con hechizos y velocidad de lanzamiento.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-all-spells-you-can-use-in-your-dark-and-darker-wizard-build\">Todos los hechizos que puedes usar en tu construcci\u00f3n de mago oscuro y m\u00e1s oscuro<\/h2>\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Nivel<\/th><th>Deletrear<\/th><th>Costo<\/th><th>Elenco<\/th><th>Descripci\u00f3n<\/th><\/tr><\/thead><tbody><tr><td>1<\/td><td>Borrar<\/td><td>1<\/td><td>5<\/td><td>Inflige da\u00f1o m\u00e1gico y quema al objetivo durante 1 segundo.<\/td><\/tr><tr><td>1<\/td><td>Orbe de luz<\/td><td>1<\/td><td>6<\/td><td>Crea esferas de luz flotante para iluminar tu entorno.<\/td><\/tr><tr><td>1<\/td><td>Encender <\/td><td>1<\/td><td>5<\/td><td>Prende fuego al arma del objetivo, lo que inflige 5 da\u00f1os m\u00e1gicos adicionales y quema a los enemigos cuando golpea.<\/td><\/tr><tr><td>2<\/td><td>Lento<\/td><td>2<\/td><td>5<\/td><td>Reduce la velocidad de movimiento del objetivo en un -40 % durante 2,5 segundos.<\/td><\/tr><tr><td>2<\/td><td>Rayo de hielo<\/td><td>2<\/td><td>5<\/td><td>Al golpear, inflige da\u00f1o m\u00e1gico y reduce la velocidad de movimiento del objetivo en un -15 % durante 1 segundo. <\/td><\/tr><tr><td>3<\/td><td>Misil m\u00e1gico<\/td><td>3<\/td><td>5<\/td><td>Dispara hasta 10 misiles guiados que infligen 12 de da\u00f1o cada uno. Moverse interrumpir\u00e1 el hechizo.<\/td><\/tr><tr><td>3<\/td><td>Prisa<\/td><td>3<\/td><td>4<\/td><td>El objetivo gana un 14% y una bonificaci\u00f3n de velocidad de movimiento durante 12 segundos. Se lanza a s\u00ed mismo si no se encuentra un objetivo v\u00e1lido.<\/td><\/tr><tr><td>4<\/td><td>Rayo<\/td><td>4<\/td><td>5<\/td><td>Despu\u00e9s de 4 segundos, un rayo de luz cae en el \u00e1rea seleccionada e inflige da\u00f1o de hechizo.<\/td><\/tr><tr><td>4<\/td><td>bola de fuego<\/td><td>4<\/td><td>5<\/td><td>Dispara una bola de fuego que causa 30 de da\u00f1o directo y 10 de da\u00f1o por salpicadura y efecto de retroceso a los objetivos cercanos.<\/td><\/tr><tr><td>4<\/td><td>Invisibilidad<\/td><td>4<\/td><td>4<\/td><td>El objetivo se vuelve invisible y gana un 10 % de bonificaci\u00f3n de velocidad de movimiento durante 4 segundos. Se lanza a s\u00ed mismo si no se encuentra un objetivo v\u00e1lido.<\/td><\/tr><tr><td>6<\/td><td>Cadena de rel\u00e1mpagos<\/td><td>6<\/td><td>3<\/td><td>Se electrocuta, inflige da\u00f1o con hechizos y dispara rayos que se transfieren a otros en un radio de 400 metros y descarga hasta 3 veces. Solo se puede transferir un objetivo una vez, y si est\u00e1s cerca, el rayo saltar\u00e1 hacia ti.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h2 class=\"wp-block-heading\" id=\"h-the-best-dark-and-darker-wizard-spells\">Los mejores hechizos de magos oscuros y m\u00e1s oscuros<\/h2>\n\n<p>Para nuestra construcci\u00f3n equilibrada arcana, tomamos los siguientes hechizos:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Cadena de rel\u00e1mpagos<\/li>\n\n\n\n<li>bola de fuego<\/li>\n\n\n\n<li>Misil m\u00e1gico<\/li>\n\n\n\n<li>Prisa<\/li>\n\n\n\n<li>Invisibilidad <\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-chain-lightning\">Cadena de rel\u00e1mpagos<\/h3>\n\n<p>Chain Lightning es el siguiente, y es nuestro hechizo m\u00e1s poderoso. Esta habilidad puede eliminar a un escuadr\u00f3n completo de jugadores enemigos y causar toneladas de da\u00f1o explosivo. Es genial en pasillos peque\u00f1os o cuando te enfrentas a m\u00faltiples objetivos.<\/p>\n\n<p>Sin embargo, tiene un tiempo de lanzamiento prolongado, se vuelve incre\u00edblemente dif\u00edcil de alcanzar en objetivos distantes y te matar\u00e1 si el objetivo est\u00e1 demasiado cerca. Chain Lightning tambi\u00e9n puede da\u00f1ar a tus compa\u00f1eros de equipo, as\u00ed que usa este hechizo con precauci\u00f3n. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-fireball\">bola de fuego<\/h3>\n\n<p>Fireball es el \u00fanico hechizo no arcano de nuestra lista porque es ic\u00f3nico y causa mucho da\u00f1o. Su da\u00f1o por salpicadura AOE es un poco decepcionante, pero es f\u00e1cil de usar, causa mucho da\u00f1o por impacto y retroceso, adem\u00e1s de infligir un peque\u00f1o DOT. Sin embargo, es dif\u00edcil acertar golpes directos a largas distancias, y puede golpear a tus compa\u00f1eros de equipo como Chain Lightning.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-magic-missile\">Misil m\u00e1gico<\/h3>\n\n<p>Magic Missile es nuestra primera elecci\u00f3n, utilizada principalmente para el combate PvE. Dado que Wizard carece de poder cuerpo a cuerpo, Magic Missile ser\u00e1 tu hechizo principal para acabar con las hordas de muertos vivientes.<\/p>\n\n<p>Magic Missile requiere que te quedes quieto mientras lanzas, pero puedes lanzar tiros consecutivos en la cabeza a zombis y esqueletos para despacharlos r\u00e1pidamente desde lejos. Adem\u00e1s, es una buena herramienta de zonificaci\u00f3n en PvP, pero no es genial ya que debes permanecer quieto mientras lanzas.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-haste-invisibility\">Prisa\/Invisibilidad<\/h3>\n\n<p>Por \u00faltimo, Prisa e Invisibilidad son hechizos incre\u00edbles para tu equipo y para ti. Prisa es un hechizo maravilloso para ayudar a las clases m\u00e1s lentas a perseguir enemigos o ayudar a retirarse de las peleas. La invisibilidad tambi\u00e9n es excelente para reposicionar o salvar a tus compa\u00f1eros de equipo de monstruos u otras amenazas a distancia.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-armor-weapons-to-use-for-wizards\">Qu\u00e9 armadura\/armas usar para los magos<\/h2>\n\n<p>Los magos pueden equipar las siguientes armaduras y armas:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>vestidos<\/li>\n\n\n\n<li>T\u00fanicas de or\u00e1culo<\/li>\n\n\n\n<li>Vestimentas m\u00edsticas<\/li>\n\n\n\n<li>Libros de hechizos<\/li>\n\n\n\n<li>bolas de cristal<\/li>\n\n\n\n<li>ballestas<\/li>\n\n\n\n<li>Dagas Rondel<\/li>\n\n\n\n<li>espadas de cristal<\/li>\n<\/ul>\n\n<p>Cuando se trata de armaduras, las construcciones de Wizard en Dark and Darker deben confiar en lo que tenga las mejores estad\u00edsticas defensivas y estad\u00edsticas ofensivas, lo que significa que no priorizan en gran medida armaduras espec\u00edficas como la necesidad de Plate Armor.<\/p>\n\n<p>Cuando se trata de armas, las cosas se complican un poco m\u00e1s. Aqu\u00ed est\u00e1n las mejores armas para Wizard:<\/p>\n\n<p><strong>Libro de hechizos:<\/strong> El Libro de hechizos es la mejor opci\u00f3n para todos los lanzadores de hechizos. El Libro de hechizos ofrece la mayor velocidad de movimiento y velocidad de lanzamiento. Si puedes usar un Libro de hechizos, en lugar de un Bast\u00f3n, toma siempre el Libro de hechizos.<br\/>El aumento en la velocidad de movimiento es lo que es m\u00e1s importante ya que necesitas reposicionarte constantemente despu\u00e9s de lanzar un hechizo, adem\u00e1s el aumento en la velocidad de lanzamiento tambi\u00e9n es una bendici\u00f3n incre\u00edble. El Libro de hechizos no ofrece una alternativa cuerpo a cuerpo como el bast\u00f3n, pero nunca querr\u00e1s estar en un cuerpo a cuerpo cuando juegues como mago.<\/p>\n\n<p><strong>Crystal Swords:<\/strong> si debes equipar un arma cuerpo a cuerpo, deber\u00eda ser la Crystal Sword. Esta arma est\u00e1 restringida a los magos y la espada act\u00faa como un catalizador de hechizos, permiti\u00e9ndote lanzar magia con ella. Sin embargo, su velocidad de lanzamiento es excepcionalmente lenta, y usamos esta arma principalmente para matar zombis y ara\u00f1as.<\/p>\n\n<p><strong>Bola de cristal:<\/strong> La Bola de cristal es similar al Libro de hechizos pero est\u00e1 restringida a Wizards. Crystal Ball sacrifica un poco de movimiento y velocidad de lanzamiento de hechizos a cambio de ser con una sola mano. Es una buena alternativa si quieres empu\u00f1ar una Daga Rondel con la Bola de Cristal. De lo contrario, solo use esto si no tiene un libro de hechizos o si tiene estad\u00edsticas incre\u00edbles.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-wizard-s-best-stats-in-dark-and-darker\">Las mejores estad\u00edsticas del mago en Dark and Darker<\/h2>\n\n<p>Hablando de estad\u00edsticas asombrosas, cada clase en Dark and Darker prefiere estad\u00edsticas adicionales espec\u00edficas que se encuentran en armas y equipo. Estos encantamientos aleatorios hacen que algunos art\u00edculos no tengan valor o sean muy buscados por ciertos grupos. Aqu\u00ed est\u00e1n las mejores estad\u00edsticas del mago:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Todos los atributos: aumenta todas las estad\u00edsticas de tu personaje.<\/li>\n\n\n\n<li>Da\u00f1o m\u00e1gico adicional: aumenta el da\u00f1o m\u00e1gico adicional infligido por tus hechizos.<\/li>\n\n\n\n<li>Conocimiento: aumenta la velocidad de lanzamiento de hechizos + recuento de hechizos + velocidad de identificaci\u00f3n de elementos.<\/li>\n\n\n\n<li>Poder m\u00e1gico: aumenta tu poder con hechizos en general.<\/li>\n\n\n\n<li>Max Health: aumenta la salud m\u00e1xima de tu personaje.<\/li>\n\n\n\n<li>Voluntad: aumenta el poder del hechizo, aumenta la duraci\u00f3n de Buff\/Curse y aumenta tu resistencia m\u00e1gica.<\/li>\n\n\n\n<li>Bonificaci\u00f3n de capacidad de hechizos: determina cu\u00e1ntos o el nivel de hechizos que puedes memorizar y llevar a cabo.<\/li>\n<\/ul>\n\n<p>Estas son las mejores estad\u00edsticas para Wizards, y los art\u00edculos espec\u00edficos con cualquiera de las mejoras antes mencionadas se vender\u00e1n mucho en el mercado. Es su decisi\u00f3n si desea quedarse con cualquier equipo bien establecido o venderlo en el mercado, pero estas son las estad\u00edsticas que los magos estar\u00e1n buscando.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-dark-and-darker-wizard-tips\">Consejos de mago oscuro y m\u00e1s oscuro<\/h2>\n\n<p>En \u00faltima instancia, todas las clases en Dark and Darker se tomar\u00e1n un tiempo para comprender sus fortalezas y debilidades. Aqu\u00ed hay algunos consejos para ayudarlo a evitar algunos errores al principio del juego que pueden salvar algunas de sus carreras.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Tenga un posicionamiento adecuado:<\/strong> un mago prospera y sufre en funci\u00f3n de su posicionamiento. Posicionarse en el rango adecuado para que un hechizo se conecte es lo que est\u00e1 buscando, pero no tan cerca de donde alguien pueda cerrar la distancia y entrar en el rango cuerpo a cuerpo.<\/li>\n\n\n\n<li><strong>Tenga cuidado con el lanzamiento de hechizos:<\/strong> casi todos los hechizos de construcci\u00f3n de magos en Dark and Darker son AOE. Esto los hace geniales para lidiar con jugadores agrupados y monstruos, pero dif\u00edciles de usar cuando tus compa\u00f1eros de equipo est\u00e1n cuerpo a cuerpo. As\u00ed que tenga en cuenta su hechizo Bola de fuego o Cadena de rel\u00e1mpagos cuando los use cerca de sus compa\u00f1eros de equipo o de usted mismo.<\/li>\n\n\n\n<li><strong>Haga llamadas de hechizos:<\/strong> si est\u00e1 en un grupo, hable sobre los hechizos que se est\u00e1 preparando para lanzar. Si vas a lanzar Cadena de rel\u00e1mpagos, pero tu Luchador est\u00e1 en el camino, p\u00eddele que retroceda para que puedas lanzarlo, en lugar de mantener el hechizo hasta que retroceda.<\/li>\n\n\n\n<li><strong>Apunta con cuidado con los hechizos potenciadores:<\/strong> la celeridad y la invisibilidad pueden afectar a los enemigos y a los jugadores si los apuntas mal. Entonces, si un p\u00edcaro est\u00e1 apu\u00f1alando a tu cl\u00e9rigo y crees que vale la pena lanzarle un hechizo de invisibilidad, ten cuidado sabiendo que puedes golpear al p\u00edcaro en su lugar.<\/li>\n\n\n\n<li><strong>Repone tus hechizos:<\/strong> una de tus mayores fortalezas como mago es recuperar tus hechizos a trav\u00e9s de la meditaci\u00f3n. El uso de esta habilidad repone lentamente todos los hechizos a la vez, no uno a la vez. Adem\u00e1s, los hechizos de nivel inferior se recargar\u00e1n significativamente m\u00e1s r\u00e1pido que los hechizos de nivel alto, as\u00ed que t\u00f3mate descansos con frecuencia.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-wrap-up-for-our-dark-and-darker-wizard-build-and-guide\">Cierre para nuestra gu\u00eda y compilaci\u00f3n de Dark and Darker Wizard.<\/h2>\n\n<p>Esa es nuestra Gu\u00eda y compilaci\u00f3n de magos para Dark and Darker. El mago es, sin duda, una de las clases m\u00e1s divertidas y explosivas para jugar, pero se siente equilibrado con tener muchas desventajas a cambio de un poder tan destructivo. Con suerte, una vez que Dark and Darker se lance por completo, veremos hechizos de mago m\u00e1s interesantes agregados a la lista para ver construcciones m\u00e1s diversas, como una construcci\u00f3n de fuego o escarcha.<\/p>\n\n<p>Si disfrut\u00f3 de nuestra mirada a Dark and Darker y desea obtener m\u00e1s informaci\u00f3n sobre el juego, consulte nuestros consejos y trucos para <a href=\"https:\/\/fpschampion.com\/es\/10-cosas-que-debes-saber-para-mejorar-en-dark-and-darker\/\" target=\"_blank\" rel=\"noreferrer noopener\">mejorar y Dark and Darker<\/a> para obtener m\u00e1s consejos \u00fatiles de supervivencia.<\/p>\n\n<p>Por ahora, \u00a1Buena Caza!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mago es una clase poderosa, ca\u00f3tica pero fr\u00e1gil en Dark and Darker. Los magos son una clase vol\u00e1til que puede significar la perdici\u00f3n para ellos mismos o para el tiempo del enemigo, dependiendo de su experiencia en el lanzamiento de hechizos. El Mago es una de las clases m\u00e1s dif\u00edciles de dominar en Dark<\/p>\n","protected":false},"author":6,"featured_media":24016,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[514],"tags":[896],"platform":[512],"class_list":{"0":"post-29633","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guias","8":"tag-oscuro-y-mas-oscuro","9":"platform-windowsos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro | FPS Champion<\/title>\n<meta name=\"description\" content=\"\u00bfQuieres jugar una de las clases m\u00e1s poderosas pero desafiantes? Domina la clase Wizard en Dark and Darker con nuestra gu\u00eda de construcci\u00f3n detallada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres jugar una de las clases m\u00e1s poderosas pero desafiantes? Domina la clase Wizard en Dark and Darker con nuestra gu\u00eda de construcci\u00f3n detallada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/\" \/>\n<meta property=\"og:site_name\" content=\"FPS Champion\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T04:38:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-04T05:40:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Wizard-class-build-in-Dark-and-Darker-game.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1576\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Butala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Butala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/\"},\"author\":{\"name\":\"Jake Butala\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\"},\"headline\":\"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro\",\"datePublished\":\"2023-04-06T04:38:58+00:00\",\"dateModified\":\"2023-06-04T05:40:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/\"},\"wordCount\":2542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Wizard-class-build-in-Dark-and-Darker-game.jpg\",\"keywords\":[\"oscuro y m\u00e1s oscuro\"],\"articleSection\":[\"Gu\u00edas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/\",\"name\":\"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro | FPS Champion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Wizard-class-build-in-Dark-and-Darker-game.jpg\",\"datePublished\":\"2023-04-06T04:38:58+00:00\",\"dateModified\":\"2023-06-04T05:40:11+00:00\",\"description\":\"\u00bfQuieres jugar una de las clases m\u00e1s poderosas pero desafiantes? Domina la clase Wizard en Dark and Darker con nuestra gu\u00eda de construcci\u00f3n detallada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Wizard-class-build-in-Dark-and-Darker-game.jpg\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Wizard-class-build-in-Dark-and-Darker-game.jpg\",\"width\":1576,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/\",\"name\":\"FPS Champion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#organization\",\"name\":\"FPS Champion\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"contentUrl\":\"https:\\\/\\\/fpschampion.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-aquare-small.png\",\"width\":512,\"height\":512,\"caption\":\"FPS Champion\"},\"image\":{\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/#\\\/schema\\\/person\\\/930ffa110c030f57cffb83778f0f1329\",\"name\":\"Jake Butala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g\",\"caption\":\"Jake Butala\"},\"description\":\"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.\",\"url\":\"https:\\\/\\\/fpschampion.com\\\/es\\\/author\\\/jbutela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro | FPS Champion","description":"\u00bfQuieres jugar una de las clases m\u00e1s poderosas pero desafiantes? Domina la clase Wizard en Dark and Darker con nuestra gu\u00eda de construcci\u00f3n detallada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/","og_locale":"es_ES","og_type":"article","og_title":"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro","og_description":"\u00bfQuieres jugar una de las clases m\u00e1s poderosas pero desafiantes? Domina la clase Wizard en Dark and Darker con nuestra gu\u00eda de construcci\u00f3n detallada.","og_url":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/","og_site_name":"FPS Champion","article_published_time":"2023-04-06T04:38:58+00:00","article_modified_time":"2023-06-04T05:40:11+00:00","og_image":[{"width":1576,"height":800,"url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Wizard-class-build-in-Dark-and-Darker-game.jpg","type":"image\/jpeg"}],"author":"Jake Butala","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Butala","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#article","isPartOf":{"@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/"},"author":{"name":"Jake Butala","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329"},"headline":"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro","datePublished":"2023-04-06T04:38:58+00:00","dateModified":"2023-06-04T05:40:11+00:00","mainEntityOfPage":{"@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/"},"wordCount":2542,"commentCount":0,"publisher":{"@id":"https:\/\/fpschampion.com\/es\/#organization"},"image":{"@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Wizard-class-build-in-Dark-and-Darker-game.jpg","keywords":["oscuro y m\u00e1s oscuro"],"articleSection":["Gu\u00edas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/fpschampion.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/","url":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/","name":"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro | FPS Champion","isPartOf":{"@id":"https:\/\/fpschampion.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#primaryimage"},"image":{"@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#primaryimage"},"thumbnailUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Wizard-class-build-in-Dark-and-Darker-game.jpg","datePublished":"2023-04-06T04:38:58+00:00","dateModified":"2023-06-04T05:40:11+00:00","description":"\u00bfQuieres jugar una de las clases m\u00e1s poderosas pero desafiantes? Domina la clase Wizard en Dark and Darker con nuestra gu\u00eda de construcci\u00f3n detallada.","breadcrumb":{"@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#primaryimage","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Wizard-class-build-in-Dark-and-Darker-game.jpg","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2023\/04\/Wizard-class-build-in-Dark-and-Darker-game.jpg","width":1576,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/fpschampion.com\/es\/guia-y-compilacion-del-mago-oscuro-y-mas-oscuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fpschampion.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Gu\u00eda y compilaci\u00f3n del mago oscuro y m\u00e1s oscuro"}]},{"@type":"WebSite","@id":"https:\/\/fpschampion.com\/es\/#website","url":"https:\/\/fpschampion.com\/es\/","name":"FPS Champion","description":"","publisher":{"@id":"https:\/\/fpschampion.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fpschampion.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fpschampion.com\/es\/#organization","name":"FPS Champion","url":"https:\/\/fpschampion.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","contentUrl":"https:\/\/fpschampion.com\/wp-content\/uploads\/2022\/03\/cropped-logo-aquare-small.png","width":512,"height":512,"caption":"FPS Champion"},"image":{"@id":"https:\/\/fpschampion.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fpschampion.com\/es\/#\/schema\/person\/930ffa110c030f57cffb83778f0f1329","name":"Jake Butala","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ae8b66044aac3edd6dac205f7400990088d37505f39b84ed337302876c4cdcb?s=96&d=mm&r=g","caption":"Jake Butala"},"description":"Jake Butala is a freelance writer who loves all types of video games, spending his time writing about different worlds and about video games just as much as he plays them.","url":"https:\/\/fpschampion.com\/es\/author\/jbutela\/"}]}},"_links":{"self":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/29633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/comments?post=29633"}],"version-history":[{"count":1,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/29633\/revisions"}],"predecessor-version":[{"id":29641,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/posts\/29633\/revisions\/29641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/media\/24016"}],"wp:attachment":[{"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/media?parent=29633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/categories?post=29633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/tags?post=29633"},{"taxonomy":"platform","embeddable":true,"href":"https:\/\/fpschampion.com\/es\/wp-json\/wp\/v2\/platform?post=29633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}